{"id":113653,"date":"2023-12-25T09:28:59","date_gmt":"2023-12-25T12:28:59","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=113653"},"modified":"2023-12-25T09:29:31","modified_gmt":"2023-12-25T12:29:31","slug":"ucrania-derriba-28-de-31-drones-y-dos-misiles-lanzados-por-rusia-ademas-de-dos-cazas","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/internacionales\/ucrania-derriba-28-de-31-drones-y-dos-misiles-lanzados-por-rusia-ademas-de-dos-cazas\/","title":{"rendered":"Ucrania derriba 28 de 31 drones y dos misiles lanzados por Rusia, adem\u00e1s de dos cazas"},"content":{"rendered":"\n<p>Las fuerzas de defensa ucranianas derribaron 28 de los 31\u00a0<strong>drones<\/strong>\u00a0de ataque Shahed y dos misiles lanzados por\u00a0<strong>Rusia\u00a0<\/strong>durante la noche, adem\u00e1s de dos cazas rusos, seg\u00fan inform\u00f3 hoy la Fuerza A\u00e9rea en un comunicado.<\/p>\n\n\n\n<p>&#8220;En la noche al 25 de diciembre, el enemigo atac\u00f3 con 31 aparatos a\u00e9reos no tripulados del tipo &#8216;Shahed&#8217; desde las zonas de Chauda, Balaklava (Crimea) y con dos\u00a0<strong>misiles\u00a0<\/strong>de aviaci\u00f3n&#8221;, indic\u00f3 la Fuerza A\u00e9rea ucraniana en un comunicado en Telegram.<\/p>\n\n\n\n<p>Precis\u00f3 que &#8220;como resultado del combate a\u00e9reo, las fuerzas y medios de la Fuerza A\u00e9rea y las Fuerzas de Defensa de\u00a0<strong>Ucrania<\/strong>\u00a0derribaron 28 veh\u00edculos a\u00e9reos no tripulados de ataque Shahed-136\/131 en las regiones de Odesa, Jers\u00f3n, Mikol\u00e1yiv, Donetsk, Kirovograd y Jmelnitski&#8221;.<\/p>\n\n\n\n<p>&#8220;Durante el ataque a\u00e9reo, el enemigo tambi\u00e9n utiliz\u00f3 un&nbsp;<strong>misil&nbsp;<\/strong>guiado Kh-59 en la direcci\u00f3n de Zaporiyia y un&nbsp;<strong>misil&nbsp;<\/strong>antirradar Kh-31P desde el Mar Negro.\u00a1Ambos fueron destruidos!&#8221;, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p>Se\u00f1al\u00f3 que &#8220;las unidades de misiles antia\u00e9reos de la Fuerza A\u00e9rea tambi\u00e9n destruyeron dos aviones enemigos: un Su-34, en la regi\u00f3n de Donetsk (reportado por la tarde), y un Su-30SM, sobre el Mar Negro&#8221;.<\/p>\n\n\n\n<p>En tanto, las Fuerzas de Defensa del Sur precisaron en un comunicado en Telegram que el ataque con drones dur\u00f3 m\u00e1s de 6,5 horas y que 17 shaheds fueron derribados en la regi\u00f3n de Odesa, tres en Jers\u00f3n y uno, respectivamente, en Mikol\u00e1yiv y Kirovograd.<\/p>\n\n\n\n<p>Indicaron que los restos de&nbsp;<strong>drones&nbsp;<\/strong>derribados causaron da\u00f1os en instalaciones t\u00e9cnicas de la infraestructura portuaria de Odesa, y en el distrito de Rozdilnianski, en un edificio administrativo inoperativo y en un almac\u00e9n de una instalaci\u00f3n inactiva, donde el fuego fue extinguido r\u00e1pidamente.<\/p>\n\n\n\n<p>Adem\u00e1s, en el distrito de Berislav, en la regi\u00f3n de Jers\u00f3n, debido al impacto de los restos de un&nbsp;<strong>dron&nbsp;<\/strong>se declar\u00f3 un incendio en un almac\u00e9n, que los bomberos pudieron extinguir.<\/p>\n\n\n\n<p>Sergu\u00ed Lisak, jefe de la administraci\u00f3n militar de Dnipropetrovsk se\u00f1al\u00f3 que cinco&nbsp;<strong>drones<\/strong>&nbsp;rusos fueron derribados por las fuerzas ucranianas a \u00faltimas horas de la tarde de ayer cuando sobrevolaban la regi\u00f3n.<\/p>\n\n\n\n<p>En un comunicado en Telegram precis\u00f3 que en el distrito de Pavlograd, los restos de un&nbsp;<strong>dron<\/strong>&nbsp;da\u00f1aron una dependencia agr\u00edcola y un cargador de grano, y en el de Dniprovski, cayeron en el recinto de una empresa inoperativa y se registr\u00f3 un incendio en un edificio de una planta, que fue extinguido.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las fuerzas de defensa ucranianas derribaron 28 de los 31\u00a0drones\u00a0de ataque Shahed y dos misiles lanzados por\u00a0Rusia\u00a0durante la noche, adem\u00e1s de dos cazas rusos, seg\u00fan inform\u00f3 hoy la Fuerza A\u00e9rea&hellip; <\/p>\n","protected":false},"author":12,"featured_media":113657,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-113653","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/113653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=113653"}],"version-history":[{"count":2,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/113653\/revisions"}],"predecessor-version":[{"id":113659,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/113653\/revisions\/113659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/113657"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=113653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=113653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=113653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}