{"id":113679,"date":"2023-12-25T10:30:45","date_gmt":"2023-12-25T13:30:45","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=113679"},"modified":"2023-12-25T19:38:47","modified_gmt":"2023-12-25T22:38:47","slug":"una-nena-de-5-anos-festejaba-la-navidad-con-sus-papas-y-una-bala-perdida-la-mato-no-hay-nadie-preso","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/actualidad\/una-nena-de-5-anos-festejaba-la-navidad-con-sus-papas-y-una-bala-perdida-la-mato-no-hay-nadie-preso\/","title":{"rendered":"Una nena de 5 a\u00f1os festejaba la Navidad con sus pap\u00e1s y una bala perdida la mat\u00f3: \u201cNo hay nadie preso\u201d"},"content":{"rendered":"\n<p>Este 25 de diciembre se cumple un a\u00f1o de la&nbsp;<strong>muerte de Candelaria Enrique, la nena de 5 a\u00f1os que fue alcanzada por una bala perdida cuando festejaba Navidad&nbsp;<\/strong>con su familia en el barrio Alvear, en Rosario.<\/p>\n\n\n\n<p>Micaela, su mam\u00e1, asegur\u00f3 a<strong>&nbsp;TN<\/strong>&nbsp;que la causa se fren\u00f3 y no hay sospechosos detenidos. Pide justicia por su hija y que su asesino sea encarcelado, pero sobre todo que haya conciencia en esta Nochebuena, para que ninguna familia tenga que pasar por el dolor de perder a un ser querido de esta manera<\/p>\n\n\n\n<p>Candelaria Enrique era alegre, educada y s\u00faper mimada por sus pap\u00e1s, ya que era hija \u00fanica. La medianoche del 25 de diciembre del a\u00f1o pasado, los tres salieron a la puerta de su casa para recibir a Papa Noel y ver los fuegos artificiales. De repente,&nbsp;<strong>la nena se desplom\u00f3 y empez\u00f3 a sangrar<\/strong>. No entend\u00edan qu\u00e9 estaba pasando, hasta que vieron que ten\u00eda una bala en la cabeza.<\/p>\n\n\n\n<p><strong>\u201cCandelaria no merec\u00eda irse de este mundo de esta manera, ten\u00eda toda una vida por delante\u201d<\/strong>, asegur\u00f3 Micaela, su mam\u00e1, quien junto a su pareja pudieron transformar el dolor en solidaridad. En agosto, cuando fue el cumplea\u00f1os de la peque\u00f1a, organizaron un homenaje para juntar juguetes para los ni\u00f1os del barrio e hicieron una celebraci\u00f3n muy colorida, para recordarla de la mejor manera.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/tn.com.ar\/resizer\/_Esyjnc0_LsqJtRqi7MPrk2n_94=\/767x0\/smart\/filters:format(webp)\/cloudfront-us-east-1.images.arcpublishing.com\/artear\/PI6ZUCN3BFBXBAAKWM5EFSSPYM.jpg\" alt=\"Cadelaria junto a su mam\u00e1, unos meses antes de su muerte. (Foto: Mika Candelaria)\"\/><figcaption>Cadelaria junto a su mam\u00e1, unos meses antes de su muerte. (Foto: Mika Candelaria)<\/figcaption><\/figure>\n\n\n\n<p>Sobre la causa, que a\u00fan sigue impune, la mujer cont\u00f3: \u201cLamentablemente no hay noticias. Hubo dos allanamientos los primeros meses despu\u00e9s del hecho, pero&nbsp;<strong>todo se fren\u00f3<\/strong>\u201d. La polic\u00eda arrest\u00f3 a un hombre al que los vecinos hab\u00edan visto portar un arma de fuego en otras ocasiones. Sin embargo, cuando se hizo la pericia para ver si era la misma pistola con la que mataron a Candelaria, los resultados dieron negativo.<\/p>\n\n\n\n<p>El lunes se cumple un a\u00f1o del fallecimiento de Candelaria y su mam\u00e1 sostuvo: \u201c<strong>La verdad que es una fecha que no quiero que llegue.&nbsp;<\/strong>C\u00f3mo pap\u00e1s sentimos un vac\u00edo inmenso. Es un dolor tan grande la perdida de un hijo, m\u00e1s siendo \u00fanica hija\u201d.<\/p>\n\n\n\n<p>A pesar del sufrimiento por la perdida de su hija,&nbsp;<strong>Micaela desea poder conocer a las personas que recibieron sus \u00f3rganos<\/strong>, ya que cuando falleci\u00f3 pudieron donarlos a dos nenas y un nene que estaban necesitando de un trasplante. \u201cSolo quiero saber que sus hijos se salvaron y tiene una mejor calidad de vida. Me gustar\u00eda saberlo\u201d, expres\u00f3.<\/p>\n\n\n\n<p>El martes pr\u00f3ximo, junto a vecinos del barrio Alvear y sus seres queridos, inaugurar\u00e1n un mural con el rostro de la peque\u00f1a para pedir justicia y que se tome conciencia de que este tipo de casos se pueden prevenir.<\/p>\n\n\n\n<p>\u201c<strong>Solo le pido a la gente que tenga mucha conciencia a la hora de festejar, por qu\u00e9 despu\u00e9s dejan a toda una familia destruida y sin consuelo.<\/strong>&nbsp;Fue horrible de la forma que se fue mi hija de este mundo, trist\u00edsimo.<strong>&nbsp;Ten\u00eda toda una vida por delante. Era muy alegre, feliz y muy educada<\/strong>\u201d, expres\u00f3 Micaela.<\/p>\n\n\n\n<p>\u201c<strong>Ese asesino nos destruy\u00f3 la vida<\/strong>, porque hay que llamarlo por lo que es: un asesino. A la hora que agarr\u00f3 el arma y tir\u00f3 al aire, hab\u00eda una posibilidad de que alguien saliera lastimado, y fue as\u00ed. Festejen con conciencia y con amor. Y disfruten cada segundo con su ser querido.<strong>&nbsp;Solo le pido un favor a toda la sociedad, que cuando levanten sus copas para brindar, pidan que se haga justicia por Candelaria<\/strong>\u201d, cerr\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este 25 de diciembre se cumple un a\u00f1o de la&nbsp;muerte de Candelaria Enrique, la nena de 5 a\u00f1os que fue alcanzada por una bala perdida cuando festejaba Navidad&nbsp;con su familia&hellip; <\/p>\n","protected":false},"author":12,"featured_media":113690,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,33],"tags":[],"class_list":["post-113679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-policiales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/113679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=113679"}],"version-history":[{"count":3,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/113679\/revisions"}],"predecessor-version":[{"id":113763,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/113679\/revisions\/113763"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/113690"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=113679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=113679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=113679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}