{"id":113924,"date":"2023-12-26T15:00:58","date_gmt":"2023-12-26T18:00:58","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=113924"},"modified":"2023-12-26T15:01:10","modified_gmt":"2023-12-26T18:01:10","slug":"que-es-el-sira-el-sistema-de-importaciones-que-termina-y-es-reemplazado-por-el-sedi","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/economia\/que-es-el-sira-el-sistema-de-importaciones-que-termina-y-es-reemplazado-por-el-sedi\/","title":{"rendered":"Qu\u00e9 es el SIRA, el sistema de importaciones que termina y es reemplazado por el SEDI"},"content":{"rendered":"\n<p>El gobierno de Javier Milei modific\u00f3 las condiciones para ingresar mercader\u00edas al pa\u00eds. Cu\u00e1les son lo cambios<\/p>\n\n\n\n<p> El SIRA es reemplazado por el SEDI, tras la publicaci\u00f3n en el Bolet\u00edn Oficial de una resoluci\u00f3n conjunta de la AFIP y la Secretar\u00eda de Comercio. El vocero presidencial\u00a0<strong>Manuel Adorni<\/strong>\u00a0habl\u00f3 del tema en conferencia de prensa. El\u00a0<strong>SIRA,<\/strong>\u00a0el Sistema de Informaci\u00f3n Registral Automatizado, fue desde octubre de 2022 y hasta ahora una plataforma web para regular las importaciones en el pa\u00eds.<\/p>\n\n\n\n<p>El&nbsp;<strong>SIRA&nbsp;<\/strong>fue dise\u00f1ado como un&nbsp;<strong>sistema de control oficial para las importaciones<\/strong>&nbsp;y establecer un&nbsp;<strong>nuevo permiso<\/strong>&nbsp;de las mismas. El sistema involucraba a la AFIP, la Secretar\u00eda de Comercio Interior, y el Banco Central (BCRA).<\/p>\n\n\n\n<p>En medio de la escasez de d\u00f3lares, los importadores estaban obligados a evidenciar su capacidad econ\u00f3mica y financiera para llevar a cabo las operaciones de importaci\u00f3n. Era esencial especificar con claridad y precisi\u00f3n la mercader\u00eda que se planeaba importar.<\/p>\n\n\n\n<p>Las&nbsp;<strong>solicitudes en el SIRA<\/strong>&nbsp;pod\u00edan encontrarse en diferentes estados: aprobadas, rechazadas o en observaci\u00f3n. En el caso de que una solicitud permaneciera en&nbsp;<strong>observaci\u00f3n por m\u00e1s de 90 d\u00edas<\/strong>, se anulaba de manera autom\u00e1tica.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/tn.com.ar\/resizer\/UZzniIJbZs9qhPTwyElBWicCubc=\/767x0\/smart\/filters:format(webp)\/cloudfront-us-east-1.images.arcpublishing.com\/artear\/6SRKEO2QCRG37MCQAQH3ADE7J4.jpg\" alt=\"Qu\u00e9 es el SIRA, el sistema de importaciones que termina y es reemplazado por el SEDI (Foto: T\u00e9lam).\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Qu\u00e9 es el SEDI, el reemplazo de las SIRA<\/h2>\n\n\n\n<p>De acuerdo con la resoluci\u00f3n conjunta 5466, el Sistema Estad\u00edstico de Importaciones (<strong>SEDI<\/strong>) apunta a \u201cel an\u00e1lisis y seguimiento de datos estad\u00edsticos sobre importaci\u00f3n de bienes, a fin de&nbsp;<strong>normalizar y facilitar el comercio exterior\u201d<\/strong>.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>La \u201cdeclaraci\u00f3n SEDI\u201d tendr\u00e1 un<strong>&nbsp;plazo de validez de 360 d\u00edas<\/strong>&nbsp;corridos para los<strong>&nbsp;importadores<\/strong>.<\/li><li>Al realizar la declaraci\u00f3n SEDI, la AFIP analizar\u00e1 la situaci\u00f3n tributaria del contribuyente y su capacidad econ\u00f3mica financiera para efectuar la operaci\u00f3n.<\/li><li>La creaci\u00f3n del SEDI tiene el objetivo de&nbsp;<strong>simplificar la tramitaci\u00f3n de operaciones de importaci\u00f3n<\/strong>.<\/li><\/ul>\n\n\n\n<p>Se cre\u00f3 tambi\u00e9n el&nbsp;<strong>Padr\u00f3n de Deuda Comercial por Importaciones con Proveedores del Exterior<\/strong>, en el cual deber\u00e1n inscribirse los sujetos que&nbsp;<strong>posean deuda comercial por importaciones&nbsp;<\/strong>de bienes y\/o de servicios y efectuar la declaraci\u00f3n jurada. La inscripci\u00f3n a este padr\u00f3n estar\u00e1 abierta por&nbsp;<strong>15 d\u00edas corridos<\/strong>&nbsp;desde la publicaci\u00f3n de la resoluci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno de Javier Milei modific\u00f3 las condiciones para ingresar mercader\u00edas al pa\u00eds. Cu\u00e1les son lo cambios El SIRA es reemplazado por el SEDI, tras la publicaci\u00f3n en el Bolet\u00edn&hellip; <\/p>\n","protected":false},"author":8,"featured_media":113925,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-113924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/113924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=113924"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/113924\/revisions"}],"predecessor-version":[{"id":113926,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/113924\/revisions\/113926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/113925"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=113924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=113924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=113924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}