{"id":114325,"date":"2023-12-27T20:42:55","date_gmt":"2023-12-27T23:42:55","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=114325"},"modified":"2023-12-27T20:43:07","modified_gmt":"2023-12-27T23:43:07","slug":"lopez-obrador-insto-a-estados-unidos-a-invertir-en-personas-no-en-muros","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/internacionales\/lopez-obrador-insto-a-estados-unidos-a-invertir-en-personas-no-en-muros\/","title":{"rendered":"L\u00f3pez Obrador inst\u00f3 a Estados Unidos a invertir en personas, no en muros"},"content":{"rendered":"\n<p>&#8220;Es m\u00e1s eficaz poner recursos en el desarrollo de los pueblos&#8221;, afirm\u00f3 el mandatario mexicano.<\/p>\n\n\n\n<p>El presidente de M\u00e9xico,&nbsp;<strong>Andr\u00e9s Manuel L\u00f3pez Obrador,<\/strong>&nbsp;dijo el mi\u00e9rcoles que el&nbsp;Congreso de Estados Unidos deber\u00eda centrarse en&nbsp;<strong>invertir en las personas en lugar de construir muros.<\/strong><\/p>\n\n\n\n<p>La administraci\u00f3n del presidente&nbsp;<strong>Joe Biden&nbsp;<\/strong>est\u00e1 buscando ayuda&nbsp;del gobierno de&nbsp;<strong>L\u00f3pez Obrador<\/strong>&nbsp;para frenar los<strong>&nbsp;flujos migratorios<\/strong>&nbsp;y&nbsp;hacer frente a un n\u00famero r\u00e9cord de personas que intentan llegar a&nbsp;la frontera estadounidense, una cuesti\u00f3n clave antes de las&nbsp;elecciones presidenciales estadounidenses de noviembre.<\/p>\n\n\n\n<p>Las reuniones se producen despu\u00e9s de que m\u00e1s de medio mill\u00f3n de&nbsp;migrantes cruzaron este a\u00f1o la peligrosa&nbsp;<strong>Selva del Dari\u00e9n hacia&nbsp;Centroam\u00e9rica&nbsp;<\/strong>\u2013el doble del r\u00e9cord del a\u00f1o pasado\u2013, muchos de&nbsp;ellos huyendo de la delincuencia, la pobreza y los conflictos para&nbsp;intentar entrar a Estados Unidos.<\/p>\n\n\n\n<p><strong>L\u00f3pez Obrador,<\/strong>&nbsp;quien la semana pasada asegur\u00f3 a Estados Unidos&nbsp;que M\u00e9xico ayudar\u00eda a aliviar las presiones migratorias,&nbsp;<strong>dijo que&nbsp;el Congreso estadounidense deber\u00eda invertir en los pobres de&nbsp;Am\u00e9rica Latina y el Caribe &#8220;en vez de estar all\u00ed poniendo&nbsp;barreras, alambradas en el r\u00edo o pensando en construir muros&#8221;.<\/strong><\/p>\n\n\n\n<p><strong>&#8220;Es m\u00e1s eficaz y m\u00e1s humano que se invierta en el desarrollo de&nbsp;los pueblos y eso es lo que siempre hemos planteado&#8221;, dijo L\u00f3pez&nbsp;Obrador<\/strong>&nbsp;en conferencia de prensa. A\u00f1adi\u00f3 que espera que las&nbsp;elecciones estadounidenses del pr\u00f3ximo a\u00f1o pongan en primer plano&nbsp;el tema de la migraci\u00f3n.<\/p>\n\n\n\n<p>El ex presidente estadounidense&nbsp;<strong>Donald Trump<\/strong>, principal&nbsp;candidato a la nominaci\u00f3n presidencial republicana en 2024, ha&nbsp;prometido tomar<strong>&nbsp;medidas en\u00e9rgicas<\/strong>&nbsp;contra la inmigraci\u00f3n ilegal y&nbsp;restringir la legal si es elegido para un segundo mandato de&nbsp;cuatro a\u00f1os.<\/p>\n\n\n\n<p><strong>Trump se centr\u00f3 en construir un muro en la frontera con M\u00e9xico&nbsp;durante su primer mandato<\/strong>&nbsp;y se ha comprometido a cerrar las&nbsp;brechas en el muro fronterizo si es reelegido. Su administraci\u00f3n&nbsp;construy\u00f3 725 kil\u00f3metros de barreras a lo largo de la frontera de&nbsp;3,145 kil\u00f3metros, pero gran parte de eso reemplaz\u00f3 las estructuras&nbsp;existentes.<\/p>\n\n\n\n<p><strong>El mi\u00e9rcoles, miles de migrantes y solicitantes de asilo&nbsp;marchaban lentamente hacia el norte desde el sur de M\u00e9xico<\/strong>&nbsp;en una&nbsp;caravana con la esperanza de llegar a la frontera con Estados&nbsp;Unidos, muchos de ellos con ni\u00f1os peque\u00f1os.<\/p>\n\n\n\n<p>&#8220;No tenemos la necesidad de volver a nuestro pa\u00eds si no tenemos&nbsp;nada all\u00e1. Si tuvi\u00e9ramos no estuviera migrando y no estuvi\u00e9ramos&nbsp;invadiendo una parte que no nos pertenece, pero queremos ayuda&#8221;&nbsp;dijo la migrante venezolana Nohem\u00eda Zendejas mientras caminaba con&nbsp;sus cuatro hijos, uno de ellos cargado en sus brazos.<\/p>\n\n\n\n<p>&#8220;Venimos desde lejos, yo vengo de Venezuela y Venezuela est\u00e1&nbsp;quebrada&#8221;, agreg\u00f3 la mujer, visiblemente agotada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Es m\u00e1s eficaz poner recursos en el desarrollo de los pueblos&#8221;, afirm\u00f3 el mandatario mexicano. El presidente de M\u00e9xico,&nbsp;Andr\u00e9s Manuel L\u00f3pez Obrador,&nbsp;dijo el mi\u00e9rcoles que el&nbsp;Congreso de Estados Unidos deber\u00eda&hellip; <\/p>\n","protected":false},"author":4,"featured_media":114341,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-114325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/114325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=114325"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/114325\/revisions"}],"predecessor-version":[{"id":114342,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/114325\/revisions\/114342"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/114341"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=114325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=114325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=114325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}