{"id":114435,"date":"2023-12-28T09:25:11","date_gmt":"2023-12-28T12:25:11","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=114435"},"modified":"2023-12-28T09:32:07","modified_gmt":"2023-12-28T12:32:07","slug":"encontraron-el-cuerpo-de-una-jubilada-en-un-pozo-ciego-e-investigan-si-sus-vecinos-la-mataron-para-robarle","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/policiales\/encontraron-el-cuerpo-de-una-jubilada-en-un-pozo-ciego-e-investigan-si-sus-vecinos-la-mataron-para-robarle\/","title":{"rendered":"Encontraron el cuerpo de una jubilada en un pozo ciego e investigan si sus vecinos la mataron para robarle"},"content":{"rendered":"\n<p>En las \u00faltimas horas,\u00a0<strong>una mujer de 71 a\u00f1os fue hallada\u00a0muerta\u00a0en el pozo ciego<\/strong>\u00a0de la casa que alquilaba hace dos meses en\u00a0<strong>Rosario<\/strong>. Los primeros indicios indican que habr\u00eda sido<strong>asesinada\u00a0en medio de un robo<\/strong>,pero el caso todav\u00eda est\u00e1 siendo investigado.<\/p>\n\n\n\n<p>El dram\u00e1tico hallazgo ocurri\u00f3 este mi\u00e9rcoles en una vivienda ubicada en la calle Vicente Medina al 4700. La v\u00edctima fue identificada como\u00a0<strong>Mar\u00eda Isabel Pereyra<\/strong>\u00a0y era jubilada.<\/p>\n\n\n\n<p>De acuerdo al testimonio de uno de los hijos de la mujer, hac\u00eda dos meses que se hab\u00eda mudado all\u00ed. \u201cElla ten\u00eda una casa pero la tuvo que vender hace unos a\u00f1os por un problema que tuvo un familiar\u201d, explic\u00f3.<\/p>\n\n\n\n<p>Adem\u00e1s, cont\u00f3 que fue&nbsp;<strong>uno de sus<\/strong>&nbsp;<strong>nietos&nbsp;<\/strong>quien intent\u00f3 contactarse con ella y al no obtener respuesta se acerc\u00f3 hasta la vivienda y<strong>&nbsp;la encontr\u00f3 sin vida<\/strong>. \u201cNosotros la hab\u00edamos visto para el 25 y estaba todo bien, pero al d\u00eda siguiente \u00e9l la empez\u00f3 a llamar varias veces y como no lo atendi\u00f3 vino a ver qu\u00e9 pasaba\u201d, detall\u00f3 y sum\u00f3: \u201cCuando entr\u00f3 a la casa lo primero que vio fue que&nbsp;<strong>estaba todo revuelto, desordenado<\/strong>, como si hubieran entrado a robarle. Pero adem\u00e1s faltaban cosas:<strong>&nbsp;le hab\u00edan sacado unas garrafas, el televisor, un ventilador, el celular y la billetera<\/strong>\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/tn.com.ar\/resizer\/-P8tCeMghM7uh8H-61bJhGfOyvs=\/767x0\/smart\/filters:format(webp)\/cloudfront-us-east-1.images.arcpublishing.com\/artear\/UYOWRVIXXNAZBBZBKOUJLVC3D4.PNG\" alt=\"El crimen ocurri\u00f3 en una vivienda ubicada en Vicente Medina al 4700. (Foto: Google Street View)\"\/><figcaption>El crimen ocurri\u00f3 en una vivienda ubicada en Vicente Medina al 4700. (Foto: Google Street View)<\/figcaption><\/figure>\n\n\n\n<p>Enseguida escuch\u00f3 el llanto del perro de Pereyra que proven\u00eda del fondo del terreno. Cuando se acerc\u00f3 vio la terror\u00edfica escena:&nbsp;<strong>la mujer estaba muerta en el pozo ciego<\/strong>.Enseguida llam\u00f3 a los vecinos, quienes se comunicaron con la Polic\u00eda.<\/p>\n\n\n\n<p>\u201cDicen que se ve\u00edan solo los pies\u201d, coment\u00f3 una hija de la v\u00edctima en di\u00e1logo con el medio local<em>&nbsp;La Capital.&nbsp;<\/em>\u201cEstaba sin vida, boca abajo, en el pozo ciego del fondo del terreno donde se ubican dos casas precarias\u201d, indicaron desde la Fiscal\u00eda Regional 2.<\/p>\n\n\n\n<p>En el lugar trabaj\u00f3 personal del gabinete criminal\u00edstico de la Polic\u00eda de Investigaciones (PDI), bombero y la secci\u00f3n canes del Ministerio P\u00fablico de la Acusaci\u00f3n (MPA).<\/p>\n\n\n\n<p>En principio, seg\u00fan se confirm\u00f3 de manera oficial, el cuerpo de Mar\u00eda Isabel&nbsp;<strong>no presentaba heridas de bala o de arma blanca&nbsp;<\/strong>por lo que se deber\u00e1 esperar el resultado de la autopsia para establecer cu\u00e1l fue la causa de la muerte. \u201cHay que ver si fue alg\u00fan golpe o si la asfixiaron\u201d, se\u00f1al\u00f3 uno de los hijos.<\/p>\n\n\n\n<p>El faltante de varios objetos dentro de la vivienda sumado al crimen de la mujer gener\u00f3 sospechas acerca de quienes le robaron debido a que<strong>&nbsp;los habitantes de la casa delantera del terreno, vecinos de la v\u00edctima, se fueron de all\u00ed.&nbsp;<\/strong>En tal sentido, los investigadores realizan tareas de investigaci\u00f3n para dar con ellos.<\/p>\n\n\n\n<p>Las primeras hip\u00f3tesis indican que Pereyra fue asesinada unas 24 horas del hallazgo. La investigaci\u00f3n del episodio qued\u00f3 a cargo del fiscal de Homicidios en turno, Patricio Saldutti, quien orden\u00f3 las primeras medidas de rigor para iniciar la pesquisa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En las \u00faltimas horas,\u00a0una mujer de 71 a\u00f1os fue hallada\u00a0muerta\u00a0en el pozo ciego\u00a0de la casa que alquilaba hace dos meses en\u00a0Rosario. Los primeros indicios indican que habr\u00eda sidoasesinada\u00a0en medio de&hellip; <\/p>\n","protected":false},"author":12,"featured_media":114443,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-114435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/114435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=114435"}],"version-history":[{"count":2,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/114435\/revisions"}],"predecessor-version":[{"id":114451,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/114435\/revisions\/114451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/114443"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=114435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=114435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=114435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}