{"id":11477,"date":"2022-10-15T16:43:28","date_gmt":"2022-10-15T19:43:28","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=11477"},"modified":"2022-10-15T16:43:32","modified_gmt":"2022-10-15T19:43:32","slug":"rio-negro-ordenan-restituir-las-viviendas-usurpadas-por-mapuches","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/actualidad\/rio-negro-ordenan-restituir-las-viviendas-usurpadas-por-mapuches\/","title":{"rendered":"<strong>R\u00edo Negro: ordenan restituir las viviendas usurpadas por mapuches<\/strong>"},"content":{"rendered":"\n<p>La jueza Silvana Dom\u00ednguez tambi\u00e9n dictamin\u00f3 que se mantenga el espacio \u201crewe\u201d, considerado como un lugar sagrado por los mapuches y el grupo \u201cLof Lafken Winkul Mapu\u201d.<\/p>\n\n\n\n<p>Este s\u00e1bado, <strong>la Justicia orden\u00f3 la restituci\u00f3n de las propiedades usurpadas por los mapuches en Villa Mascardi, localidad de la provincia de R\u00edo Negro<\/strong>.<\/p>\n\n\n\n<p>A su vez, decidi\u00f3 <strong>mantener el espacio \u201crewe\u201d, considerado sagrado por la comunidad. Eran ocupadas por el grupo \u201cLof Lafken Winkul Mapu\u201d<\/strong>. La medida se produjo en medio de los conflictos y la incertidumbre en Villa la Angostura y Bariloche.<\/p>\n\n\n\n<p>La jueza Silvana Dom\u00ednguez fue quien emiti\u00f3 la orden. <strong>La toma de los terrenos por los mapuches se realiz\u00f3 en 2017<\/strong>. De esta manera, los propietarios de los lugares podr\u00e1n acceder a sus terrenos y tirar abajo las construcciones que se hicieron en sus propiedades durante los \u00faltimos cinco a\u00f1os.<\/p>\n\n\n\n<p>En la resoluci\u00f3n, Dom\u00ednguez determin\u00f3 <strong>la restituci\u00f3n del Ex Hotel Mascardi a la Administraci\u00f3n de Parques Nacionales, \u201cLa Escondida\u201d a Mar\u00eda Magdalena Gim\u00e9nez Tournier<\/strong>, del predio \u201c9-7-A011-12 y 19-7-A-011-10\u2033 a la Uni\u00f3n Personal del Gas del Estado y <strong>\u201cLos Radales\u201d a Mercedes Josefina Olivera<\/strong>. Tambi\u00e9n detall\u00f3 que los alimentos que sean hallados sean donados a distintas instituciones de la ciudad de Bariloche.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/F73lhNCJDdF-ihHOuJBn5gxGdO-mRWGK9DTzqmrqX7eKtlVhe6EWyQT9m6KqztHa3A6DHEVDQLgxUgjq9Te9KWkuKHWFc5xBNJfj2ZZIdZmaIk9hFp1kiHAVmIc4b21hcQFTTSxbykUXQe9PHfRmQaq8qt9aGY3tUWQxVl5hx6Lp0lMZOBfBlUVEkg\" alt=\"\"\/><\/figure>\n\n\n\n<p>Ademas, marc\u00f3 que <strong>se deber\u00e1 mantener el espacio \u201crewe\u201d o T\u00f3tem, considerado por la comunidad como un lugar sagrado<\/strong>. \u201cRequerir\u00e9 a la APN que conserve debidamente la \u201ctalla antropomorfa y su espacio circundante\u201d por ser un lugar utilizado como espacio de culto mapuche\u201d, expres\u00f3 en el documento.<\/p>\n\n\n\n<p>La Justicia provincial seguir\u00e1 tratando, acorde a lo expresado en la resoluci\u00f3n, el tr\u00e1mite del predio del Obispado de San Isidro. En el texto, la jueza solicit\u00f3 que el caso se ponga a disposici\u00f3n \u201cde la Fiscal Jefe de la III Circunscripci\u00f3n Judicial del Poder Judicial de R\u00edo Negro el predio 19-7-A-011-13 (caba\u00f1as \u201cHueche Ruca del Obispado de San Isidro), a los fines que estime corresponder\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La jueza Silvana Dom\u00ednguez tambi\u00e9n dictamin\u00f3 que se mantenga el espacio \u201crewe\u201d, considerado como un lugar sagrado por los mapuches y el grupo \u201cLof Lafken Winkul Mapu\u201d. Este s\u00e1bado, la&hellip; <\/p>\n","protected":false},"author":1,"featured_media":11478,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-11477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/11477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=11477"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/11477\/revisions"}],"predecessor-version":[{"id":11479,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/11477\/revisions\/11479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/11478"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=11477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=11477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=11477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}