{"id":115360,"date":"2023-12-31T11:01:20","date_gmt":"2023-12-31T14:01:20","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=115360"},"modified":"2023-12-31T11:01:31","modified_gmt":"2023-12-31T14:01:31","slug":"nicaragua-detuvo-a-otros-cuatro-sacerdotes-catolicos","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/internacionales\/nicaragua-detuvo-a-otros-cuatro-sacerdotes-catolicos\/","title":{"rendered":"Nicaragua detuvo a otros cuatro sacerdotes cat\u00f3licos"},"content":{"rendered":"\n<p>Ya suman 12 religiosos arrestados en tres d\u00edas.<\/p>\n\n\n\n<p>La polic\u00eda nicarag\u00fcense detuvo la madrugada del s\u00e1bado a cuatro&nbsp;<strong>sacerdotes<\/strong>&nbsp;m\u00e1s, para sumar 12 en los \u00faltimos tres d\u00edas, confirm\u00f3 a la agencia de noticias Reuters un miembro de alto rango de la iglesia cat\u00f3lica del pa\u00eds centroamericano.<\/p>\n\n\n\n<p>En la madrugada fueron sacados de sus casas los&nbsp;<strong>sacerdotes<\/strong>&nbsp;Mikel Monterrey, Gerardo Rodr\u00edguez y Ra\u00fal Zamora, junto con monse\u00f1or Miguel Mantica, hijo de una de las familias m\u00e1s ricas de Nicaragua.<\/p>\n\n\n\n<p>&#8220;Est\u00e1n confirmadas las detenciones por las que preguntas, todos son de la<strong>&nbsp;Arquidi\u00f3cesis de Managua<\/strong>&nbsp;y pensamos que lo que quieren es expulsarlos del pa\u00eds&#8221;, sostuvo el miembro de alto rango de la Iglesia.<\/p>\n\n\n\n<p>En los \u00faltimos d\u00edas fueron detenidos en Nicaragua 12 sacerdotes y el obispo Isidro Mora, que junto al obispo Rolando \u00c1lvarez &nbsp;-condenado a 26 a\u00f1os de c\u00e1rcel- son los miembros de m\u00e1s alto rango de la iglesia arrestados en el pa\u00eds que&nbsp;<strong>Daniel<\/strong>&nbsp;<strong>Ortega&nbsp;<\/strong>gobierna desde 2007. Esto lo llev\u00f3 a confrontar con los cat\u00f3licos.<\/p>\n\n\n\n<p><strong>Ortega&nbsp;<\/strong>acusa a los sacerdotes de prestarse para darle un golpe de Estado en 2018 cuando estallaron las protestas callejeras que el Gobierno reprimi\u00f3 y dej\u00f3 un saldo de 360 fallecidos, la mayor\u00eda opositores, v\u00edctimas &nbsp;de la Polic\u00eda y civiles armados leales al r\u00e9gimen, seg\u00fan organismos internacionales de derechos humanos.<\/p>\n\n\n\n<p>Los obispos pidieron a&nbsp;<strong>Ortega&nbsp;<\/strong>justicia por los fallecidos y elecciones adelantadas.<\/p>\n\n\n\n<p>Entre los detenidos este s\u00e1bado en la madrugada se encuentran dos&nbsp;<strong>sacerdotes&nbsp;<\/strong>que abrieron las puertas de su parroquia a los estudiantes de dos universidades que en 2018 fueron atacadas por el Gobierno.<\/p>\n\n\n\n<p>Monterrey es sacerdote de una parroquia aleda\u00f1a a la extinta&nbsp;<strong>bautista Universidad Polit\u00e9cnica<\/strong>, confiscada por el Gobierno, y en sus homil\u00edas no dejaba de orar por monse\u00f1or \u00c1lvarez, feligreses de su iglesia.<\/p>\n\n\n\n<p>Seg\u00fan tres fuentes de la Iglesia nicarag\u00fcense, el Gobierno pidi\u00f3 que no mencionaran el nombre de&nbsp;<strong>\u00c1lvarez&nbsp;<\/strong>en las homil\u00edas y los detenidos se habr\u00edan negado aduciendo que como cristianos ten\u00edan que orar por los presos.<\/p>\n\n\n\n<p>Reuters busc\u00f3 una versi\u00f3n del&nbsp;<strong>Gobierno nicarag\u00fcense&nbsp;<\/strong>y la Polic\u00eda, pero no obtuvo una respuesta a tiempo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya suman 12 religiosos arrestados en tres d\u00edas. La polic\u00eda nicarag\u00fcense detuvo la madrugada del s\u00e1bado a cuatro&nbsp;sacerdotes&nbsp;m\u00e1s, para sumar 12 en los \u00faltimos tres d\u00edas, confirm\u00f3 a la agencia&hellip; <\/p>\n","protected":false},"author":4,"featured_media":115361,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-115360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/115360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=115360"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/115360\/revisions"}],"predecessor-version":[{"id":115362,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/115360\/revisions\/115362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/115361"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=115360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=115360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=115360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}