{"id":115488,"date":"2024-01-01T09:18:43","date_gmt":"2024-01-01T12:18:43","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=115488"},"modified":"2024-01-01T09:18:48","modified_gmt":"2024-01-01T12:18:48","slug":"terremoto-de-76-grados-en-japon-hay-alerta-de-tsunami-cortes-de-energia-y-personas-atrapadas-bajo-los-escombros","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/informacion-general\/terremoto-de-76-grados-en-japon-hay-alerta-de-tsunami-cortes-de-energia-y-personas-atrapadas-bajo-los-escombros\/","title":{"rendered":"Terremoto de 7,6 grados en Jap\u00f3n: hay alerta de tsunami, cortes de energ\u00eda y personas atrapadas bajo los escombros"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<p>Olas de\u00a0<strong>tsunami\u00a0<\/strong>de m\u00e1s de un metro de altura sacudieron el lunes el centro de\u00a0<strong>Jap\u00f3n\u00a0<\/strong>tras una serie de fuertes\u00a0<strong>terremotos\u00a0<\/strong>que da\u00f1aron viviendas, cerraron carreteras y llevaron a las autoridades a instar a la poblaci\u00f3n a correr hacia zonas m\u00e1s altas.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Un terremoto de 7,4 grados activa la alerta de tsunami en Jap\u00f3n\" width=\"1110\" height=\"624\" src=\"https:\/\/www.youtube.com\/embed\/jT4e8s8wVrU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Un<strong>\u00a0terremoto de magnitud 7,6 sacudi\u00f3 la regi\u00f3n de Noto<\/strong>, en la prefectura de\u00a0<strong>Ishikawa<\/strong>, sobre las 16:10 (0710 GMT), seg\u00fan inform\u00f3 el Servicio Geol\u00f3gico de Estados Unidos (USGS). La agencia meteorol\u00f3gica japonesa inform\u00f3 de una<strong>\u00a0sucesi\u00f3n de 21 sismos de magnitud 4,0<\/strong>\u00a0o superior que sacudieron la regi\u00f3n central del pa\u00eds en poco m\u00e1s de 90 minutos.<\/p>\n\n\n\n<p>Chile Evacuaci\u00f3n Tsunami Tonga 2<\/p>\n\n\n\n<p>CerrarLos registros de este video se efectuaron en Suzu, prefectura de Ishikawa<\/p>\n\n\n\n<p><strong>Olas de tsunami de hasta 1,2 metros de altura<\/strong>&nbsp;golpearon el puerto de&nbsp;<strong>Wajima<\/strong>, en la prefectura de&nbsp;<strong>Ishikawa<\/strong>, a las 16:21 (0721 GMT), unos 10 minutos despu\u00e9s de la sacudida m\u00e1s fuerte, inform\u00f3 la Agencia Meteorol\u00f3gica de Jap\u00f3n (JMA).<\/p>\n\n\n\n<p>\u201cTodos los residentes deben evacuar inmediatamente a terrenos m\u00e1s elevados\u201d, dijo la cadena nacional&nbsp;<em>NHK&nbsp;<\/em>tras los terremotos.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Grietas en la carretera causadas por un terremoto en Wajima (Kyodo via REUTERS)\" height=\"2447\" width=\"3263\" src=\"https:\/\/www.infobae.com\/new-resizer\/u1rSYUaBYQpBUkOBnTG-3orNq48=\/420x315\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/CPYITBSPQXU5J7E4QYLWWPLS6I.jpg%20420w\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/u1rSYUaBYQpBUkOBnTG-3orNq48=\/420x315\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/CPYITBSPQXU5J7E4QYLWWPLS6I.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/rpida4IdAiOziSGkY9YKDD882_o=\/768x576\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/CPYITBSPQXU5J7E4QYLWWPLS6I.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/2JTbgp9HD7UaZM01-756MgqYiZc=\/992x744\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/CPYITBSPQXU5J7E4QYLWWPLS6I.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/qFn0sdiGx9nGGuhWlxAYs86eyxM=\/1200x900\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/CPYITBSPQXU5J7E4QYLWWPLS6I.jpg 1200w,https:\/\/www.infobae.com\/new-resizer\/fNPeFl7rmn0oQavcK-MsfYwrexk=\/1440x1080\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/CPYITBSPQXU5J7E4QYLWWPLS6I.jpg 1440w\">Grietas en la carretera causadas por un terremoto en Wajima (Kyodo via REUTERS)<\/p>\n\n\n\n<p>Tras el sismo,<strong>&nbsp;Ishikawa&nbsp;<\/strong>emiti\u00f3 una \u201calerta de envergadura por tsunami\u201d, la primera de esta naturaleza desde el devastador terremoto de 2011, y que implicaba la aparici\u00f3n de olas de entre tres y cinco metros contra la costa. Posteriormente se ha rebajado a \u201calerta de tsunami\u201d. Las autoridades tambi\u00e9n han confirmado la llegada de oleaje a las prefecturas de&nbsp;<strong>Yamagata<\/strong>,&nbsp;<strong>Niigata&nbsp;<\/strong>y&nbsp;<strong>Toyama<\/strong>.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"La JMA activ\u00f3 la alerta para olas de hasta cinco metros de altura en la prefectura de Ishikawa y para olas de hasta tres metros para las prefecturas de Fukui, Toyama, Hyogo, Niigata y Yamagata, y tambi\u00e9n implement\u00f3 una alerta general de tsunami para toda la costa occidental de la islas de Honshu y Hokkaido y el norte de la isla de Kyushu. (NHK)\n\" height=\"532\" width=\"949\" src=\"https:\/\/www.infobae.com\/new-resizer\/LANGF14fis9bsa5zwflaOGwHgTo=\/420x236\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/TCRMXETYBNGSRERFJNGLIK4RTM.png%20420w\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/LANGF14fis9bsa5zwflaOGwHgTo=\/420x236\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/TCRMXETYBNGSRERFJNGLIK4RTM.png 420w,https:\/\/www.infobae.com\/new-resizer\/kMkukyDyQ4-ndlCY_MtZiwgmtqA=\/768x432\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/TCRMXETYBNGSRERFJNGLIK4RTM.png 768w,https:\/\/www.infobae.com\/new-resizer\/H_EshO8jK_TMR461ymk4EkO9VYQ=\/992x558\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/TCRMXETYBNGSRERFJNGLIK4RTM.png 992w,https:\/\/www.infobae.com\/new-resizer\/VnCd64I7Z0zhEYYsmDN6iprn0_Y=\/1200x675\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/TCRMXETYBNGSRERFJNGLIK4RTM.png 1200w,https:\/\/www.infobae.com\/new-resizer\/gYSNIPgWM6O7MD0hOGY1Ja1XUVc=\/1440x810\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/TCRMXETYBNGSRERFJNGLIK4RTM.png 1440w\">La JMA activ\u00f3 la alerta para olas de hasta cinco metros de altura en la prefectura de Ishikawa y para olas de hasta tres metros para las prefecturas de Fukui, Toyama, Hyogo, Niigata y Yamagata, y tambi\u00e9n implement\u00f3 una alerta general de tsunami para toda la costa occidental de la islas de Honshu y Hokkaido y el norte de la isla de Kyushu. (NHK)<\/p>\n\n\n\n<p>El&nbsp;<strong>Centro de Alerta de Tsunamis del Pac\u00edfico<\/strong>, con sede en Hawai, se\u00f1al\u00f3 que era posible que se produjeran<strong>&nbsp;olas de tsunami peligrosas en un radio de 300 kil\u00f3metros<\/strong>&nbsp;desde el epicentro del se\u00edsmo a lo largo de la costa, en el lado del Mar de Jap\u00f3n de la isla principal japonesa de Honshu.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Una casa derrumbada tras un terremoto en Wajima, prefectura de Ishikawa, (Kyodo via REUTERS)\" height=\"1338\" width=\"1973\" src=\"https:\/\/www.infobae.com\/new-resizer\/updF0kYJha4s6gwcSBgz7ououY8=\/420x280\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/PS7CFWYWFBN6LQ3CIXOSTN7YTE.jpg%20420w\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/updF0kYJha4s6gwcSBgz7ououY8=\/420x280\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/PS7CFWYWFBN6LQ3CIXOSTN7YTE.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/8QGmvsPmDzUkljRyyfVsaQ1VRS0=\/768x512\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/PS7CFWYWFBN6LQ3CIXOSTN7YTE.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/rIKZYzhiYyvycVdaoJl00zZGaHI=\/992x661\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/PS7CFWYWFBN6LQ3CIXOSTN7YTE.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/mLrUvjiSeS_oypuRLwAC99394EE=\/1200x800\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/PS7CFWYWFBN6LQ3CIXOSTN7YTE.jpg 1200w,https:\/\/www.infobae.com\/new-resizer\/VufZdkNZhGngdrQ2qlBT-VpHOr4=\/1440x960\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/PS7CFWYWFBN6LQ3CIXOSTN7YTE.jpg 1440w\">Una casa derrumbada tras un terremoto en Wajima, prefectura de Ishikawa, (Kyodo via REUTERS)<\/p>\n\n\n\n<p>Por eso, ciudades del extremo oriente ruso, entre ellas&nbsp;<strong>Vladivostok<\/strong>, tambi\u00e9n emitieron una<strong>&nbsp;\u201calerta<\/strong>\u201d por posible riesgo de tsunami, aunque por el momento no se llegaron a cabo evacuaciones. \u201dLas zonas costeras de la costa occidental de&nbsp;<strong>Sajal\u00edn&nbsp;<\/strong>podr\u00edan verse afectadas por las olas de un tsunami\u201d, alert\u00f3 el ministerio ruso de Situaciones de Emergencia en Telegram. Las autoridades de Vladivostok aconsejaron a los pescadores que regresen al puerto.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Un coche atrapado bajo una casa derrumbada tras un terremoto, en la ciudad de Shika, prefectura de Ishikawa. (Kyodo via REUTERS)\" height=\"1707\" width=\"960\" src=\"https:\/\/www.infobae.com\/new-resizer\/W5ACW73hsg0QTnxC1U6RRF_QZP0=\/420x747\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/HAP3R7VMCJBMDQ6SP5XUYTR5BA.jpg%20420w\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/W5ACW73hsg0QTnxC1U6RRF_QZP0=\/420x747\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/HAP3R7VMCJBMDQ6SP5XUYTR5BA.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/MOMU8-fqgAvfUkwJnb8fagGI1S0=\/768x1365\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/HAP3R7VMCJBMDQ6SP5XUYTR5BA.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/O2-BaPJ4i6G671b5ItvQrU1N-ow=\/992x1764\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/HAP3R7VMCJBMDQ6SP5XUYTR5BA.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/aDZBB0fuKXM-S0VRr6_kIN06krc=\/1200x2133\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/HAP3R7VMCJBMDQ6SP5XUYTR5BA.jpg 1200w\">Un coche atrapado bajo una casa derrumbada tras un terremoto, en la ciudad de Shika, prefectura de Ishikawa. (Kyodo via REUTERS)<\/p>\n\n\n\n<p><strong>Corea del Sur<\/strong>&nbsp;ha emitido alertas por la subida del nivel del mar, inform\u00f3 la agencia de noticias&nbsp;<em>Yonhap<\/em>. La provincia oriental de&nbsp;<strong>Gangwon&nbsp;<\/strong>ha instado a algunos residentes a evacuar a zonas m\u00e1s altas. La Administraci\u00f3n Meteorol\u00f3gica de Corea del Sur dijo que las olas del tsunami pueden alcanzar mayores alturas despu\u00e9s de las olas iniciales.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\u201cTodos los residentes deben evacuar inmediatamente a terrenos m\u00e1s altos\u201d, dijo la emisora nacional NHK.\" height=\"1600\" width=\"1200\" src=\"https:\/\/www.infobae.com\/new-resizer\/z3x2E8IIo_6XLO3HjaYISyNoNW0=\/420x560\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ODROTD27AFCPNMJWM3MZEKCFJQ.jpg%20420w\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/z3x2E8IIo_6XLO3HjaYISyNoNW0=\/420x560\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ODROTD27AFCPNMJWM3MZEKCFJQ.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/S1ttHwlZxhMxo3uqFs20CNKUbVQ=\/768x1024\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ODROTD27AFCPNMJWM3MZEKCFJQ.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/vmYffoZ-G2xXC1LFAc7h_9358DI=\/992x1323\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ODROTD27AFCPNMJWM3MZEKCFJQ.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/cWp6xmxnFkDZBcSsyahWPmnrkI4=\/1200x1600\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ODROTD27AFCPNMJWM3MZEKCFJQ.jpg 1200w\">\u201cTodos los residentes deben evacuar inmediatamente a terrenos m\u00e1s altos\u201d, dijo la emisora nacional NHK.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">35 mil hogares sin electricidad<\/h2>\n\n\n\n<p>Terremoto en Jap\u00f3n<\/p>\n\n\n\n<p>El gobierno japon\u00e9s dijo que todav\u00eda estaba&nbsp;<strong>evaluando los da\u00f1os&nbsp;<\/strong>causados y si hab\u00eda habido v\u00edctimas.<\/p>\n\n\n\n<p>La ciudad de&nbsp;<strong>Wajima<\/strong>, en la prefectura de Ishikawa, ha sido la m\u00e1s afectada hasta ahora por el sismo. Las autoridades locales han confirmado que al menos una decena de edificios se han derrumbado y hay un&nbsp;<strong>n\u00famero todav\u00eda indeterminado de gente bajo los escombros.<\/strong><\/p>\n\n\n\n<p>En la ciudad tambi\u00e9n se desataron<strong>&nbsp;incendios que han destruido al menos media docena de casas.<\/strong>&nbsp;A\u00fan no hay noticias de heridos o v\u00edctimas mortales.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Una vista a\u00e9rea muestra el lugar del incendio tras el terremoto en una zona residencial de Wajima, prefectura de Ishikawa,  (Kyodo via REUTERS)\" height=\"2806\" width=\"3948\" src=\"https:\/\/www.infobae.com\/new-resizer\/uxuV0F4R9Tdr4xb73umwHG0xJjc=\/420x280\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/HR2V7E2LYW7LUAOC5KV6WQMZG4.jpg%20420w\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/uxuV0F4R9Tdr4xb73umwHG0xJjc=\/420x280\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/HR2V7E2LYW7LUAOC5KV6WQMZG4.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/sE9skKI71WJg02lkgvTOlMLfxNU=\/768x512\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/HR2V7E2LYW7LUAOC5KV6WQMZG4.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/MfqhsV_a4w_OjVP-xQfzV8Jdjig=\/992x661\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/HR2V7E2LYW7LUAOC5KV6WQMZG4.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/zFEjhn5sBEM3GjzhTnQzWyQxqio=\/1200x800\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/HR2V7E2LYW7LUAOC5KV6WQMZG4.jpg 1200w,https:\/\/www.infobae.com\/new-resizer\/NTZ5NY5myRnURIyH82nXYEx53LU=\/1440x960\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/HR2V7E2LYW7LUAOC5KV6WQMZG4.jpg 1440w\">Una vista a\u00e9rea muestra el lugar del incendio tras el terremoto en una zona residencial de Wajima, prefectura de Ishikawa, (Kyodo via REUTERS)<\/p>\n\n\n\n<p>Alrededor de&nbsp;<strong>33.500 hogares de los alrededores del epicentro<\/strong>, en las prefecturas de Toyama, Ishikawa y Niigata,&nbsp;<strong>se quedaron sin electricidad,<\/strong>&nbsp;seg\u00fan las empresas locales de servicios p\u00fablicos.<\/p>\n\n\n\n<p>Terremoto en Jap\u00f3n y alerta de tsunami<\/p>\n\n\n\n<p>\u201cEste es el distrito Matsunami de Noto. Estamos en una situaci\u00f3n horrible. Por favor, vengan a ayudarnos. Mi ciudad est\u00e1 en una situaci\u00f3n horrible\u201d, dice una persona a la que se escucha en el v\u00eddeo.<\/p>\n\n\n\n<p>El hospital de la ciudad de&nbsp;<strong>Suzu<\/strong>, en Ishikawa, est\u00e1<strong>&nbsp;recibiendo un gran n\u00famero de heridos.<\/strong>&nbsp;Las carreteras da\u00f1adas est\u00e1n retrasando el transporte de los heridos. El hospital funciona con sus propios generadores, ya que el distrito circundante se ha quedado sin electricidad. Se prev\u00e9 que las temperaturas en la zona afectada desciendan hasta alrededor de 1 \u00baC durante la noche<strong>.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La vida por encima de todo<\/h2>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"En Kaga, prefectura de Ishikawa, se observa una instalaci\u00f3n comercial derrumbada a causa de un terremoto. (Kyodo via REUTERS)\" height=\"1326\" width=\"1823\" src=\"https:\/\/www.infobae.com\/new-resizer\/hcmHld6Y61C3q-tOVlKlotB-2-4=\/420x315\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/BZRKUQ6FFJQMZFA2AIF43AOAP4.jpg%20420w\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/hcmHld6Y61C3q-tOVlKlotB-2-4=\/420x315\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/BZRKUQ6FFJQMZFA2AIF43AOAP4.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/CPKCwT9unzRmfexcuoLQQGAJ2JQ=\/768x576\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/BZRKUQ6FFJQMZFA2AIF43AOAP4.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/8qLH1S9cQqvOKcAJde3WmvuTX7Y=\/992x744\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/BZRKUQ6FFJQMZFA2AIF43AOAP4.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/4_qPZ_e5N0Bx1m928lsSnm-o4xs=\/1200x900\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/BZRKUQ6FFJQMZFA2AIF43AOAP4.jpg 1200w,https:\/\/www.infobae.com\/new-resizer\/9_117q1sJxt16Tb98IqMJSLUUOs=\/1440x1080\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/BZRKUQ6FFJQMZFA2AIF43AOAP4.jpg 1440w\">En Kaga, prefectura de Ishikawa, se observa una instalaci\u00f3n comercial derrumbada a causa de un terremoto. (Kyodo via REUTERS)<\/p>\n\n\n\n<p>La JMA dijo que la regi\u00f3n de Noto experiment\u00f3 una r\u00e1pida sucesi\u00f3n de sismos, con otro temblor de 6,2 grados que se produjo poco despu\u00e9s del enjambre inicial, dijo el USGS.<\/p>\n\n\n\n<p>El mayor de los se\u00edsmos llev\u00f3 a las cadenas de televisi\u00f3n a cambiar a una programaci\u00f3n especial y a hacer<strong>&nbsp;llamamientos urgentes para que los residentes afectados se marcharan a terrenos m\u00e1s elevados.<\/strong><\/p>\n\n\n\n<p>\u201cSomos conscientes de que su casa y sus pertenencias son preciosas para ustedes, pero<strong>&nbsp;sus vidas son importantes por encima de todo.<\/strong>&nbsp;Corran a la zona m\u00e1s alta posible\u201d, dijo a los telespectadores un presentador de la cadena&nbsp;<em>NHK<\/em>.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Personas sentadas en el suelo mientras los art\u00edculos caen de las estanter\u00edas al suelo dentro de una tienda tras un terremoto, en Kanazawa, Ishikawa. (Instagram @hsu.tw\/via REUTERS)\" height=\"2240\" width=\"1248\" src=\"https:\/\/www.infobae.com\/new-resizer\/r7iy3MenW_KquSbKABVe5L1qJv4=\/420x747\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/6JPBJXTSP7777MBGQU2EGYV7IE.jpg%20420w\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/r7iy3MenW_KquSbKABVe5L1qJv4=\/420x747\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/6JPBJXTSP7777MBGQU2EGYV7IE.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/WpTBCQBzLDFmWAXwjA8_I1y4ELM=\/768x1365\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/6JPBJXTSP7777MBGQU2EGYV7IE.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/V54fyty6qyAakCfkAmu2Yw7YBE8=\/992x1764\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/6JPBJXTSP7777MBGQU2EGYV7IE.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/lAajM4pSl5_RIk5col5LKp17qU0=\/1200x2133\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/6JPBJXTSP7777MBGQU2EGYV7IE.jpg 1200w\">Personas sentadas en el suelo mientras los art\u00edculos caen de las estanter\u00edas al suelo dentro de una tienda tras un terremoto, en Kanazawa, Ishikawa. (Instagram @hsu.tw\/via REUTERS)<\/p>\n\n\n\n<p>Varias autopistas importantes fueron cerradas alrededor del epicentro, dijo el operador de carreteras de Jap\u00f3n, y los servicios del tren bala&nbsp;<strong>Shinkansen&nbsp;<\/strong>tambi\u00e9n fueron suspendidos entre Tokio y el epicentro en Noto. El diario econ\u00f3mico&nbsp;<em>Nikkei&nbsp;<\/em>inform\u00f3 que tambi\u00e9n se han<strong>&nbsp;suspendido los servicios ferroviarios&nbsp;<\/strong>en el noreste del pa\u00eds y en el centro y norte del litoral occidental.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"El movimiento tel\u00farico tuvo su origen en la prefectura de Ishikawa, situada en el centro de la isla de Honshu, la principal del pa\u00eds\" height=\"1600\" width=\"1200\" src=\"https:\/\/www.infobae.com\/new-resizer\/XbWUvpfMptMYJNDFQAXegYAPlOQ=\/420x560\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/JWV747ZJ3ZCUTI5VUGPXLULUEE.jpg%20420w\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/XbWUvpfMptMYJNDFQAXegYAPlOQ=\/420x560\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/JWV747ZJ3ZCUTI5VUGPXLULUEE.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/AFW48kVureSLTK2eQgOOrM1Kz34=\/768x1024\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/JWV747ZJ3ZCUTI5VUGPXLULUEE.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/4enzkektDa8nbRJ_PojQlB6KVv0=\/992x1323\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/JWV747ZJ3ZCUTI5VUGPXLULUEE.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/JZOw3JejBlt8ZJ7hkxNPIhylBZ0=\/1200x1600\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/JWV747ZJ3ZCUTI5VUGPXLULUEE.jpg 1200w\">El movimiento tel\u00farico tuvo su origen en la prefectura de Ishikawa, situada en el centro de la isla de Honshu, la principal del pa\u00eds<\/p>\n\n\n\n<p>El d\u00eda de A\u00f1o Nuevo es la principal fiesta de invierno en Jap\u00f3n y muchas familias tendr\u00e1n que volver a visitar a sus parientes en sus ciudades de origen desde grandes ciudades como&nbsp;<strong>Tokio&nbsp;<\/strong>y&nbsp;<strong>Osaka<\/strong>. Los residentes de la capital del pa\u00eds han constatado temblores en los edificios a consecuencia del temblor pero de momento no se tiene constancia de v\u00edctimas en la metr\u00f3polis.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Puerta torii derrumbada a causa de un terremoto en Onohiyoshi, en Kanazawa (Kyodo via REUTERS)\" height=\"1500\" width=\"2000\" src=\"https:\/\/www.infobae.com\/new-resizer\/9HABy1PeK2TfPowUb00KcEw0W9k=\/420x315\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/447KGROLBY62OEC5YR73FNKUUE.jpg%20420w\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/9HABy1PeK2TfPowUb00KcEw0W9k=\/420x315\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/447KGROLBY62OEC5YR73FNKUUE.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/UY6lcxOB9uq0EOSC_XXpfmYuAf0=\/768x576\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/447KGROLBY62OEC5YR73FNKUUE.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/FVRgkyhjUZjszq_XGgZLhXd5a9M=\/992x744\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/447KGROLBY62OEC5YR73FNKUUE.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/p-R3uHuoWj9R2epC3GQl5WzzxHQ=\/1200x900\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/447KGROLBY62OEC5YR73FNKUUE.jpg 1200w,https:\/\/www.infobae.com\/new-resizer\/yamxwVJLcK1FE93wS3zvt9MRcts=\/1440x1080\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/447KGROLBY62OEC5YR73FNKUUE.jpg 1440w\">Puerta torii derrumbada a causa de un terremoto en Onohiyoshi, en Kanazawa (Kyodo via REUTERS)<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Centrales nucleares sin anomal\u00edas<\/h2>\n\n\n\n<p>La oficina del primer ministro nip\u00f3n,&nbsp;<strong>Fumio Kishida<\/strong>, convoc\u00f3 un gabinete de crisis para gestionar la situaci\u00f3n.<\/p>\n\n\n\n<p>La<strong>&nbsp;Autoridad de Regulaci\u00f3n Nuclear<\/strong>&nbsp;(NRA) de&nbsp;<strong>Jap\u00f3n&nbsp;<\/strong>declar\u00f3 que<strong>&nbsp;no se hab\u00edan detectado problemas en los reactores de ninguna de las centrales nucleares de la zona<\/strong>&nbsp;afectada en una rueda de prensa celebrada hacia las 18.30 horas. Sin embargo, se han confirmado vertidos de petr\u00f3leo y otros da\u00f1os menores en las instalaciones nucleares de la zona.<\/p>\n\n\n\n<p>La operadora Kansai Electric Power Company no ha constatado da\u00f1os en las centrales nucleares de&nbsp;<strong>Ohi&nbsp;<\/strong>y&nbsp;<strong>Takahama<\/strong>, en la prefectura de Fukui, dos de las m\u00e1s vulnerables del litoral oeste ante un posible se\u00edsmo, recoge la cadena p\u00fablica japonesa&nbsp;<em>NHK<\/em>.<\/p>\n\n\n\n<p>Tampoco se ha visto afectada de momento la central de Kashiwazaki-Kariwa, seg\u00fan un comunicado de la Tokyo Electric Power Company (TEPCO) recogido por el<em>&nbsp;Asahi Shimbun<\/em>.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Varias personas caminan por una carretera da\u00f1ada por el terremoto en Wajima (Kyodo via REUTERS)\" height=\"2447\" width=\"3263\" src=\"https:\/\/www.infobae.com\/new-resizer\/GbX-NHwxtCUoMMh5wmmr0iygqdI=\/420x315\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/E6UBJW4O4EE5PW5VQB3JPW5EYA.jpg%20420w\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/GbX-NHwxtCUoMMh5wmmr0iygqdI=\/420x315\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/E6UBJW4O4EE5PW5VQB3JPW5EYA.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/JunsuMjOp4xC9g8IymQIKTIkVKM=\/768x576\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/E6UBJW4O4EE5PW5VQB3JPW5EYA.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/WdLo0YF0I2PKYgvkRSbcVzW5TzU=\/992x744\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/E6UBJW4O4EE5PW5VQB3JPW5EYA.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/CWU8I_PFdsJ_PBWTKKux73AAexY=\/1200x900\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/E6UBJW4O4EE5PW5VQB3JPW5EYA.jpg 1200w,https:\/\/www.infobae.com\/new-resizer\/vXqGiVMO0g0YmDpOshqpjKN6Lag=\/1440x1080\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/E6UBJW4O4EE5PW5VQB3JPW5EYA.jpg 1440w\">Varias personas caminan por una carretera da\u00f1ada por el terremoto en Wajima (Kyodo via REUTERS)<\/p>\n\n\n\n<p>Dos de los reactores actualmente en funcionamiento en la zona, en la central de&nbsp;<strong>Shika<\/strong>, en Ishikawa, no estaban en marcha en el momento de los temblores debido a una revisi\u00f3n programada.<\/p>\n\n\n\n<p>La mayor\u00eda de los 54 reactores de Jap\u00f3n est\u00e1n fuera de servicio desde la cat\u00e1strofe nuclear de&nbsp;<strong>Fukushima&nbsp;<\/strong>de marzo de 2011, desencadenada por un terremoto de magnitud 9 y un tsunami devastador.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Un grupo de personas junto a una puerta torii derrumbada por un terremoto en el santuario de Onohiyoshi, en Kanazawa. (Kyodo via REUTER)\" height=\"1152\" width=\"1643\" src=\"https:\/\/www.infobae.com\/new-resizer\/-khqewQTsDO4ojDSN3Sy-uZ2KzA=\/420x280\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/P3ULRIRBXOYLFBXPT5DJ3F7XKM.jpg%20420w\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/-khqewQTsDO4ojDSN3Sy-uZ2KzA=\/420x280\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/P3ULRIRBXOYLFBXPT5DJ3F7XKM.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/6IgCj13Kk8S7kAPZ5lrEfVpF7Hk=\/768x512\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/P3ULRIRBXOYLFBXPT5DJ3F7XKM.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/cL3gVhc4dJ5XN_hqP9j8lGo3J98=\/992x661\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/P3ULRIRBXOYLFBXPT5DJ3F7XKM.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/5mVAGYb9ocrRGN3pl3gcgU5HBRE=\/1200x800\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/P3ULRIRBXOYLFBXPT5DJ3F7XKM.jpg 1200w,https:\/\/www.infobae.com\/new-resizer\/0zVu-aCeESsUexyAq5scfRoEC5M=\/1440x960\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/P3ULRIRBXOYLFBXPT5DJ3F7XKM.jpg 1440w\">Un grupo de personas junto a una puerta torii derrumbada por un terremoto en el santuario de Onohiyoshi, en Kanazawa. (Kyodo via REUTER)<\/p>\n\n\n\n<p><strong>Jap\u00f3n&nbsp;<\/strong>cuenta con estrictas normas de construcci\u00f3n para garantizar que los edificios puedan resistir fuertes terremotos y realiza habitualmente simulacros de emergencia para prepararse ante una sacudida de gran magnitud.<\/p>\n\n\n\n<p>Pero el pa\u00eds est\u00e1&nbsp;<strong>atormentado por el recuerdo de un enorme terremoto submarino de magnitud 9,0 frente al noreste de Jap\u00f3n en marzo de 2011<\/strong>, que desencaden\u00f3 un tsunami que dej\u00f3 alrededor de&nbsp;<strong>18.500 muertos o desaparecidos.<\/strong><\/p>\n\n\n\n<p>El<strong>&nbsp;tsunami de 2011&nbsp;<\/strong>tambi\u00e9n provoc\u00f3 la fusi\u00f3n de tres reactores de la central nuclear de&nbsp;<strong>Fukushima<\/strong>, causando el peor desastre de la posguerra en Jap\u00f3n y el accidente nuclear m\u00e1s grave desde Chern\u00f3bil.<\/p>\n\n\n\n<p>En marzo de 2022, un terremoto de magnitud 7,4 frente a la costa de Fukushima sacudi\u00f3 amplias zonas del este de Jap\u00f3n y caus\u00f3 tres muertos.<\/p>\n\n\n\n<p>La capital, Tokio, fue devastada por un gran terremoto hace un siglo, en 1923.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Olas de\u00a0tsunami\u00a0de m\u00e1s de un metro de altura sacudieron el lunes el centro de\u00a0Jap\u00f3n\u00a0tras una serie de fuertes\u00a0terremotos\u00a0que da\u00f1aron viviendas, cerraron carreteras y llevaron a las autoridades a instar a&hellip; <\/p>\n","protected":false},"author":1,"featured_media":115491,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-115488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/115488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=115488"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/115488\/revisions"}],"predecessor-version":[{"id":115492,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/115488\/revisions\/115492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/115491"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=115488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=115488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=115488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}