{"id":115502,"date":"2024-01-01T10:30:57","date_gmt":"2024-01-01T13:30:57","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=115502"},"modified":"2024-01-01T10:31:09","modified_gmt":"2024-01-01T13:31:09","slug":"inflacion-cerca-del-30-en-diciembre-supero-el-200-en-2023","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/economia\/inflacion-cerca-del-30-en-diciembre-supero-el-200-en-2023\/","title":{"rendered":"Inflaci\u00f3n cerca del 30% en diciembre, super\u00f3 el 200%\u00a0en 2023"},"content":{"rendered":"\n<p>La devaluaci\u00f3n del tipo de cambio y la liberaci\u00f3n de precios de diciembre prepararon el terreno para un \u00edndice mensual de inflaci\u00f3n que ser\u00e1 r\u00e9cord en m\u00e1s de tres d\u00e9cadas, superior al 200% interanual. Las consultoras estiman que el IPC estar\u00e1 bien por encima del 20% y algunas lo arriman al 30%, lo que dejar\u00e1 un arrastre para el inicio del 2024. El \u00faltimo mes del 2023 habr\u00e1 implicado, as\u00ed, un fuerte impacto inicial en el poder de compra de salarios y jubilaciones en el arranque de mandato del presidente Javier Milei.<\/p>\n\n\n\n<p>El salto cambiario en el inicio del plan econ\u00f3mico del gobierno libertario y el fin de los acuerdos con empresas que manten\u00edan a raya una serie de precios relevantes de la econom\u00eda provocaron una reacci\u00f3n inmediata en el ecosistema de precios, entre ellos en los alimentos. Los aumentos de precios semanales relevados por consultoras privadas anotaron niveles r\u00e9cord, a ritmo de dos d\u00edgitos, algo que solo se hab\u00eda registrado para las mediciones con alcance mensual en los \u00faltimos meses.<\/p>\n\n\n\n<p>Puesto en n\u00fameros, seg\u00fan Equilibra, &#8220;desde el ballotage la nafta subi\u00f3 92%, los medicamentos 52%, cigarrillos 37% y varios productos dentro el programa de Precios Justos entre 40% y 60%&#8221;, enumer\u00f3 la consultora, que para diciembre estim\u00f3 un aumento de 26% del \u00edndice general.<\/p>\n\n\n\n<p>Por su parte, Invecq midi\u00f3 que en el \u00faltimo mes del a\u00f1o pasado los precios subieron 22,8%, un guarismo m\u00e1s bajo pero que igualmente ser\u00eda el incremento mensual general de precios m\u00e1s alto en 33 a\u00f1os. &#8220;Este incremento extraordinario se explica principalmente por el aumento del tipo de cambio oficial (118%); y, en menor medida, por la paulatina correcci\u00f3n de algunos precios regulados. En su interior, se destaca la din\u00e1mica de los alimentos, cuyo precio trep\u00f3 casi 34%&#8221;, destac\u00f3 la consultora.<\/p>\n\n\n\n<p>En ese sentido, Invecq mencion\u00f3 que &#8220;los precios se dispararon tras la devaluaci\u00f3n del 13\/12 y aumentaron 9,4% en tan solo una semana. Desde aquel entonces, la suba moriger\u00f3 su ritmo (aunque vienen creciendo a un ritmo de casi 30% mensual)&#8221;.<\/p>\n\n\n\n<p>Para Libertad y Progreso, en tanto, con la informaci\u00f3n disponible hasta la tercera semanas del mes, la inflaci\u00f3n de diciembre viajaba a ritmo de 24,6 por ciento. &#8220;Siguiendo la trayectoria actual, proyectamos que la suba del IPC del mes se situar\u00e1 en torno al 29%&#8221;, indicaron. &#8220;En cuanto a la variaci\u00f3n interanual, la misma rond\u00f3 el 210%, y de confirmarse la proyecci\u00f3n mencionada, cerraremos al a\u00f1o con una inflaci\u00f3n acumulada de alrededor 219%, la m\u00e1s alta desde 1990\u2033.<\/p>\n\n\n\n<p>La consultora LCG hace una medici\u00f3n particular de alimentos. &#8220;En la cuarta semana la inflaci\u00f3n de alimentos desaceler\u00f3 4,4 puntos porcentuales respecto a la semana anterior&#8221;, indicaron. En la tercera de diciembre la remarcaci\u00f3n de precios fue de 11,5%, mientras que en la siguiente desaceler\u00f3 hasta 7,1 por ciento. &#8220;La suba promedia 27,1% en las \u00faltimas 4 semanas y 36,1% punta a punta en el mismo per\u00edodo&#8221;, ampliaron.<\/p>\n\n\n\n<p>Seg\u00fan Equilibra, desde el ballotage la nafta subi\u00f3 92%, los medicamentos 52%, cigarrillos 37% y varios productos dentro el programa de Precios Justos entre 40% y 60%<br>La consultora PxQ midi\u00f3 que el IPC de diciembre rondar\u00e1 el 27,3% y calcul\u00f3 cu\u00e1l fue el impacto en las jubilaciones. &#8220;Tomando en cuenta el bono anunciado, la jubilaci\u00f3n m\u00ednima de enero pierde 21,8% de poder adquisitivo contra noviembre (\u00faltimo pico) y 17% si se las compara con su nivel de enero de 2023 (todo esto asumiendo una inflaci\u00f3n de 30% para enero de 2024). La din\u00e1mica del haber m\u00ednimo jubilatorio viene siendo tendencialmente negativa desde septiembre de 2015, con un breve per\u00edodo de recuperaci\u00f3n durante de 2022, para luego sufrir los embates de la aceleraci\u00f3n inflacionaria que tuvo lugar en los \u00faltimos 2 a\u00f1os&#8221;, mencion\u00f3 la consultora que dirige Emmanuel \u00c1lvarez Agis.<\/p>\n\n\n\n<p>La Fundaci\u00f3n Mediterr\u00e1nea hizo ese ejercicio para medir el efecto en los salarios. &#8220;La devaluaci\u00f3n de diciembre de 2023 baj\u00f3 el salario privado formal hasta los 990 d\u00f3lares, si se mide con el tipo de cambio oficial, o 660 d\u00f3lares con el blue. Quiere decir que, actualmente, el salario formal privado en d\u00f3lares resulta 41% menor al de noviembre de 2023, y un 74% inferior a noviembre de 2015\u2033, estim\u00f3.<\/p>\n\n\n\n<p>Y adem\u00e1s, con una mirada hacia adelante, plante\u00f3 un escenario en que, con \u00edndices mensuales como los que se esperan para diciembre y enero, la competitividad cambiaria ganada por la devaluaci\u00f3n ser\u00e1 puesta a prueba. &#8220;Si la inflaci\u00f3n resulta, por ejemplo, del 25% en diciembre y del 20% en enero, ya en febrero algunos tipos de cambio efectivos reales, como trigo, carne, no tradicionales y d\u00f3lar tarjeta, la variaci\u00f3n efectiva podr\u00eda ubicarse en valores negativos&#8221;.<\/p>\n\n\n\n<p>El inicio del 2024 tiene elementos que ofrecer\u00e1n una resistencia a la baja en el ritmo de inflaci\u00f3n. Para Equilibra, &#8220;desde enero se ir\u00e1n sumando otras subas de precios que est\u00e1n atrasados&#8221;, entre las que mencion\u00f3 &#8220;el subte, el colectivo y posiblemente el tren en el AMBA tendr\u00e1n una primera suba de 45% desde el 1\u00b0 de enero y la medicina prepaga subir\u00eda entre 40% y 50% en los pr\u00f3ximos d\u00edas&#8221;, plante\u00f3.<\/p>\n\n\n\n<p>&#8220;En febrero, vendr\u00e1n las subas de electricidad y gas y, en marzo, llegar\u00e1 el turno a las escuelas privadas. En todos estos casos, las correcciones de los atrasos son parciales -luego vendr\u00e1n otras- y, adem\u00e1s, se indexar\u00e1n mensualmente a la inflaci\u00f3n del mes anterior. Con esas subas previstas, es dif\u00edcil pensar que el ajuste del tipo de cambio se mantenga en el 2% mensual m\u00e1s all\u00e1 de enero y, m\u00e1s dif\u00edcil todav\u00eda, que los salarios no comiencen tambi\u00e9n a moverse con alguna f\u00f3rmula de adecuaci\u00f3n mensual que siga a la inflaci\u00f3n pasada&#8221;, indicaron desde la consultora que dirige Mart\u00edn Rapetti.<\/p>\n\n\n\n<p>Invecq, en ese plano, mencion\u00f3 que &#8220;las perspectivas para los pr\u00f3ximos meses tampoco son favorables: la correcci\u00f3n de precios relativos, sin ancla nominal expl\u00edcita, acelerar\u00e1 fuertemente la inflaci\u00f3n mensual. En este sentido, ya se anunciaron aumentos en el transporte p\u00fablico (trenes, colectivos, subtes), medicina prepaga, telecomunicaciones, entre otros&#8221;, coincidi\u00f3.<\/p>\n\n\n\n<p>Por \u00faltimo, Equilibra proyect\u00f3 cu\u00e1l ser\u00e1 la foto m\u00e1s reciente con la que los precios y los salarios llegar\u00e1n al inicio del ciclo lectivo. &#8220;Todos estos elementos nos hacen pensar que para cuando arranquen las clases, la econom\u00eda habr\u00e1 vivido un trimestre con una inflaci\u00f3n mensual promedio en torno a 25% (un total de casi 100% de inflaci\u00f3n en tres meses) y experimentado una ca\u00edda del poder de compra de los salarios superior al 10% en el segmento formal y todav\u00eda mayor en el de los informales&#8221;, asegur\u00f3 en su informe de cierre del 2023.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La devaluaci\u00f3n del tipo de cambio y la liberaci\u00f3n de precios de diciembre prepararon el terreno para un \u00edndice mensual de inflaci\u00f3n que ser\u00e1 r\u00e9cord en m\u00e1s de tres d\u00e9cadas,&hellip; <\/p>\n","protected":false},"author":1,"featured_media":4778,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-115502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/115502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=115502"}],"version-history":[{"count":2,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/115502\/revisions"}],"predecessor-version":[{"id":115516,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/115502\/revisions\/115516"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/4778"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=115502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=115502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=115502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}