{"id":115699,"date":"2024-01-02T15:15:06","date_gmt":"2024-01-02T18:15:06","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=115699"},"modified":"2024-01-02T15:15:18","modified_gmt":"2024-01-02T18:15:18","slug":"el-bitcoin-supera-los-us-45-000-por-primera-vez-en-casi-dos-anos","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/informacion-general\/el-bitcoin-supera-los-us-45-000-por-primera-vez-en-casi-dos-anos\/","title":{"rendered":"El Bitcoin supera los US$ 45.000 por primera vez en casi dos a\u00f1os"},"content":{"rendered":"\n<p>En la madrugada de este martes lleg\u00f3 incluso a un pico de US$ 45.877, el valor m\u00e1s alto desde abril de 2022.<\/p>\n\n\n\n<p>El&nbsp;<strong>Bitcoin,<\/strong>&nbsp;la criptomoneda m\u00e1s utilizada en el mundo, super\u00f3 los&nbsp;<strong>US$<\/strong>&nbsp;<strong>45.000<\/strong>&nbsp;por primera vez en casi dos a\u00f1os, a causa del optimismo por la posible aprobaci\u00f3n por parte de la&nbsp;<strong>Comisi\u00f3n de Bolsa y Valores<\/strong>&nbsp;(SEC) de los primeras fondos cotizados en bolsa (ETF) indexados en criptomonedas.<\/p>\n\n\n\n<p>Este mediod\u00eda cotizaba a alrededor de\u00a0<strong>US$ 45.100\u00a0<\/strong>seg\u00fan el portal Coinmaketcap, con\u00a0<strong>una suba de casi 5,3% en las \u00faltimas 24 horas y de 16% en los \u00faltimos 30 d\u00edas.<\/strong><\/p>\n\n\n\n<p>En la madrugada de hoy lleg\u00f3 incluso a un pico de US$ 45.877, el valor m\u00e1s alto desde abril de 2022. El apetito de los inversores por el Bitcoin se centra en la cuesti\u00f3n regulatoria. El pr\u00f3ximo 10 de enero es la fecha l\u00edmite para que la SEC apruebe los primeros fondos cotizados en Bitcoin, uno de ellos, tramitado por Blackrock.<\/p>\n\n\n\n<p>Esto permitir\u00eda comprar un producto indexado al precio del Bitcoin sin necesidad de comprar la moneda en s\u00ed, lo cual podr\u00eda potenciar el inter\u00e9s entre inversores institucionales de mayor tama\u00f1o.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/media.minutouno.com\/p\/de3626786cbc560bd242d0cb84a5662f\/adjuntos\/150\/imagenes\/039\/217\/0039217815\/bitcoinjpg.jpg\" alt=\"\" title=\"\"\/><\/figure>\n\n\n\n<p>\u201cHay un miedo de algunos &#8216;traders&#8217; de quedarse afuera de la aprobaci\u00f3n y comenzaron a comprar el 1 de enero, la primera cosa que hicieron desde el a\u00f1o nuevo\u201d, manifest\u00f3 Hayden Hughes, cofundador de la plataforma cripto Alpha Impact a la agencia Bloomberg.<\/p>\n\n\n\n<p>Desde el mercado se cree que es poco probable que haya una correcci\u00f3n en el precio en el corto plazo, ya que adem\u00e1s del optimismo que impera por los ETF, hay una expectativa puesta por el proceso de \u201chalving\u201d (reducci\u00f3n a la mitad) en la plataforma del Bitcoin que se dar\u00e1 en abril<\/p>\n\n\n\n<p>Se trata del evento programado en el protocolo que se realiza aproximadamente cada cuatro a\u00f1os, y que reduce a la mitad la cantidad de nuevos bitcoins que los mineros reciben por verificar las transacciones. Este proceso, al reducir y limitar la oferta de nuevas monedas, genera un incentivo a que suban los precios si la demanda se mantiene constante o si sube.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/media.minutouno.com\/p\/75ba57bd0cf2879e8909ceaaa2ea018f\/adjuntos\/150\/imagenes\/039\/316\/0039316588\/610x0\/smart\/210513101022-bitcoin-file-full-169.jpg\" alt=\"\" title=\"\"\/><\/figure>\n\n\n\n<p>Por lo general, los \u00faltimos r\u00e9cords en el precio del Bitcoin se dieron luego de cada uno de los \u201chalvings\u201d: El \u00faltimo de ellos fue en noviembre de 2021 cuando lleg\u00f3 a un pico cercano a los US$ 69.000.<\/p>\n\n\n\n<p>Tras ese r\u00e9cord, el Bitcoin tuvo un 2022 negro en el medio de una crisis que afect\u00f3 a toda la industria y mediante la cual lleg\u00f3 a un piso de casi US$ 15.000.<\/p>\n\n\n\n<p>La aceleraci\u00f3n del valor tambi\u00e9n responde a la posibilidad de que la Reserva Federal (FED) comience este a\u00f1o con los recortes en la tasa de inter\u00e9s luego de llevarlas de niveles cercanos a cero en marzo de 2022 al 5,25% actual, lo cual afect\u00f3 el atractivo del mercado cripto. La entidad monetaria proyecta recortar las tasas este a\u00f1o en tres oportunidades, seg\u00fan sus \u00faltimas proyecciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la madrugada de este martes lleg\u00f3 incluso a un pico de US$ 45.877, el valor m\u00e1s alto desde abril de 2022. El&nbsp;Bitcoin,&nbsp;la criptomoneda m\u00e1s utilizada en el mundo, super\u00f3&hellip; <\/p>\n","protected":false},"author":8,"featured_media":115700,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-115699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/115699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=115699"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/115699\/revisions"}],"predecessor-version":[{"id":115701,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/115699\/revisions\/115701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/115700"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=115699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=115699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=115699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}