{"id":115758,"date":"2024-01-02T20:58:17","date_gmt":"2024-01-02T23:58:17","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=115758"},"modified":"2024-01-03T09:30:52","modified_gmt":"2024-01-03T12:30:52","slug":"con-el-regreso-de-alexis-mac-allister-liverpool-gano-y-es-el-lider-de-la-premier-league-en-el-inicio-del-2024","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/deportes\/con-el-regreso-de-alexis-mac-allister-liverpool-gano-y-es-el-lider-de-la-premier-league-en-el-inicio-del-2024\/","title":{"rendered":"Con el regreso de Alexis Mac Allister, Liverpool gan\u00f3 y es el l\u00edder de la Premier League en el inicio del 2024"},"content":{"rendered":"\n<p>Fue triunfo por 4 a 2 frente al Newcastle como local y el argentino se recuper\u00f3 de su lesi\u00f3n en la rodilla izquierda producto de un corte.<\/p>\n\n\n\n<p>En el inicio del 2024,&nbsp;<strong>Liverpool venci\u00f3 4-2 a Newcastle en lo que fue el regreso de&nbsp;Alexis Mac Allister&nbsp;despu\u00e9s de su lesi\u00f3n y lidera en solitario la tabla de posiciones<\/strong>, con tres puntos de ventaja sobre el segundo,&nbsp;<strong>el Aston Villa de Emiliano Mart\u00ednez<\/strong>&nbsp;en el cierre de la vig\u00e9sima fecha de la Premier League.<\/p>\n\n\n\n<p>El primer tiempo termin\u00f3 0-0, pero tuvo&nbsp;<strong>la anulaci\u00f3n del gol del colombiano Luis D\u00edaz por posici\u00f3n adelantada y la atajada de Martin Dubravka a un penal ejecutado por Mohamed Salah<\/strong>, por lo que la incertidumbre en el marcador estuvo presente.<\/p>\n\n\n\n<p>No obstante, Liverpool fue claramente superior y desperdici\u00f3 varias oportunidades de gol que tuvo tras estos fallos para demostrar una vez m\u00e1s que la pelota no quer\u00eda entrar.<\/p>\n\n\n\n<p>En la segunda mitad,&nbsp;<strong>Salah desat\u00f3 el festejo en Anfield al abrir el marcador con una jugada colectiva brillante, que tuvo la asistencia del uruguayo Darwin N\u00fa\u00f1ez.<\/strong>&nbsp;A pesar de dominar completamente a su rival, Liverpool tuvo que lidiar con la sorpresa de un contraataque que result\u00f3 en el empate 1-1 por parte de Alexander Isak.<\/p>\n\n\n\n<p>La persistencia de Liverpool fue recompensada a los 75 minutos con un gol de Curtis Jones, desatando una seguidilla de anotaciones. Cody Gakpo aument\u00f3 la ventaja a 3-1 gracias a una magn\u00edfica asistencia de tres dedos de Salah.<\/p>\n\n\n\n<p>Sin embargo, Newcastle no se rindi\u00f3 y logr\u00f3 acortar distancias con un cabezazo de Sven Botman en el minuto 81, igualando moment\u00e1neamente el marcador. La emoci\u00f3n alcanz\u00f3 su punto \u00e1lgido cuando, tras un controvertido penal que no fue, Salah sell\u00f3 la victoria 4-2 en el minuto 86.<\/p>\n\n\n\n<p><strong>La entrada de Alexis Mac Allister para los \u00faltimos 20 minutos result\u00f3 crucial, participando en la jugada que llev\u00f3 al cuarto gol.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fue triunfo por 4 a 2 frente al Newcastle como local y el argentino se recuper\u00f3 de su lesi\u00f3n en la rodilla izquierda producto de un corte. En el inicio&hellip; <\/p>\n","protected":false},"author":4,"featured_media":115760,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,4],"tags":[],"class_list":["post-115758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-deportes"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/115758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=115758"}],"version-history":[{"count":2,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/115758\/revisions"}],"predecessor-version":[{"id":115849,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/115758\/revisions\/115849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/115760"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=115758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=115758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=115758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}