{"id":126459,"date":"2024-02-18T20:52:29","date_gmt":"2024-02-18T23:52:29","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=126459"},"modified":"2024-02-18T20:52:33","modified_gmt":"2024-02-18T23:52:33","slug":"lionel-messi-sorprendio-a-un-emprendedor-con-un-pedido-y-se-volvio-viral","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/informacion-general\/lionel-messi-sorprendio-a-un-emprendedor-con-un-pedido-y-se-volvio-viral\/","title":{"rendered":"Lionel Messi sorprendi\u00f3 a un emprendedor con un pedido y se volvi\u00f3 viral."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El capit\u00e1n de la Selecci\u00f3n Argentina, en una nueva muestra de sencillez, le escribi\u00f3 desde su cuenta de Instagram a un emprendimiento y la historia explot\u00f3 en Internet.<\/h2>\n\n\n\n<p>La im\u00e1gen de Lionel Messi crece cada vez m\u00e1s en su exitosa carrera pero lo que sigue sorprendiendo en el paso de los a\u00f1os es con la sencillez que se maneja siendo el mejor futbolista de todos los tiempos. Tranquilo, con perfil bajo y una humildad enorme, el 10 tuvo una nueva muestra que sorprendi\u00f3 a todos y la historia se volvi\u00f3 viral en las redes sociales.<\/p>\n\n\n\n<p>El capit\u00e1n de la Selecci\u00f3n Argentina le pidi\u00f3 hace algunas semanas una parrilla a un emprendimiento de argentinos directamente desde su cuenta de Instagram y en las \u00faltimas horas sali\u00f3 a la luz el chat que mantuvo el futbolsita con un trabajador que guardar\u00e1 ese recuerdo para toda la vida.<\/p>\n\n\n\n<p>&#8220;Hola, hace poco un amigo te compr\u00f3 una parrilla y se la mandaste ac\u00e1 a Miami. Quer\u00eda ver si te pod\u00eda pedir otra, una m\u00e1s grande y mandarla al mismo lugar&#8221;, fue el mensaje que lleg\u00f3 a la cuenta del emprendimiento &#8220;Laboratorio de Hierro&#8221;, que fabrica parrillas en San Miguel, provincia de Buenos Aires.<\/p>\n\n\n\n<p>Por esta raz\u00f3n desde el emprendimiento decidieron, c\u00f3mo amerita la situaci\u00f3n, realizarle un modelo desde 0 a Lionel Messi y, ahora, aparece en los cat\u00e1logos para que las personas puedan tener la misma parrilla que pidi\u00f3 el 10.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">EL MENSAJE COMPLETO DEL EMPRENDIMIENTO EN SUS REDES<\/h3>\n\n\n\n<p>&#8220;El 10 de diciembre de 2023, recibimos un mensaje que nos llen\u00f3 de alegr\u00eda y emoci\u00f3n. Nada menos que Leo Messi nos escribi\u00f3 por Instagram para expresar su inter\u00e9s en adquirir una de nuestras parrillas LaboHierro.<\/p>\n\n\n\n<p>Como fan\u00e1ticos del f\u00fatbol y admiradores del talento de Messi, est\u00e1bamos emocionados de tenerlo como cliente. Despu\u00e9s de todo, \u00e9l no solo es uno de los mejores jugadores de todos los tiempos, sino tambi\u00e9n un verdadero amante del asado, al igual que nosotros.<\/p>\n\n\n\n<p>Fue entonces cuando surgi\u00f3 la idea de hacer algo especial en su honor. Decidimos crear una parrilla \u00fanica, inspirada en su legado y pasi\u00f3n por el f\u00fatbol y el asado.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.diarioepoca.com\/content\/bucket\/5\/1347825w762h762c.webp.webp\" alt=\"\"\/><\/figure>\n\n\n\n<p>As\u00ed naci\u00f3 \u00abLa Parrilla del Capit\u00e1n\u00bb de LaboHierro. Dise\u00f1ada con los mejores materiales y cuidadosamente elaborada para reflejar la grandeza y la elegancia del propio Messi, esta parrilla es verdaderamente especial. Desde su dise\u00f1o innovador hasta sus caracter\u00edsticas de alto rendimiento, \u00abLa Parrilla del Capit\u00e1n\u00bb representa lo mejor de LaboHierro y rinde homenaje a un \u00edcono del deporte mundial.<\/p>\n\n\n\n<p>Para nosotros, la historia de Leo Messi uni\u00e9ndose a la familia LaboHierro es m\u00e1s que una transacci\u00f3n comercial. Es un testimonio de nuestra pasi\u00f3n compartida por el asado y la excelencia en todo lo que hacemos. Estamos orgullosos de tener a Messi como parte de nuestra comunidad y esperamos que \u00abLa Parrilla del Capit\u00e1n\u00bb le traiga tantas alegr\u00edas como las que nos ha tra\u00eddo a nosotros.<\/p>\n\n\n\n<p>Unite a nosotros en el emocionante viaje de LaboHierro y descubre por qu\u00e9 Messi y tantos otros eligen nuestras parrillas para sus momentos m\u00e1s especiales alrededor de la parrilla. Porque en LaboHierro, no solo hacemos parrillas, creamos experiencias inolvidables&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El capit\u00e1n de la Selecci\u00f3n Argentina, en una nueva muestra de sencillez, le escribi\u00f3 desde su cuenta de Instagram a un emprendimiento y la historia explot\u00f3 en Internet. La im\u00e1gen&hellip; <\/p>\n","protected":false},"author":6,"featured_media":126460,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-126459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/126459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=126459"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/126459\/revisions"}],"predecessor-version":[{"id":126461,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/126459\/revisions\/126461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/126460"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=126459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=126459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=126459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}