{"id":135299,"date":"2024-03-24T19:04:24","date_gmt":"2024-03-24T22:04:24","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=135299"},"modified":"2024-03-24T19:04:35","modified_gmt":"2024-03-24T22:04:35","slug":"un-joven-de-19-anos-choco-con-su-moto-y-fallecio","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/policiales\/un-joven-de-19-anos-choco-con-su-moto-y-fallecio\/","title":{"rendered":"Un joven de 19 a\u00f1os choc\u00f3 con su moto y falleci\u00f3."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Joel N\u00fa\u00f1ez, un joven de 19 a\u00f1os de edad que se accident\u00f3 a bordo de su motocicleta durante la madrugada de este domingo en Resistencia, sufri\u00f3 traumatismo de cr\u00e1neo y muri\u00f3 en el lugar donde ocurri\u00f3 el hecho. Su acompa\u00f1ante sali\u00f3 ilesa.<\/h2>\n\n\n\n<p>En la madrugada de hoy, alrededor de las 6 de la ma\u00f1ana, se registr\u00f3\u00a0<strong>un accidente fatal en la calle Necochea al 1450 de la ciudad de Resistencia<\/strong>, provincia de Chaco.<\/p>\n\n\n\n<p>Seg\u00fan informes policiales, personal de la Comisar\u00eda Tercera se dirigi\u00f3 al lugar tras recibir un reporte sobre el siniestro, en el que\u00a0<strong>dos personas aparentemente resultaron heridas<\/strong>.<\/p>\n\n\n\n<p>Al llegar, los agentes encontraron a&nbsp;<strong>Joel N\u00fa\u00f1ez, de 19 a\u00f1os, quien conduc\u00eda una motocicleta de 110 cc, tendido en la calle junto a su acompa\u00f1ante, una joven de 24 a\u00f1os.<\/strong>&nbsp;Hasta el momento, los motivos del accidente no han sido esclarecidos ni divulgados por la Polic\u00eda.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2024-03-24\/701823.png\"><img decoding=\"async\" src=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2024-03-24\/701823.png_nota.png\" alt=\"\"\/><\/a><\/figure>\n\n\n\n<p>Una ambulancia lleg\u00f3 poco despu\u00e9s y examin\u00f3 a ambos j\u00f3venes. Lamentablemente,\u00a0<strong>se confirm\u00f3 que Joel hab\u00eda fallecido y se le diagnostic\u00f3 un\u00a0&#8220;traumatismo de base de cr\u00e1neo&#8221;<\/strong>. En cuanto a la joven, se inform\u00f3 que sufri\u00f3 &#8220;hipoglucemia&#8221; pero no sufri\u00f3 lesiones f\u00edsicas.<\/p>\n\n\n\n<p><em>Fuente: Con informaci\u00f3n de Diario Chaco.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Joel N\u00fa\u00f1ez, un joven de 19 a\u00f1os de edad que se accident\u00f3 a bordo de su motocicleta durante la madrugada de este domingo en Resistencia, sufri\u00f3 traumatismo de cr\u00e1neo y&hellip; <\/p>\n","protected":false},"author":6,"featured_media":135304,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-135299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/135299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=135299"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/135299\/revisions"}],"predecessor-version":[{"id":135306,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/135299\/revisions\/135306"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/135304"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=135299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=135299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=135299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}