{"id":136477,"date":"2024-03-28T17:47:24","date_gmt":"2024-03-28T20:47:24","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=136477"},"modified":"2024-03-28T17:47:36","modified_gmt":"2024-03-28T20:47:36","slug":"luis-ventura-anuncio-que-morena-rial-esta-embarazada","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/espectaculos\/luis-ventura-anuncio-que-morena-rial-esta-embarazada\/","title":{"rendered":"Luis Ventura anunci\u00f3 que Morena Rial est\u00e1 embarazada."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Durante una comunicaci\u00f3n telef\u00f3nica, la influencer le revel\u00f3 la noticia al periodista Luis Ventura.<\/h2>\n\n\n\n<p><strong>Luis Ventura anunci\u00f3 que\u00a0Morena Rial\u00a0est\u00e1 embarazada de su segundo hijo.<\/strong><\/p>\n\n\n\n<p>De acuerdo con la informaci\u00f3n que dio el periodista, a quien la hija de Jorge Rial considera un t\u00edo,<strong>\u00a0est\u00e1 en el tercer mes de gestaci\u00f3n y su familia ya lo sabe.<\/strong><\/p>\n\n\n\n<p>\u201c\u00bfQui\u00e9n es el padre?\u201d, pregunt\u00f3 el panelista Diego Esteves. \u201c<strong>No s\u00e9 ni me interesa<\/strong>, \u00bfsab\u00e9s por qu\u00e9? porque lo tengo que bendecir igual, porque forma parte de su realidad y la voy a acompa\u00f1ar\u201d, respondi\u00f3 contundente Ventura.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/tn.com.ar\/resizer\/micW1AeeF_6trPRY-7nh-WYEBQ0=\/767x0\/smart\/filters:format(webp)\/cloudfront-us-east-1.images.arcpublishing.com\/artear\/33GIWR4LGVGMVFOUCAS4PRFGFE.png\" alt=\"Morena Rial junto a su hijo Francesco (Foto: captura Instagram\/morerialok)\"\/><figcaption class=\"wp-element-caption\">Morena Rial junto a su hijo Francesco (Foto: captura Instagram\/morerialok)<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">C\u00f3mo fue la charla en la que Morena Rial le cont\u00f3 a Luis Ventura de su embarazo<\/h2>\n\n\n\n<p>Morena, quien ya es madre de Francesco,<strong>&nbsp;llam\u00f3 al conductor de&nbsp;<\/strong><em><strong>Secretos verdaderos (Am\u00e9rica)<\/strong><\/em><strong>&nbsp;para contarle de su embarazo<\/strong>.<\/p>\n\n\n\n<p>\u201cHace poco m\u00e1s de un mes ella me llam\u00f3 por tel\u00e9fono y me dijo:&nbsp;<strong>\u2018T\u00edo, estoy embarazada. Por ahora no lo voy a decir porque quiero estar segura, quiero ver c\u00f3mo se va desarrollando<\/strong>\u2019\u201d, dijo Ventura.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/tn.com.ar\/resizer\/gzMi8jnRpyFqC7hDGCEagQxFKeY=\/767x0\/smart\/filters:format(webp)\/cloudfront-us-east-1.images.arcpublishing.com\/artear\/SJZADNTALNC6ZGXBIZ373AYDPI.jpg\" alt=\"Luis Ventura tiene una relaci\u00f3n muy cercana con Morena Rial (Foto: captura Am\u00e9rica)\"\/><figcaption class=\"wp-element-caption\">Luis Ventura tiene una relaci\u00f3n muy cercana con Morena Rial (Foto: captura Am\u00e9rica)<\/figcaption><\/figure>\n\n\n\n<p>El presidente de APTRA dio m\u00e1s detalles de la charla con la medi\u00e1tica: \u201c<strong>Hablamos de eso, hablamos de Francesco, que ahora cumpli\u00f3 un aniversario de bautismo<\/strong>, hablamos de c\u00f3mo va sorteando las dificultades que va teniendo en la vida, la manera de encontrar una vivienda como corresponde&#8230;\u201d.<\/p>\n\n\n\n<p>Y cerr\u00f3: \u201cAhora est\u00e1 en Buenos Aires, se est\u00e1 yendo para C\u00f3rdoba en las pr\u00f3ximas horas\u201d.<\/p>\n\n\n\n<p>Adem\u00e1s, Ventura dijo que no sabe el sexo del beb\u00e9 porque no se lo pregunt\u00f3 a Morena.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qui\u00e9n ser\u00eda el padre del hijo que est\u00e1 esperando Morena Rial<\/h2>\n\n\n\n<p><strong>Morena Rial\u00a0<\/strong>volvi\u00f3 a sonre\u00edr\u00a0despu\u00e9s de varios meses a puros disgustos.\u00a0<strong>Se puso de novia con un boxeador<\/strong>\u00a0y est\u00e1 completamente enamorada, y tambi\u00e9n dispuesta a jug\u00e1rsela al m\u00e1ximo para que todo prospere.<\/p>\n\n\n\n<p>El hombre que le rob\u00f3 el coraz\u00f3n se llama Mat\u00edas, y ser\u00eda el padre del segundo hijo de Morena.<\/p>\n\n\n\n<p>En las \u00faltimas semanas apareci\u00f3 la primera foto en la que se los ve juntos, aunque es bastante subida de tono.<\/p>\n\n\n\n<p>La imagen, publicada por&nbsp;<em>Ciudad Magazine,&nbsp;<\/em>los muestra recostados sobre un sof\u00e1. Y si bien \u00e9l aparece con una remera negra con una estampa en verde,&nbsp;<strong>ella pos\u00f3 con un corpi\u00f1o de encaje y mostr\u00f3 de m\u00e1s<\/strong>. La postal hizo que muchos usuarios recordaran aquella que se sac\u00f3 en 2017 con su primer novio, Mart\u00edn Casar, en baby doll.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/tn.com.ar\/resizer\/cClih-EWmo0_3WJcecn55GmesIw=\/767x0\/smart\/filters:format(webp)\/cloudfront-us-east-1.images.arcpublishing.com\/artear\/33QVTUEXXNGF5BHCVIB56C2J24.jpg\" alt=\"Morena Rial y su novio boxeador. (Foto: Ciudad Magazine)\"\/><figcaption class=\"wp-element-caption\">Morena Rial y su novio boxeador. (Foto: Ciudad Magazine)<\/figcaption><\/figure>\n\n\n\n<p>Sobre este romance, la medi\u00e1tica expres\u00f3: \u201cA Mat\u00edas lo conoc\u00ed por medio de un amigo. Es boxeador y se est\u00e1 preparando para ser profesional.\u00a0<strong>Lo vi boxear, es muy bueno en lo que hace, y es dif\u00edcil de tirar.\u00a0<\/strong>A m\u00ed mucho el boxeo no me gusta, pero lo acompa\u00f1o. Me da impresi\u00f3n\u201d. La joven reconoci\u00f3 que por ahora ni piensa en casarse, ya que no cree en los papeles. Por \u00faltimo, expuso su felicidad por lo bien que el chico se lleva con Francesco Benicio, su hijo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><em>Fuente: Todo Noticias.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante una comunicaci\u00f3n telef\u00f3nica, la influencer le revel\u00f3 la noticia al periodista Luis Ventura. Luis Ventura anunci\u00f3 que\u00a0Morena Rial\u00a0est\u00e1 embarazada de su segundo hijo. De acuerdo con la informaci\u00f3n que&hellip; <\/p>\n","protected":false},"author":6,"featured_media":136479,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-136477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/136477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=136477"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/136477\/revisions"}],"predecessor-version":[{"id":136481,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/136477\/revisions\/136481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/136479"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=136477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=136477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=136477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}