{"id":136640,"date":"2024-03-29T17:55:24","date_gmt":"2024-03-29T20:55:24","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=136640"},"modified":"2024-03-29T17:55:36","modified_gmt":"2024-03-29T20:55:36","slug":"dos-personas-fueron-detenidas-en-operativos-antidroga","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/policiales\/dos-personas-fueron-detenidas-en-operativos-antidroga\/","title":{"rendered":"Dos personas fueron detenidas en operativos antidroga."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La Polic\u00eda de Chaco arrest\u00f3 a una mujer y un hombre en la ciudad de S\u00e1enz Pe\u00f1a y Quitilipi respectivamente por cargar con cocina y marihuana. En el primer caso, tambi\u00e9n se confiscaron m\u00e1s de 190 mil pesos.<\/h2>\n\n\n\n<p>En dos operativos policiales llevados a cabo este mi\u00e9rcoles en las localidades chaque\u00f1as de Roque S\u00e1enz Pe\u00f1a y Quitilipi, fueron detenidas dos personas por posesi\u00f3n de drogas.<\/p>\n\n\n\n<p>El primer procedimiento se realiz\u00f3 ayer por la tarde, cuando los efectivos de la Divisi\u00f3n Microgr\u00e1fico Interior y la Divisi\u00f3n Interior Presidencia Roque S\u00e1enz Pe\u00f1a, con la colaboraci\u00f3n de un ayudante, allanaron una vivienda en la calle Belgrano del barrio Municipal de dicha localidad.&nbsp;<\/p>\n\n\n\n<p>Durante la inspecci\u00f3n del lugar, se incautaron 27 envoltorios de nylon conteniendo un total de 7,02 gramos de coca\u00edna, adem\u00e1s de la suma de $191.430 en efectivo. Tambi\u00e9n se encontraron una motosierra, un compresor de aire y un microondas de origen dudoso. En el operativo, fue detenida una joven de 25 a\u00f1os.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2024-03-29\/905852.jpg\"><img decoding=\"async\" src=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2024-03-29\/905852.jpg_nota.jpg\" alt=\"\"\/><\/a><\/figure>\n\n\n\n<p>El segundo procedimiento tuvo lugar aproximadamente cerca de las 20, cuando los agentes policiales realizaban tareas de prevenci\u00f3n en la ciudad de Quitilipi.<\/p>\n\n\n\n<p>Durante la patrulla en la avenida Juan Domingo Per\u00f3n, cerca de la intersecci\u00f3n con la ruta provincial N\u00b04, detuvieron a un hombre de 30 a\u00f1os y encontraron en su posesi\u00f3n dos envoltorios transparentes con sustancias sospechosas. Tras las pruebas de campo correspondientes, se determin\u00f3 que uno conten\u00eda 66 gramos de coca\u00edna y en el otro, 26 gramos de marihuana.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2024-03-29\/637205.jpg\"><img decoding=\"async\" src=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2024-03-29\/637205.jpg_nota.jpg\" alt=\"\"\/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2024-03-29\/824968.jpg\"><img decoding=\"async\" src=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2024-03-29\/824968.jpg_nota.jpg\" alt=\"\"\/><\/a><\/figure>\n\n\n\n<p>Ambos sospechosos fueron notificados de su detenci\u00f3n y llevados ante las comisar\u00edas de sus respectivos distritos. Las investigaciones contin\u00faan a cargo de la Fiscal\u00eda de Investigaci\u00f3n Antidrogas N\u00b0 2.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Polic\u00eda de Chaco arrest\u00f3 a una mujer y un hombre en la ciudad de S\u00e1enz Pe\u00f1a y Quitilipi respectivamente por cargar con cocina y marihuana. En el primer caso,&hellip; <\/p>\n","protected":false},"author":6,"featured_media":136645,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-136640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/136640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=136640"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/136640\/revisions"}],"predecessor-version":[{"id":136646,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/136640\/revisions\/136646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/136645"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=136640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=136640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=136640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}