{"id":136647,"date":"2024-03-29T18:23:03","date_gmt":"2024-03-29T21:23:03","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=136647"},"modified":"2024-03-29T18:23:46","modified_gmt":"2024-03-29T21:23:46","slug":"viernes-santo-la-pasion-y-muerte-del-senor-fue-conmemorada-por-los-fieles-en-la-catedral","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/informacion-general\/viernes-santo-la-pasion-y-muerte-del-senor-fue-conmemorada-por-los-fieles-en-la-catedral\/","title":{"rendered":"Viernes Santo: la Pasi\u00f3n y Muerte del Se\u00f1or fue conmemorada por los fieles en la Catedral."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">En horas de la siesta, se celebr\u00f3 la Pasi\u00f3n y Muerte de nuestro Se\u00f1or Jesucristo en la Iglesia Catedral.<\/h2>\n\n\n\n<p>La Iglesia Cat\u00f3lica se une este Viernes Santo en esp\u00edritu de duelo y penitencia para conmemorar la Pasi\u00f3n y Muerte del Se\u00f1or. Las distintas comunidades realizan el tradicional V\u00eda Crucis y contemplan la Cruz de Jes\u00fas.<\/p>\n\n\n\n<p>La liturgia depara momentos intensos en los que se profundiza el misterio del sacrificio de Cristo. En todo el mundo se reza el V\u00eda Crucis, se escucha el Serm\u00f3n de las Siete Palabras del Se\u00f1or Jes\u00fas en la Cruz y se realizan procesiones presididas por la imagen de Cristo sufriente y de su Madre Dolorosa.<\/p>\n\n\n\n<p>En este d\u00eda no se celebra la Santa Eucarist\u00eda ni ning\u00fan otro sacramento, a excepci\u00f3n del Sacramento de la Reconciliaci\u00f3n y la Unci\u00f3n de los Enfermos (en caso de necesidad).<\/p>\n\n\n\n<p>&nbsp; &#8220;Puede haber una postura de la cruz que aplasta. Puede haber una postura de la cruz que se mira de lejos con curiosidad. Y puede haber una postura que se asume, es la de Mar\u00eda, serena y fuerte&#8221;, beato Eduardo Pironio.<\/p>\n\n\n\n<p>La Pasi\u00f3n inici\u00f3 minutos antes de las 15.&nbsp;<\/p>\n\n\n\n<p>Esta previsto que a las 21 se realice en la Plaza Cabral, el V\u00eda Crucis Viviente.<\/p>\n\n\n\n<p>Por la ma\u00f1ana, a las 10 se realiz\u00f3\u00a0el V\u00eda Crucis de las familias organizado por la Pastoral Vocacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En horas de la siesta, se celebr\u00f3 la Pasi\u00f3n y Muerte de nuestro Se\u00f1or Jesucristo en la Iglesia Catedral. La Iglesia Cat\u00f3lica se une este Viernes Santo en esp\u00edritu de&hellip; <\/p>\n","protected":false},"author":6,"featured_media":136653,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-136647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/136647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=136647"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/136647\/revisions"}],"predecessor-version":[{"id":136651,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/136647\/revisions\/136651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/136653"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=136647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=136647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=136647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}