{"id":140193,"date":"2024-04-15T08:19:47","date_gmt":"2024-04-15T11:19:47","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=140193"},"modified":"2024-04-15T08:19:59","modified_gmt":"2024-04-15T11:19:59","slug":"la-ucr-de-corrientes-se-suma-a-la-marcha-federal-universitaria","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/actualidad\/la-ucr-de-corrientes-se-suma-a-la-marcha-federal-universitaria\/","title":{"rendered":"La UCR de Corrientes se suma a la Marcha Federal Universitaria"},"content":{"rendered":"\n<p>Asimismo sostiene que &#8220;en este sentido, nos sumamos a la convocatoria de la Marcha Federal Universitaria del pr\u00f3ximo 23 de abril, donde expresaremos nuestro apoyo y respaldo a la Universidad Nacional del Nordeste y a todas las instituciones de educaci\u00f3n superior afectadas por los recortes presupuestarios impuestos por el Gobierno.<\/p>\n\n\n\n<p>&#8220;Las universidades p\u00fablicas son espacios de formaci\u00f3n acad\u00e9mica, investigaci\u00f3n y generaci\u00f3n de conocimiento que brindan oportunidades de crecimiento y desarrollo a miles de estudiantes. Sin embargo, la grave decisi\u00f3n de llevar adelante ajustes presupuestarios sin precedentes pone en riesgo el normal funcionamiento de estas instituciones y limita las posibilidades de acceso a una educaci\u00f3n de calidad&#8221;, indican en otro tramo del escrito difundido.&nbsp;<\/p>\n\n\n\n<p>&#8220;Entendemos que es fundamental lograr un equilibrio fiscal y trabajar por un Estado eficiente, pero subrayamos que la inversi\u00f3n en educaci\u00f3n superior es un pilar imprescindible para alcanzar el crecimiento sostenible que nuestro pa\u00eds tanto necesita. Cualquier detrimento al sistema universitario no solo afecta a los estudiantes y docentes, sino que tambi\u00e9n compromete el avance cient\u00edfico, tecnol\u00f3gico y cultural de toda la naci\u00f3n&#8221;.<\/p>\n\n\n\n<p>Finalemnte reiteraron &#8220;la UCR Corrientes reafirma su compromiso hist\u00f3rico con la educaci\u00f3n p\u00fablica y ratifica su convicci\u00f3n de que invertir en conocimiento es invertir en el futuro de nuestra sociedad. Luchemos juntos por la defensa de nuestras universidades y por una Argentina que valora y promueve la educaci\u00f3n como motor de desarrollo y progreso&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asimismo sostiene que &#8220;en este sentido, nos sumamos a la convocatoria de la Marcha Federal Universitaria del pr\u00f3ximo 23 de abril, donde expresaremos nuestro apoyo y respaldo a la Universidad&hellip; <\/p>\n","protected":false},"author":12,"featured_media":140202,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-140193","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/140193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=140193"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/140193\/revisions"}],"predecessor-version":[{"id":140203,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/140193\/revisions\/140203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/140202"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=140193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=140193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=140193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}