{"id":141820,"date":"2024-04-21T19:56:44","date_gmt":"2024-04-21T22:56:44","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=141820"},"modified":"2024-04-21T19:56:45","modified_gmt":"2024-04-21T22:56:45","slug":"guillermo-francos-afirmo-que-el-gobierno-retomara-la-obra-publica","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/politica\/guillermo-francos-afirmo-que-el-gobierno-retomara-la-obra-publica\/","title":{"rendered":"Guillermo Francos afirm\u00f3 que el Gobierno retomar\u00e1 la obra p\u00fablica."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Guillermo Francos se\u00f1al\u00f3 que los gobernadores de la Regi\u00f3n Centro le plantearon sus inquietudes respecto de la reactivaci\u00f3n de las obras p\u00fablicas.<\/h2>\n\n\n\n<p>El ministro del Interior, Guillermo Francos, anunci\u00f3 el reinicio de obras p\u00fablicas que hab\u00edan sido detenidas, respondiendo as\u00ed a una demanda constante de los gobernadores provinciales.<\/p>\n\n\n\n<p>En declaraciones radiales, Francos destac\u00f3 la importancia de la infraestructura en Argentina y reconoci\u00f3 que, a pesar de las inversiones pasadas, el pa\u00eds a\u00fan enfrenta carencias significativas en este \u00e1mbito.<\/p>\n\n\n\n<p>El funcionario mencion\u00f3 su reciente encuentro con gobernadores de la Regi\u00f3n Centro, donde se abordaron preocupaciones sobre la reactivaci\u00f3n de obras de infraestructura.&nbsp;<\/p>\n\n\n\n<p>Francos explic\u00f3 que el gobierno cuenta con una lista de m\u00e1s de 5.000 proyectos p\u00fablicos en el pa\u00eds, y que se est\u00e1n priorizando aquellos que est\u00e1n cerca de su finalizaci\u00f3n.<\/p>\n\n\n\n<p><em><strong>\u201cEs un pensamiento que algunos gobernadores tienen y yo los respeto, pero, a esta altura de los acontecimientos de la Argentina, lo que hay que mirar es la cantidad de plata que tienen los bancos\u201d<\/strong><\/em>, afirm\u00f3.<\/p>\n\n\n\n<p>Y agreg\u00f3:&nbsp;<strong><em>\u201cLos bancos tienen una cantidad de fondos disponibles para prestar y ahora que est\u00e1 bajando la tasa, y que el Estado no les toma m\u00e1s plata, va a haber una monta\u00f1a de dinero disponible que los bancos se van a ver necesitados de colocar\u201d<\/em><\/strong>.&nbsp;<em><strong>\u201cEse va a ser el gran motor del crecimiento de la Argentina\u201d<\/strong><\/em>, detall\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Guillermo Francos se\u00f1al\u00f3 que los gobernadores de la Regi\u00f3n Centro le plantearon sus inquietudes respecto de la reactivaci\u00f3n de las obras p\u00fablicas. El ministro del Interior, Guillermo Francos, anunci\u00f3 el&hellip; <\/p>\n","protected":false},"author":6,"featured_media":141823,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-141820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/141820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=141820"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/141820\/revisions"}],"predecessor-version":[{"id":141825,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/141820\/revisions\/141825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/141823"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=141820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=141820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=141820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}