{"id":141838,"date":"2024-04-21T20:38:34","date_gmt":"2024-04-21T23:38:34","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=141838"},"modified":"2024-04-21T20:38:38","modified_gmt":"2024-04-21T23:38:38","slug":"un-jugador-de-las-inferiores-de-defensores-de-cambaceres-se-descompenso-y-murio-durante-un-partido","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/deportes\/un-jugador-de-las-inferiores-de-defensores-de-cambaceres-se-descompenso-y-murio-durante-un-partido\/","title":{"rendered":"Un jugador de las inferiores de Defensores de Cambaceres se descompens\u00f3 y muri\u00f3 durante un partido."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Tiago Benjam\u00edn Cricenti ten\u00eda 16 a\u00f1os. El chico fue trasladado por su padre al Hospital Horacio Cestino, donde falleci\u00f3.<\/h2>\n\n\n\n<p><strong>Tiago Benjam\u00edn Cricenti<\/strong>, de 16 a\u00f1os, se descompens\u00f3 este domingo mientras disputaba un partido de la S\u00e9ptima divisi\u00f3n del club\u00a0<strong>Defensores de Cambaceres\u00a0<\/strong>contra General Lamadrid y falleci\u00f3 en el\u00a0<strong>Hospital Horacio Cestino<\/strong>, del partido de\u00a0<strong>Ensenada<\/strong>, al que hab\u00eda sido trasladado por su padre, informaron fuentes oficiales.<\/p>\n\n\n\n<p>\u201cEl Club Defensores de Cambaceres&nbsp;<strong>lamenta informar el fallecimiento del jugador Tiago Benjam\u00edn Cricenti&nbsp;<\/strong>de la s\u00e9ptima categor\u00eda, quien sufri\u00f3 una descompensaci\u00f3n durante el partido de hoy\u201d, poste\u00f3 la instituci\u00f3n sobre la tragedia durante el encuentro ante General Lamadrid y&nbsp;<strong>decret\u00f3 un duelo hasta el mi\u00e9rcoles<\/strong>.<\/p>\n\n\n\n<p>\u201cAgradecemos al personal del Hospital Horacio Cestino por los esfuerzos brindados. Acompa\u00f1amos a su familia, compa\u00f1eros de equipo, t\u00e9cnicos, amigos y dem\u00e1s allegados en este dif\u00edcil momento\u201d, a\u00f1adi\u00f3 en el posteo el club.<\/p>\n\n\n\n<p>Tiago, que era mediocampista, se descompens\u00f3 durante el segundo tiempo. Seg\u00fan public\u00f3 el portal&nbsp;<em>El D\u00eda<\/em>, el juvenil fue asistido por los auxiliares que estaban en el banco de suplentes, quienes lo llevaron hasta el borde de la cancha.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"774\" width=\"659\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/sAjgpXcuP9p8xsv4WETe5ryx444=\/420x560\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ZHDTSHSTD5BI7MPDGDRBNWE5FE.png 420w,https:\/\/www.infobae.com\/new-resizer\/-L17vtjTv-PowY7RAi9FWBGFWg0=\/768x1024\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ZHDTSHSTD5BI7MPDGDRBNWE5FE.png 768w,https:\/\/www.infobae.com\/new-resizer\/ez4v0KUYmhBWgoWBBO--32aL2So=\/992x1323\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ZHDTSHSTD5BI7MPDGDRBNWE5FE.png 992w,https:\/\/www.infobae.com\/new-resizer\/bVehmV2bG8P7Vh4N_OfUnip5_SI=\/1200x1600\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ZHDTSHSTD5BI7MPDGDRBNWE5FE.png 1200w\" class=\"\" src=\"https:\/\/www.infobae.com\/new-resizer\/sAjgpXcuP9p8xsv4WETe5ryx444=\/420x560\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ZHDTSHSTD5BI7MPDGDRBNWE5FE.png%20420w\" alt=\"El posteo de Defensores de Cambaceres en redes\"><\/p>\n\n\n\n<p>El posteo de Defensores de Cambaceres en redes<\/p>\n\n\n\n<p>Un testigo afirm\u00f3 a ese mismo sitio web que\u00a0<strong>Tiago fue luego trasladado \u201cen camilla hacia un veh\u00edculo particular\u201d<\/strong>\u00a0y que desde la tribuna \u201ccomenzaron a gritar para que lo lleven al hospital\u201d porque \u201cen la cancha no hab\u00eda ambulancia\u201d.<\/p>\n\n\n\n<p>Seg\u00fan pudo saber este medio de fuentes oficiales, \u201cel padre se lo llev\u00f3 directamente al hospital;&nbsp;<strong>se hicieron todos los trabajos en urgencia, pero entr\u00f3 en paro card\u00edaco&nbsp;<\/strong>yfalleci\u00f3 a los pocos minutos<strong>&nbsp;a pesar de las maniobras de reanimaci\u00f3n&nbsp;<\/strong>que se le practicaron\u201d. Y agregaron que \u201cel chico ten\u00eda todos los estudios correspondientes para poder jugar en AFA\u201d.<\/p>\n\n\n\n<p>Tambi\u00e9n dijeron que se aguarda el resultado de la&nbsp;<strong>autopsia&nbsp;<\/strong>para establecer las causas del fallecimiento del deportista que hab\u00eda nacido el 10 de enero de 2008, se hab\u00eda formado en Ringuelet y era fana de Estudiante de La Plata: su \u00faltimo posteo en las historias de Instagram fue el triunfo del Pincha 3 a 0 de este s\u00e1bado ante Barracas Central.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"355\" width=\"488\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/2Uv3UUqqOLNachZctnAuSbiSt7A=\/420x315\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/UF5NR7T3MNDG3CTDOFUHXIKKUU.png 420w,https:\/\/www.infobae.com\/new-resizer\/2X6YJfGj5vipnBCnfhXamozeuoU=\/768x576\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/UF5NR7T3MNDG3CTDOFUHXIKKUU.png 768w,https:\/\/www.infobae.com\/new-resizer\/LJohVeoQEaTjebW2XWFGZF7U330=\/992x744\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/UF5NR7T3MNDG3CTDOFUHXIKKUU.png 992w,https:\/\/www.infobae.com\/new-resizer\/NJC63uLRtP10XjsU1uv5ESoKh1k=\/1200x900\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/UF5NR7T3MNDG3CTDOFUHXIKKUU.png 1200w,https:\/\/www.infobae.com\/new-resizer\/pBR9gH1wHLFjXO5ueJNxoLYgAXw=\/1440x1080\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/UF5NR7T3MNDG3CTDOFUHXIKKUU.png 1440w\" class=\"\" src=\"https:\/\/www.infobae.com\/new-resizer\/2Uv3UUqqOLNachZctnAuSbiSt7A=\/420x315\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/UF5NR7T3MNDG3CTDOFUHXIKKUU.png%20420w\" alt=\"El comunicado del club\"><\/p>\n\n\n\n<p>El comunicado del club<\/p>\n\n\n\n<p>Justamente, en esa red social, Tiago mostraba im\u00e1genes de su paso por Ringuelet, club del que se fue a fines de 2023 para sumarse a Cambaceres. El 9 de diciembre, les escribi\u00f3 a sus compa\u00f1eros y subi\u00f3 una foto del equipo. \u201cHoy, \u00faltimo partido con este grupo hermoso.&nbsp;<strong>Solo me queda decirles gracias a cada uno de ustedes por estar en las buenas y en las malas, por cada gol, cada festejo y cada momento.<\/strong>&nbsp;Desde que llegu\u00e9 me hicieron sentir como si fuera de&nbsp;<em>ringue<\/em>&nbsp;desde siempre, as\u00ed que por eso les agradezco mucho. Son unos cracks todos y mejor grupo, gracias por todo\u201d.<\/p>\n\n\n\n<p>El \u00faltimo posteo del juvenil en su feed fue el 30 de diciembre, en un reel en el que se le\u00eda parte de la letra del tema&nbsp;<em>Milagrosa&nbsp;<\/em>de&nbsp;<strong>Milo J.<\/strong>&nbsp;\u201c<strong>el progreso lo noto, ma\u00f1ana ser\u00e9 un genio, pero hoy soy un loco, loco que tiene un sue\u00f1o, loco que tiene un sue\u00f1o<\/strong>\u201djunto a im\u00e1genes de \u00e9l vistiendo los colores de Ringuelet, del equipo de Estudiantes de La Plata y de la Selecci\u00f3n Nacional campeona del mundo. Las fotos del Pincha y del equipo de Lionel Messi que aparec\u00edan en los dos \u00faltimos versos, cuando hablaba de&nbsp;<strong>sue\u00f1os<\/strong>.<\/p>\n\n\n\n<p>\u201cQu\u00e9 injusticia que hayas partido hermano, pero bueno, ahora est\u00e1s sin sufrir, est\u00e1s en paz, espero volver a verte en alg\u00fan momento\u201d, le respondi\u00f3 a ese posteo uno de sus seguidores este domingo. Otro, simplemente escribi\u00f3:<strong>&nbsp;\u201cSiempre en el coraz\u00f3n, crack\u201d.<\/strong><\/p>\n\n\n\n<p>Tambi\u00e9n lo despidieron otros clubes.\u201cComo instituci\u00f3n amiga, estamos con ustedes en este dif\u00edcil momento y les brindamos nuestro apoyo y solidaridad. Que encuentren consuelo en los recuerdos compartidos y en el amor que los rodea. QEPD Tiago\u201d, fue el mensaje de&nbsp;<strong>Alem<\/strong>.<\/p>\n\n\n\n<p>El club<strong>\u00a0Central Ballester<\/strong>\u00a0poste\u00f3 que lamenta \u201cprofundamente el fallecimiento del jugador de 7ma divisi\u00f3n de @cambaceres_oficial Tiago Benjam\u00edn Cricenti\u201d y Juventud Unida de Ensenada public\u00f3: \u201cHacemos extensivo el saludo a sus amigos, compa\u00f1eros de equipo y dem\u00e1s integrantes de su Club. A Tiago no lo conoc\u00edamos, pero una p\u00e9rdida de este tipo nos duele a todos\u201d.<\/p>\n\n\n\n<p><em>Fuente: Infobae.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tiago Benjam\u00edn Cricenti ten\u00eda 16 a\u00f1os. El chico fue trasladado por su padre al Hospital Horacio Cestino, donde falleci\u00f3. Tiago Benjam\u00edn Cricenti, de 16 a\u00f1os, se descompens\u00f3 este domingo mientras&hellip; <\/p>\n","protected":false},"author":6,"featured_media":141847,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-141838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/141838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=141838"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/141838\/revisions"}],"predecessor-version":[{"id":141848,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/141838\/revisions\/141848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/141847"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=141838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=141838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=141838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}