{"id":143702,"date":"2024-04-28T20:02:12","date_gmt":"2024-04-28T23:02:12","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=143702"},"modified":"2024-04-28T20:02:24","modified_gmt":"2024-04-28T23:02:24","slug":"murio-un-jugador-de-futbol-luego-de-chocar-contra-un-muro-de-la-cancha","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/deportes\/murio-un-jugador-de-futbol-luego-de-chocar-contra-un-muro-de-la-cancha\/","title":{"rendered":"Muri\u00f3 un jugador de f\u00fatbol luego de chocar contra un muro de la cancha."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Un joven jugador del club Ferr\u00e9 de Bella Vista falleci\u00f3 este domingo tras impactar contra el muro de la cancha. Ocurri\u00f3 a los 10 minutos del segundo tiempo.<\/h2>\n\n\n\n<p>El jugador identificado como Angel Ojeda fue trasladado al Hospital de Bella Vista en grave estado y minutos m\u00e1s tarde perdi\u00f3 la vida.&nbsp; El partido correspondiente a la Liga Bellavistense era entre Pedro Ferr\u00e9 contra Citrex.&nbsp;<\/p>\n\n\n\n<p>&#8220;Fue una conmoci\u00f3n para todos los que est\u00e1bamos en la cancha&#8221;, se\u00f1al\u00f3 al medio local \u00d1ande Cable el \u00e1rbitro del encuentro.<\/p>\n\n\n\n<p><em>Fuente: Radio Dos.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un joven jugador del club Ferr\u00e9 de Bella Vista falleci\u00f3 este domingo tras impactar contra el muro de la cancha. Ocurri\u00f3 a los 10 minutos del segundo tiempo. El jugador&hellip; <\/p>\n","protected":false},"author":6,"featured_media":143706,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,1658],"tags":[],"class_list":["post-143702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-interior"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/143702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=143702"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/143702\/revisions"}],"predecessor-version":[{"id":143708,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/143702\/revisions\/143708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/143706"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=143702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=143702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=143702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}