{"id":146866,"date":"2024-05-12T21:16:26","date_gmt":"2024-05-13T00:16:26","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=146866"},"modified":"2024-05-12T21:16:38","modified_gmt":"2024-05-13T00:16:38","slug":"el-senado-retoma-el-debate-de-la-ley-bases-en-comision-y-el-oficialismo-apuesta-a-lograr-dictamen-esta-semana","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/politica\/el-senado-retoma-el-debate-de-la-ley-bases-en-comision-y-el-oficialismo-apuesta-a-lograr-dictamen-esta-semana\/","title":{"rendered":"El Senado retoma el debate de la Ley Bases en comisi\u00f3n y el oficialismo apuesta a lograr dictamen esta semana."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El Gobierno busca que el proyecto se trate en el recinto el 23 de este mes, previo al Pacto de Mayo convocado por Javier Milei.<\/h2>\n\n\n\n<p>A dos semanas para el\u00a0<strong>Pacto de Mayo<\/strong>\u00a0que encabezar\u00e1 el presidente\u00a0<strong>Javier Milei,<\/strong>\u00a0el Senado retoma este lunes a partir de las 15:00 el debate de la\u00a0<strong>Ley Bases<\/strong>\u00a0en comisiones, tras un cuarto intermedio. El objetivo del oficialismo es lograr dictamen\u00a0<strong>el jueves,\u00a0<\/strong>para tratarlo en el recinto el\u00a0<strong>23 de mayo,\u00a0<\/strong>al igual que el<strong>\u00a0paquete fiscal,<\/strong>\u00a0dos d\u00edas antes de la cumbre del Presidente con la mayor cantidad posible de gobernadores en C\u00f3rdoba.<\/p>\n\n\n\n<p>Desde el oficialismo, el ministro del Interior,\u00a0<strong>Guillermo Francos,<\/strong>\u00a0sali\u00f3 a plantear que tienen \u201clos votos suficientes\u201d para aprobar el proyecto en general, en medio de la\u00a0<strong>fuerte pulseada\u00a0<\/strong>con el bloque de Uni\u00f3n por la Patria, liderado por\u00a0<strong>Jos\u00e9 Mayans,<\/strong>\u00a0sumado a la fuerte injerencia de la expresidenta,\u00a0<strong>Cristina Kirchner.\u00a0<\/strong>En la bancada K de 33 legisladores advirtieron que buscan\u00a0<strong>cuatro votos<\/strong>\u00a0para tratar de bloquear el proyecto clave del Gobierno.<\/p>\n\n\n\n<p>De manera el\u00edptica, la exmandataria les envi\u00f3 un fuerte mensaje a los gobernadores peronistas que negocian voluntades para la aprobaci\u00f3n de las iniciativas del oficialismo en el Senado. \u201cHay familias que comen una vez por d\u00eda. C\u00f3mo puede ser posible que con este estado de situaci\u00f3n\u00a0<strong>haya gente que apoya estas cosas\u201d<\/strong>, dijo en un acto homenaje al padre\u00a0<strong>Carlos Mugica<\/strong>\u00a0a<strong>\u00a050 a\u00f1os de su asesinato.<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno busca que el proyecto se trate en el recinto el 23 de este mes, previo al Pacto de Mayo convocado por Javier Milei. A dos semanas para el\u00a0Pacto&hellip; <\/p>\n","protected":false},"author":6,"featured_media":146868,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-146866","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/146866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=146866"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/146866\/revisions"}],"predecessor-version":[{"id":146869,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/146866\/revisions\/146869"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/146868"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=146866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=146866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=146866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}