{"id":150326,"date":"2024-05-26T19:22:56","date_gmt":"2024-05-26T22:22:56","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=150326"},"modified":"2024-05-26T19:22:56","modified_gmt":"2024-05-26T22:22:56","slug":"exodo-masivo-en-bangladesh-por-la-llegada-de-un-peligroso-ciclon","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/internacionales\/exodo-masivo-en-bangladesh-por-la-llegada-de-un-peligroso-ciclon\/","title":{"rendered":"\u00c9xodo masivo en Bangladesh por la llegada de un peligroso cicl\u00f3n."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Buscan refugio en zonas del interior del pa\u00eds. El tif\u00f3n Remal alcanza r\u00e1fagas de hasta 130 kil\u00f3metros por hora.<\/h2>\n\n\n\n<p>En una masiva evacuaci\u00f3n ordenada por las autoridades, al menos\u00a0<strong>800.000 banglades\u00edes abandonaron este domingo sus pueblos costeros<\/strong>\u00a0para refugiarse en zonas del interior del pa\u00eds ante la llegada de un peligroso cicl\u00f3n en la Bah\u00eda de Bengala.<\/p>\n\n\n\n<p>\u201cEl intenso cicl\u00f3n Remal ha comenzado a cruzar la costa\u201d, inform\u00f3 el director del Departamento Meteorol\u00f3gico,&nbsp;<strong>Azizur Rahman<\/strong>. La tormenta podr\u00eda seguir azotando la zona hasta la madrugada del lunes. \u201dHasta ahora hemos registrado vientos de hasta 90 kil\u00f3metros por hora\u201d, agreg\u00f3. Esa intensidad para vientos sostenidos ubican a Remal en la categor\u00eda de tormenta tropical, m\u00e1s all\u00e1 de que se detectaron r\u00e1fagas de 130 kil\u00f3metros horarios.<\/p>\n\n\n\n<p>Seg\u00fan el pron\u00f3stico, el cicl\u00f3n\u00a0<strong>Remal<\/strong>\u00a0golpear\u00e1 al pa\u00eds y partes de la vecina India.<\/p>\n\n\n\n<p>El cuerpo del cicl\u00f3n comenz\u00f3 a tocar tierra a trav\u00e9s de la localidad costera de Khepupara, cerca del puerto occidental de Monga. La primera v\u00edctima fue un hombre que se ahog\u00f3 mientras intentaba rescatar a personas en un refugio en una de las zonas vulnerables, el distrito occidental de Patuakhali, dijo el administrador local&nbsp;<strong>Rabiul Islam<\/strong>.<\/p>\n\n\n\n<p>Los ciclones mataron a cientos de miles de personas en Bangladesh en las \u00faltimas d\u00e9cadas, pero el n\u00famero de tormentas que azotan su densamente poblada costa aument\u00f3 en forma dr\u00e1stica en los \u00faltimos tiempos, de una al a\u00f1o hasta tres, debido al impacto del cambio clim\u00e1tico, seg\u00fan expertos.<\/p>\n\n\n\n<p>\u201cEl cicl\u00f3n podr\u00eda desencadenar una marejada cicl\u00f3nica de hasta cuatro metros por encima de la marea astron\u00f3mica normal, lo que puede ser peligroso\u201d, dijo&nbsp;<strong>Muhammad Abul Kalam Mallik<\/strong>, funcionario de meteorolog\u00eda.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">M\u00e1xima alerta y orden de evacuaci\u00f3n<\/h2>\n\n\n\n<p>La mayor parte de las zonas costeras de Banglad\u00e9s est\u00e1n a uno o dos metros por encima del nivel del mar.<\/p>\n\n\n\n<p>Las autoridades elevaron al m\u00e1ximo el nivel de alerta y activaron&nbsp;<strong>una orden de evacuaci\u00f3n<\/strong>&nbsp;para quienes se encuentren en zonas vulnerables.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/tn.com.ar\/resizer\/6olF0Z9B1nQ0SkKmJEtjT0lZ3VE=\/767x0\/smart\/filters:format(webp)\/cloudfront-us-east-1.images.arcpublishing.com\/artear\/3XFF53MTU5F4BFRHDE7QDTUANA.jfif\" alt=\"Una familia evacua a pie una zona costera de Bangladesh (Foto: Reuters)\"\/><figcaption class=\"wp-element-caption\">Una familia evacua a pie una zona costera de Bangladesh (Foto: Reuters)<\/figcaption><\/figure>\n\n\n\n<p>\u201cEstamos aterrorizados\u201d, declar\u00f3<strong>&nbsp;Yusuf Fakir<\/strong>&nbsp;en Kuakata, una localidad del extremo sur del pa\u00eds, justo en la ruta prevista de la tormenta.<\/p>\n\n\n\n<p>Este pescador de 35 a\u00f1os decidi\u00f3 quedarse a cuidar de sus pertenencias y envi\u00f3 a su mujer y a sus hijos a casa de un pariente en el interior.<\/p>\n\n\n\n<p>\u201cAl menos 800.000 personas fueron trasladadas a refugios anticicl\u00f3nicos en los distritos costeros del pa\u00eds\u201d, declar\u00f3 secretario de gesti\u00f3n de cat\u00e1strofes del gobierno,&nbsp;<strong>Kamrul Hasan<\/strong>.<\/p>\n\n\n\n<p>Las autoridades movilizaron a decenas de miles de voluntarios para alertar del peligro, pero los funcionarios locales afirmaron que muchas personas se quedaban en sus casas por temor a que les robaran sus pertenencias.<\/p>\n\n\n\n<p>El pa\u00eds prepar\u00f3 alrededor de 4000 refugios a lo largo de la extensa costa en el golfo de Bengala. Seg\u00fan el departamento meteorol\u00f3gico de Banglad\u00e9s, el cicl\u00f3n Remal tocar\u00e1 tierra el domingo a medianoche.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buscan refugio en zonas del interior del pa\u00eds. El tif\u00f3n Remal alcanza r\u00e1fagas de hasta 130 kil\u00f3metros por hora. En una masiva evacuaci\u00f3n ordenada por las autoridades, al menos\u00a0800.000 banglades\u00edes&hellip; <\/p>\n","protected":false},"author":6,"featured_media":150328,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-150326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/150326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=150326"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/150326\/revisions"}],"predecessor-version":[{"id":150329,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/150326\/revisions\/150329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/150328"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=150326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=150326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=150326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}