{"id":150365,"date":"2024-05-26T22:27:15","date_gmt":"2024-05-27T01:27:15","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=150365"},"modified":"2024-05-26T22:27:18","modified_gmt":"2024-05-27T01:27:18","slug":"regresan-2-cuadros-que-habian-desaparecido-misteriosamente-de-un-prestigioso-museo-suizo","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/internacionales\/regresan-2-cuadros-que-habian-desaparecido-misteriosamente-de-un-prestigioso-museo-suizo\/","title":{"rendered":"Regresan 2 cuadros que hab\u00edan desaparecido misteriosamente de un prestigioso museo suizo."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Las piezas faltaban desde 2023, cuando el Kunsthaus de Z\u00farich cerr\u00f3 para hacer arreglos tras un incendio.<\/h2>\n\n\n\n<p>Dos cuadros que desaparecieron misteriosamente del Kunsthaus de Z\u00farich, museo dotado de una de las colecciones de arte m\u00e1s prestigiosas de Suiza, volvieron a aparecer en circunstancias confusas, anunci\u00f3 el museo el domingo.<\/p>\n\n\n\n<p>Las dos obras \u201cvolvieron a aparecer en buen estado y podr\u00e1n en breve volver a ser expuestas\u201d, subray\u00f3 el museo.<\/p>\n\n\n\n<p>A inicios de 2023, el Kunsthaus perdi\u00f3 la pista de los dos cuadros, enmarcados y protegidos por vidrio. Se trata de un\u00a0<strong>Robert van den Hoecke<\/strong>\u00a0de mediados del siglo XVII, que mostraba soldados en su campamento, y de una naturaleza muerta floral de\u00a0<strong>Dirck de Bray<\/strong>, fechada en 1673.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2024\/05\/image-660.png\" alt=\"\" class=\"wp-image-150371\" srcset=\"https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2024\/05\/image-660.png 768w, https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2024\/05\/image-660-300x225.png 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p>&#8220;Soldados en su campamento&#8221;, de Robert van den Hoecke<\/p>\n\n\n\n<p>Ambos cuadros de peque\u00f1o formato, que son pr\u00e9stamos permanentes de coleccionistas privados, fueron descolgados junto a unas 700 obras para ser limpiados y restaurados por los servicios del museo, donde se registr\u00f3 un incendio a comienzos de agosto de 2022.<\/p>\n\n\n\n<p>\u201cTras revisar los cuadros, el servicio de restauraci\u00f3n del Kunsthaus constat\u00f3 que el estado de ambos es bueno\u201d, subray\u00f3 el museo.<\/p>\n\n\n\n<p>El misterio de la reaparici\u00f3n contin\u00faa, y el Kunsthaus precis\u00f3 que debido a la investigaci\u00f3n policiaca en curso \u201cno puede suministrar ninguna informaci\u00f3n por el momento\u201d.<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" height=\"669\" width=\"550\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/FlUQEMX4uhHeHLqaHYm4mj0Xf24=\/420x560\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/XDJA3NTKFBD7VAH3RZBYDGIAHE.png 420w,https:\/\/www.infobae.com\/new-resizer\/Cq7kY_FSeq_LRDsbeW-c-VPcM0Y=\/768x1024\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/XDJA3NTKFBD7VAH3RZBYDGIAHE.png 768w,https:\/\/www.infobae.com\/new-resizer\/mSyuvROuhcgRxOhCucZfEpF10q8=\/992x1323\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/XDJA3NTKFBD7VAH3RZBYDGIAHE.png 992w,https:\/\/www.infobae.com\/new-resizer\/BjE4wGdDSju99fV3ur3DgF2KdU0=\/1200x1600\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/XDJA3NTKFBD7VAH3RZBYDGIAHE.png 1200w\" class=\"\" src=\"https:\/\/www.infobae.com\/new-resizer\/FlUQEMX4uhHeHLqaHYm4mj0Xf24=\/420x560\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/XDJA3NTKFBD7VAH3RZBYDGIAHE.png%20420w\" alt=\"&quot;Narcisos y otras flores en un jarr\u00f3n de cristal sobre una placa&quot;, de m\u00e1rmol de Dirck de Bray\n\"><\/p>\n\n\n\n<p>&#8220;Narcisos y otras flores en un jarr\u00f3n de cristal sobre una placa&#8221;, de m\u00e1rmol de Dirck de Bray<\/p>\n\n\n\n<p><strong>Ann Demeester<\/strong>, directora del museo, y&nbsp;<strong>Philipp Hildebrand<\/strong>, presidente de la sociedad Kunsthaus Zurich, expresaron su alegr\u00eda de reencontrar los cuadros, as\u00ed como la de la familia propietaria. Ninguna otra pieza descolgada despu\u00e9s del incendio faltaba en el inventario realizado.<\/p>\n\n\n\n<p>Seg\u00fan el sitio internet, el museo tiene 4.000 pinturas y esculturas y 95.000 obras gr\u00e1ficas. Unas 1.000 obras son expuestas en permanencia. El museo dispone de una vasta colecci\u00f3n de obras de Edward Munch y Alberto Giacometti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las piezas faltaban desde 2023, cuando el Kunsthaus de Z\u00farich cerr\u00f3 para hacer arreglos tras un incendio. Dos cuadros que desaparecieron misteriosamente del Kunsthaus de Z\u00farich, museo dotado de una&hellip; <\/p>\n","protected":false},"author":6,"featured_media":150372,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-150365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/150365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=150365"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/150365\/revisions"}],"predecessor-version":[{"id":150373,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/150365\/revisions\/150373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/150372"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=150365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=150365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=150365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}