{"id":150377,"date":"2024-05-26T22:36:22","date_gmt":"2024-05-27T01:36:22","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=150377"},"modified":"2024-05-26T22:36:25","modified_gmt":"2024-05-27T01:36:25","slug":"boca-unidos-cayo-ante-central-norte","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/deportes\/boca-unidos-cayo-ante-central-norte\/","title":{"rendered":"Boca Unidos cay\u00f3 ante Central Norte."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Fue 0-2\u00a0en el Padre Martearena de Salta. El equipo correntino sum\u00f3 su quinta ca\u00edda en lo que va del torneo y se encuentra en la pen\u00faltima posici\u00f3n de la Zona D.<\/h2>\n\n\n\n<p>En el marco de la 11\u00aa fecha del Federal A, Boca Unidos perdi\u00f3 2 a 0 ante Central Norte, con un doblete de German Lesman, en el estadio Padre Martearena de Salta.<\/p>\n\n\n\n<p>El conjunto Aurirrojo enfrenta un momento complicado en la competencia actual. Con esta derrota, sum\u00f3 su quinta p\u00e9rdida en lo que va del torneo y se encuentra en la pen\u00faltima posici\u00f3n de la Zona D, acumulando un total de 7 puntos.<\/p>\n\n\n\n<p>Este rev\u00e9s representa un duro golpe para Boca Unidos que tendr\u00e1 fecha libre en la pr\u00f3xima jornada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fue 0-2\u00a0en el Padre Martearena de Salta. El equipo correntino sum\u00f3 su quinta ca\u00edda en lo que va del torneo y se encuentra en la pen\u00faltima posici\u00f3n de la Zona&hellip; <\/p>\n","protected":false},"author":6,"featured_media":150381,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-150377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/150377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=150377"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/150377\/revisions"}],"predecessor-version":[{"id":150382,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/150377\/revisions\/150382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/150381"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=150377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=150377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=150377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}