{"id":150378,"date":"2024-05-26T22:34:25","date_gmt":"2024-05-27T01:34:25","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=150378"},"modified":"2024-05-26T22:34:29","modified_gmt":"2024-05-27T01:34:29","slug":"incautaron-plantas-de-marihuana-en-paso-de-la-patria","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/policiales\/incautaron-plantas-de-marihuana-en-paso-de-la-patria\/","title":{"rendered":"Incautaron plantas de marihuana en Paso de la Patria."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">En el operativo se confiscaron dos plantas, varios envoltorios de droga y otras pertenencias del due\u00f1o de la finca.<\/h2>\n\n\n\n<p>Polic\u00edas de Corrientes incautaron dos plantas de marihuana en Paso de la Patria durante la tarde del pasado domingo. Adem\u00e1s, se confiscaron otros objetos del lugar y se procedi\u00f3 a la detenci\u00f3n del propietario de la finca.<\/p>\n\n\n\n<p>La intervenci\u00f3n se llev\u00f3 a cabo tras un exhaustivo trabajo de investigaci\u00f3n realizado por efectivos de la Direcci\u00f3n de Drogas Peligrosas y Crimen Organizado, en colaboraci\u00f3n con personal de la Comisar\u00eda local.<\/p>\n\n\n\n<p>La diligencia incluy\u00f3 la ejecuci\u00f3n de una orden de allanamiento en una propiedad de la mencionada localidad correntina. Durante el operativo, se encontraron y secuestraron dos plantas de cannabis, las cuales, al ser sometidas al narcotest, dieron positivo para marihuana.<\/p>\n\n\n\n<p>Adem\u00e1s, se hallaron envoltorios conteniendo sustancia vegetal, as\u00ed como tambi\u00e9n se confiscaron cuatro tel\u00e9fonos celulares, una balanza y una suma de dinero en efectivo.<\/p>\n\n\n\n<p>Tanto el individuo detenido como todos los elementos secuestrados fueron puestos a disposici\u00f3n de la autoridad judicial competente para continuar con las diligencias correspondientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el operativo se confiscaron dos plantas, varios envoltorios de droga y otras pertenencias del due\u00f1o de la finca. Polic\u00edas de Corrientes incautaron dos plantas de marihuana en Paso de&hellip; <\/p>\n","protected":false},"author":6,"featured_media":150379,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-150378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/150378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=150378"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/150378\/revisions"}],"predecessor-version":[{"id":150380,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/150378\/revisions\/150380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/150379"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=150378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=150378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=150378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}