{"id":154153,"date":"2024-07-21T22:40:58","date_gmt":"2024-07-22T01:40:58","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=154153"},"modified":"2024-07-21T22:41:09","modified_gmt":"2024-07-22T01:41:09","slug":"boca-debuto-con-todos-sus-refuerzos-y-empato-con-defensa-y-justicia","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/deportes\/boca-debuto-con-todos-sus-refuerzos-y-empato-con-defensa-y-justicia\/","title":{"rendered":"Boca debut\u00f3 con todos sus refuerzos y empat\u00f3 con Defensa y Justicia."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El Xeneize y el Halc\u00f3n igualaron 2 a 2. Miguel Merentiel, de penal, y Kevin Guti\u00e9rrez, en contra, marcaron para el conjunto de Diego Mart\u00ednez. Los de Francisco Meneghini festejaron a trav\u00e9s de Santiago Ramos y Aaron Molinas.<\/h2>\n\n\n\n<p>En Florencio Varela se vivi\u00f3 un duelo en el que la repartici\u00f3n de puntos no conform\u00f3 a ninguno. Boca present\u00f3 a sus cuatro refuerzos, pero demostr\u00f3 que le falta rodaje al nuevo proyecto de Diego Mart\u00ednez. Fue una noche en la que se aplic\u00f3 la\u00a0<em>Ley del Ex,\u00a0<\/em>dado que Miguel Merentiel, de penal, Santiago Ramos y Aaron Molinas no celebraron sus conquistas por respeto al pasado. El Facha Guti\u00e9rrez tambi\u00e9n sufri\u00f3 una desgracia y convirti\u00f3 contra su propia voluntad y sell\u00f3 el 2 a 2. El Xeneize tiene la cabeza puesta en la Copa Sudamericana y el Halc\u00f3n no logr\u00f3 terminar con la racha adversa que atraviesa desde que comenz\u00f3 el torneo, ya que sigue sin ganar en el \u00e1mbito dom\u00e9stico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Xeneize y el Halc\u00f3n igualaron 2 a 2. Miguel Merentiel, de penal, y Kevin Guti\u00e9rrez, en contra, marcaron para el conjunto de Diego Mart\u00ednez. Los de Francisco Meneghini festejaron&hellip; <\/p>\n","protected":false},"author":6,"featured_media":154161,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-154153","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/154153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=154153"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/154153\/revisions"}],"predecessor-version":[{"id":154162,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/154153\/revisions\/154162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/154161"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=154153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=154153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=154153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}