{"id":154183,"date":"2024-07-22T09:29:54","date_gmt":"2024-07-22T12:29:54","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=154183"},"modified":"2024-07-22T09:29:58","modified_gmt":"2024-07-22T12:29:58","slug":"el-vicegobernador-analizo-los-cambios-en-el-gobierno","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/politica\/el-vicegobernador-analizo-los-cambios-en-el-gobierno\/","title":{"rendered":"El Vicegobernador analiz\u00f3 los cambios en el Gobierno."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El vicegobernador de la provincia, Pedro Braillard Poccard, habl\u00f3 con el programa Lo bueno, lo malo y lo feo por Radio Dos.<\/h2>\n\n\n\n<p>Sobre los cambios en la cartera de seguridad dijo que &#8220;Hay veces en que los cambios responden a generar mayor confianza en la sociedad. Son decisiones muy dif\u00edciles de tomar, muy duras. Pero todo apunta a que la sociedad conf\u00ede en sus instituciones, en una instituci\u00f3n tan fundamental como es la seguridad. Pero s\u00e9 que hay gente honorable que ha hecho todo el esfuerzo, pero tambi\u00e9n pueden haber habido errores y en la duda lo que hay que recuperar es la confianza de la gente en las instituciones. Eso es lo fundamental&#8221;<\/p>\n\n\n\n<p>Acerca de las afirmaciones del gobernador, que habl\u00f3 de que intentaron desestabilizar al gobierno dijo que &#8220;Yo creo que hubo gente que s\u00ed porque hay algunas acusaciones que no tienen ning\u00fan sentido. Nosotros hemos gastado m\u00e1s las energ\u00edas en poner a disposici\u00f3n y hacer todo el esfuerzo para lograr el objetivo fundamental, exclusivo y excluyente en todo esto, que es la aparici\u00f3n con vida del chiquito. Todo lo dem\u00e1s viene despu\u00e9s. Despu\u00e9s aclararemos las cosas, despu\u00e9s diremos lo que tenemos que decir. Pero yo creo que s\u00ed, que aqu\u00ed ha habido gente que ha tenido la intenci\u00f3n. Desde el momento que uno lee en algunos medios de Buenos Aires que se habla de intervenci\u00f3n de un poder evidentemente, alguien lleva esa informaci\u00f3n o alguien la plantea. Eso no aparece como de casualidad&#8221;, resalt\u00f3.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El vicegobernador de la provincia, Pedro Braillard Poccard, habl\u00f3 con el programa Lo bueno, lo malo y lo feo por Radio Dos. Sobre los cambios en la cartera de seguridad&hellip; <\/p>\n","protected":false},"author":6,"featured_media":154188,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-154183","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/154183","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=154183"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/154183\/revisions"}],"predecessor-version":[{"id":154189,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/154183\/revisions\/154189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/154188"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=154183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=154183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=154183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}