{"id":154199,"date":"2024-07-22T09:48:50","date_gmt":"2024-07-22T12:48:50","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=154199"},"modified":"2024-07-22T09:48:54","modified_gmt":"2024-07-22T12:48:54","slug":"un-argentino-murio-mientras-hacia-una-excursion-en-machu-picchu","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/policiales\/un-argentino-murio-mientras-hacia-una-excursion-en-machu-picchu\/","title":{"rendered":"Un argentino muri\u00f3 mientras hac\u00eda una excursi\u00f3n en Machu Picchu."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La v\u00edctima, identificada como Carlos Rubinstein, de 59 a\u00f1os, se descompens\u00f3 cuando recorr\u00eda el parque arqueol\u00f3gico Ollantaytambo. Se desconoce si ten\u00eda problemas de salud preexistentes.<\/h2>\n\n\n\n<p>Lo que promet\u00eda ser un viaje de ensue\u00f1o se transform\u00f3 en una pesadilla. Un turista argentino que participaba de una excursi\u00f3n al Machu Picchu, en Per\u00fa, muri\u00f3 tras desplomarse frente a su esposa y varios otros viajeros. A pesar de que los presentes intentaron socorrerlo realizando maniobras de primeros auxilios, el hombre falleci\u00f3 en el acto.<\/p>\n\n\n\n<p>\u00a0La v\u00edctima del hecho es Carlos Jorge Rubinstein de 59 a\u00f1os. El hombre estaba una visita al parque arqueol\u00f3gico Ollantaytambo, una zona que se encuentra a unos 2.792 metros sobre el nivel del mar, cuando perdi\u00f3 la vida.<\/p>\n\n\n\n<p>El hecho ocurri\u00f3 el pasado martes 16 de julio, pero la noticia se difundi\u00f3 en las \u00faltimas horas a ra\u00edz de la publicaciones en medios locales. Un video difundido por la se\u00f1al Cusco Visi\u00f3n muestra a dos personas que desesperadas se turnaban para realizarle Reanimaci\u00f3n Cardio Pulmonar (RCP) a Rubinstein. &#8220;\u00a1Respir\u00e1!&#8221;Ah\u00ed tiene pulsaci\u00f3n ahorita&#8221;, se escucha que dijo uno de los involucrados, esperanzado. A\u00fan as\u00ed la respuesta de un compa\u00f1ero de la excursi\u00f3n en contundente. &#8220;S\u00ed, pero se le va. \u00a1Necesito el ox\u00edgeno!&#8221;, grit\u00f3 el hombre.<\/p>\n\n\n\n<p>&#8220;Carlos respir\u00e1, Carlos respir\u00e1. Carlos escuch\u00e1 a tu mujer&#8221;, le suplicaba su esposa que intentaba reanimarlo. Mientras ,un hombre hablaba por tel\u00e9fono y ped\u00eda la asistencia m\u00e9dica en el lugar. En ese momento se lo oye decir: &#8220;Hay una posta ac\u00e1 al ladito. No quieren venir&#8221;.<\/p>\n\n\n\n<p>&nbsp;Los testigos y turistas que acompa\u00f1aban a Rubinstein denunciaron que los servicios de emergencia tardaron alrededor de 20 minutos en llegar a la zona. Adem\u00e1s, aseguraron que los m\u00e9dicos llegaron sin un tanque de ox\u00edgeno ya que no hab\u00eda insumos en el centro de asistencia.<\/p>\n\n\n\n<p>&#8220;Es lamentable tener este tipo de noticias. Son situaciones que ocurren. No quisi\u00e9ramos que ocurran, pero ha pasado en la estaci\u00f3n del tren. Ha sido asistido en un primera momento por el personal que ha estado en las inmediaciones&#8221;, dijo Hanner Horna, jefe de la polic\u00eda de Turismo de Cusco, al medio RPP.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La v\u00edctima, identificada como Carlos Rubinstein, de 59 a\u00f1os, se descompens\u00f3 cuando recorr\u00eda el parque arqueol\u00f3gico Ollantaytambo. Se desconoce si ten\u00eda problemas de salud preexistentes. Lo que promet\u00eda ser un&hellip; <\/p>\n","protected":false},"author":6,"featured_media":154200,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-154199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/154199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=154199"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/154199\/revisions"}],"predecessor-version":[{"id":154201,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/154199\/revisions\/154201"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/154200"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=154199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=154199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=154199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}