{"id":154218,"date":"2024-07-22T10:38:18","date_gmt":"2024-07-22T13:38:18","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=154218"},"modified":"2024-07-22T10:38:30","modified_gmt":"2024-07-22T13:38:30","slug":"un-apostador-se-quedo-con-el-pozo-millonario-del-quini-6","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/informacion-general\/un-apostador-se-quedo-con-el-pozo-millonario-del-quini-6\/","title":{"rendered":"Un apostador se qued\u00f3 con el pozo millonario del Quini 6."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Fue en la provincia de San Luis donde solo un apostador se llev\u00f3 m\u00e1s de 2.100 millones de pesos.<\/h2>\n\n\n\n<p>Un apostador de la ciudad de San Luis acert\u00f3 al combinaci\u00f3n de seis n\u00fameros de la modalidad Revancha del Quini 6, en el sorteo n\u00famero 3.184, realizado este domingo, y se llevar\u00e1 el premio acumulado de algo m\u00e1s de 2.100 millones de pesos.<\/p>\n\n\n\n<p>En tanto, el Siempre Sale tuvo quince ganadores, cada uno de los cuales se quedar\u00e1 con algo m\u00e1s de diez millones de pesos.<\/p>\n\n\n\n<p>El pr\u00f3ximo sorteo del Quini 6 se realizar\u00e1 el mi\u00e9rcoles 24, a las 21.15, y tendr\u00e1 un pozo acumulado de 2.600 millones de pesos.<\/p>\n\n\n\n<p><strong>Tradicional<\/strong><\/p>\n\n\n\n<p>N\u00fameros sorteados: 03 &#8211; 06 &#8211; 16 &#8211; 19 &#8211; 35 &#8211; 42<\/p>\n\n\n\n<p>Con seis aciertos: vacante, con un pozo de $831.987.344<\/p>\n\n\n\n<p>Con cinco aciertos: 31 ganadores, que recibir\u00e1n $545.994<\/p>\n\n\n\n<p>Con cuatro aciertos: 1.969 ganadores, que recibir\u00e1n $2.578<\/p>\n\n\n\n<p><strong>La Segunda<\/strong><\/p>\n\n\n\n<p>N\u00fameros sorteados: 08 &#8211; 16 &#8211; 25 &#8211; 29 &#8211; 32 &#8211; 44<\/p>\n\n\n\n<p>Con seis aciertos: vacante, con un pozo de $1.077.630.727<\/p>\n\n\n\n<p>Con cinco aciertos: 48 ganadores, que recibir\u00e1n $352.621<\/p>\n\n\n\n<p>Con cuatro aciertos: 2.139 ganadores, que recibir\u00e1n $2.373<\/p>\n\n\n\n<p><strong>Revancha<\/strong><\/p>\n\n\n\n<p>N\u00fameros sorteados: 07 &#8211; 09 &#8211; 15 &#8211; 19 &#8211; 29 &#8211; 33<\/p>\n\n\n\n<p>Con seis aciertos: 1 ganador, que recibir\u00e1 $2.134.182.803<\/p>\n\n\n\n<p><strong>Siempre Sale<\/strong><\/p>\n\n\n\n<p>N\u00fameros sorteados: 15 &#8211; 19 &#8211; 20 &#8211; 25 &#8211; 40 &#8211; 42<\/p>\n\n\n\n<p>Con cinco aciertos: 15 ganadores, que recibir\u00e1n $10.115.325<\/p>\n\n\n\n<p><strong>Pozo extra<\/strong><\/p>\n\n\n\n<p>1.271 ganadores, que recibir\u00e1n $51.140<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fue en la provincia de San Luis donde solo un apostador se llev\u00f3 m\u00e1s de 2.100 millones de pesos. Un apostador de la ciudad de San Luis acert\u00f3 al combinaci\u00f3n&hellip; <\/p>\n","protected":false},"author":6,"featured_media":154220,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-154218","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/154218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=154218"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/154218\/revisions"}],"predecessor-version":[{"id":154221,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/154218\/revisions\/154221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/154220"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=154218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=154218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=154218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}