{"id":155836,"date":"2024-07-29T21:59:00","date_gmt":"2024-07-30T00:59:00","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=155836"},"modified":"2024-07-29T21:59:11","modified_gmt":"2024-07-30T00:59:11","slug":"villarruel-critico-la-hipocresia-del-kirchnerismo-sobre-venezuela","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/politica\/villarruel-critico-la-hipocresia-del-kirchnerismo-sobre-venezuela\/","title":{"rendered":"Villarruel critic\u00f3 la &#8220;hipocres\u00eda&#8221; del kirchnerismo sobre Venezuela"},"content":{"rendered":"\n<p>La vicepresidenta aprovech\u00f3 la situaci\u00f3n para buscar conciliar con Javier Milei.<\/p>\n\n\n\n<p>La vicepresidenta\u00a0<strong>Victoria Villarruel\u00a0<\/strong>le atribuy\u00f3 este lunes\u00a0<strong>&#8220;hipocres\u00eda&#8221; al kirchnerismo<\/strong>\u00a0en torno a la situaci\u00f3n de Venezuela, al acusarlo de &#8220;mirar para otro lado&#8221; y &#8220;avalar&#8221; al mandatario de ese pa\u00eds,\u00a0<strong>Nicol\u00e1s Maduro<\/strong>, en medio de la controversia por las elecciones.\u00a0\u00a0\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">La hipocres\u00eda del kirchnerismo que mira para otro lado y avala cuando un tirano proscribe a su oposici\u00f3n, tortura en c\u00e1rceles clandestinas a sus detractores o falsifica las actas del pueblo que vota a sus gobernantes. Ese mismo kirchnerismo que proyecta en m\u00ed sus deseos m\u00e1s\u2026<\/p>&mdash; Victoria Villarruel (@VickyVillarruel) <a href=\"https:\/\/twitter.com\/VickyVillarruel\/status\/1818059937420898335?ref_src=twsrc%5Etfw\">July 29, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p><strong>&#8220;Ese mismo kirchnerismo que proyecta en m\u00ed sus deseos m\u00e1s oscuros, adjudic\u00e1ndome conductas antidemocr\u00e1ticas.\u00a0<\/strong>Quiz\u00e1s somos con el presidente\u00a0<strong>Javier Milei<\/strong>\u00a0todo lo que a la izquierda, en su inconsciente cada vez m\u00e1s consciente, les encantar\u00eda ser&#8221;, advirti\u00f3 Villarruel desde su cuenta de Twitter.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vicepresidenta aprovech\u00f3 la situaci\u00f3n para buscar conciliar con Javier Milei. La vicepresidenta\u00a0Victoria Villarruel\u00a0le atribuy\u00f3 este lunes\u00a0&#8220;hipocres\u00eda&#8221; al kirchnerismo\u00a0en torno a la situaci\u00f3n de Venezuela, al acusarlo de &#8220;mirar para&hellip; <\/p>\n","protected":false},"author":4,"featured_media":155837,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,3],"tags":[],"class_list":["post-155836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-politica"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/155836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=155836"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/155836\/revisions"}],"predecessor-version":[{"id":155838,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/155836\/revisions\/155838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/155837"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=155836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=155836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=155836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}