{"id":155904,"date":"2024-07-30T11:28:49","date_gmt":"2024-07-30T14:28:49","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=155904"},"modified":"2024-07-30T11:29:00","modified_gmt":"2024-07-30T14:29:00","slug":"tres-nenas-de-6-9-y-11-anos-fueron-asesinadas-a-punaladas-en-medio-de-una-clase-de-baile","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/internacionales\/tres-nenas-de-6-9-y-11-anos-fueron-asesinadas-a-punaladas-en-medio-de-una-clase-de-baile\/","title":{"rendered":"Tres nenas de 6, 9 y 11 a\u00f1os fueron asesinadas a pu\u00f1aladas en medio de una clase de baile"},"content":{"rendered":"\n<p>Un joven asesin\u00f3 a pu\u00f1aladas a tres nenas de 6, 9 y 11 a\u00f1os que realizaban una clase de danzaen una escuela al noroeste de Inglaterra. Por el ataque, hay otros ocho chicos y dos adultos internados en terapia intensiva.<\/p>\n\n\n\n<p><strong>El \u00fanico detenido por la brutal ataque es un chico de 17 a\u00f1os<\/strong>,que fue interrogado por la polic\u00eda este martes para determinar qu\u00e9 fue lo que lo llev\u00f3 a atacar a los nenes.<\/p>\n\n\n\n<p>Seg\u00fan informaron medios locales, el joven era de Cardiff, Gales, y viv\u00eda desde hac\u00eda unos a\u00f1os en un pueblo ubicado a unos 5 kil\u00f3metros de Southport, ciudad en la que ocurri\u00f3 el hecho. Tambi\u00e9n dijeron que no relacionaron el ataque con el terrorismo y no buscaban otros sospechosos.<\/p>\n\n\n\n<p>\u201cCreemos que<strong>&nbsp;los adultos que resultaron heridos intentaron valientemente proteger a los nenes<\/strong>&nbsp;que eran atacados\u201d, revel\u00f3 al medio AP News, Serena Kennedy, jefa de la polic\u00eda de Merseyside.<\/p>\n\n\n\n<p>En tanto, los testigos dijeron que<strong>&nbsp;\u201cla escena fue digna de una pel\u00edcula de terror\u201d&nbsp;<\/strong>en la que nenes ensangrentados gritaban e intentaban escapar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El triste mensaje de Taylor Swift tras el ataque<\/h2>\n\n\n\n<p>Tal como inform\u00f3 la Polic\u00eda de Inglaterra, el brutal ataque a los alumnos y profesores de la escuela de baile se dio mientras realizaban una clase especial con tem\u00e1tica de Taylor Swift. Luego de conocer la noticia, la artista expres\u00f3 su tristeza a trav\u00e9s de las redes sociales.<\/p>\n\n\n\n<p>\u201cEl ataque en Southport me invade continuamente y&nbsp;<strong>estoy completamente en shock<\/strong>\u201d, dijo la cantante en un comunicado que comparti\u00f3 en su cuenta de Instagram. \u201cLa p\u00e9rdida de vidas inocentes y el horrendo trauma infligido a todos los que estaban all\u00ed, a las familias y los socorristas\u201d, agreg\u00f3.<\/p>\n\n\n\n<p>\u201c<strong>Eran s\u00f3lo ni\u00f1os peque\u00f1os en una clase de baile<\/strong>. No s\u00e9 ni por d\u00f3nde empezar a transmitir mis condolencias a estas familias\u201d, finaliz\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/tn.com.ar\/resizer\/v2\/la-cantante-compartio-un-sentido-mensaje-en-sus-redes-sociales-en-el-cual-le-envio-sus-condolencias-a-la-familia-foto-instagramtaylorswift-FC2QYWDJZNAKJHPXPSQQAZ26YA.jpg?auth=52b2039da40c68339582ce484f0647f1295b7f896a593e3a014e33dbcf0cb2a8&amp;width=767\" alt=\"La cantante comparti\u00f3 un sentido mensaje en sus redes sociales, en el cu\u00e1l le envi\u00f3 sus condolencias a la familia. (Foto: Instagram\/@taylorswift)\"\/><figcaption class=\"wp-element-caption\">La cantante comparti\u00f3 un sentido mensaje en sus redes sociales, en el cu\u00e1l le envi\u00f3 sus condolencias a la familia. (Foto: Instagram\/@taylorswift)<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Un joven asesin\u00f3 a pu\u00f1aladas a tres nenas de 6, 9 y 11 a\u00f1os que realizaban una clase de danzaen una escuela al noroeste de Inglaterra. Por el ataque, hay&hellip; <\/p>\n","protected":false},"author":12,"featured_media":155932,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-155904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/155904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=155904"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/155904\/revisions"}],"predecessor-version":[{"id":155933,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/155904\/revisions\/155933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/155932"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=155904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=155904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=155904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}