{"id":156394,"date":"2024-08-01T09:55:34","date_gmt":"2024-08-01T12:55:34","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=156394"},"modified":"2024-08-01T09:55:46","modified_gmt":"2024-08-01T12:55:46","slug":"dolar-hoy-a-cuanto-cotizan-el-oficial-y-las-otras-opciones-cambiarias-este-jueves-1-de-agosto","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/economia\/dolar-hoy-a-cuanto-cotizan-el-oficial-y-las-otras-opciones-cambiarias-este-jueves-1-de-agosto\/","title":{"rendered":"D\u00f3lar hoy: a cu\u00e1nto cotizan el oficial y las otras opciones cambiarias este jueves 1 de agosto"},"content":{"rendered":"\n<p>El<strong>d\u00f3lar\u00a0oficial\u00a0<\/strong>(sin impuestos) cotiza este jueves 1 de agosto a\u00a0<strong>$911,50\u00a0<\/strong>para la compra y<strong>\u00a0$951,50 para la venta<\/strong>\u00a0en las pantallas del Banco de la Naci\u00f3n Argentina (BNA).<\/p>\n\n\n\n<p>El\u00a0<strong>d\u00f3lar blue<\/strong>\u00a0opera a a\u00a0<strong>$1350\u00a0<\/strong>para la compra y a\u00a0<strong>$1370 para la venta\u00a0<\/strong>en la Ciudad de Buenos Aires. El d\u00f3lar mayorista abre a\u00a0<strong>$932.<\/strong>\u00a0As\u00ed, la brecha entre el\u00a0<strong>blue<\/strong>\u00a0y el mayorista se ubica en<strong>\u00a046,99%<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00f3lar hoy: a cu\u00e1nto cotizan el oficial, el blue, el mayorista, el MEP, el CCL y el Cripto<\/h2>\n\n\n\n<p>Las cotizaciones de las distintas alternativas para acceder al d\u00f3lar en la Argentina:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>D\u00f3lar\u00a0<strong>blue: $1370;<\/strong><\/li>\n\n\n\n<li>D\u00f3lar\u00a0<strong>oficial: $951,50;<\/strong><\/li>\n\n\n\n<li>D\u00f3lar<strong>\u00a0solidario: $1522,40;<\/strong><\/li>\n\n\n\n<li>D\u00f3lar\u00a0<strong>tarjeta: $1522,40;<\/strong><\/li>\n\n\n\n<li>D\u00f3lar<strong>\u00a0mayorista: $932;<\/strong><\/li>\n\n\n\n<li>D\u00f3lar<strong>\u00a0MEP: $1293,33;<\/strong><\/li>\n\n\n\n<li>D\u00f3lar\u00a0<strong>CCL: $1284,84;<\/strong><\/li>\n\n\n\n<li>D\u00f3lar\u00a0<strong>Cripto: $1329,30.<\/strong><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00f3lar solidario y d\u00f3lar tarjeta<\/h2>\n\n\n\n<p>El&nbsp;<strong>d\u00f3lar solidario&nbsp;<\/strong>o ahorro opera a&nbsp;<strong>$1522,40&nbsp;<\/strong>en el Banco Naci\u00f3n y acumul\u00f3 un aumento de $197,20 en lo que va de 2024. El recargo de impuestos lo encarecen<strong>&nbsp;60%<\/strong>. En el 2023, el d\u00f3lar ahorro aument\u00f3&nbsp;<strong>$1022,04<\/strong>.<\/p>\n\n\n\n<p>La cotizaci\u00f3n surge de la suma del precio del d\u00f3lar oficial m\u00e1s los impuestos PAIS (30%) y&nbsp;<strong>la retenci\u00f3n de 30% en concepto de anticipo de Ganancias<\/strong>, tras los cambios establecidos el 13 de diciembre.<\/p>\n\n\n\n<p>En octubre, las percepciones hab\u00edan aumentado tanto para el<strong>d\u00f3lar tarjeta<\/strong>-que surgi\u00f3 el 14 de julio de 2022- y se\u00a0unific\u00f3 con el d\u00f3lar Qatar.\u00a0As\u00ed, el recargo llega al 60%, por lo que se negoci\u00f3 a<strong>\u00a0$1522,40<\/strong>. En 2023 escal\u00f3\u00a0<strong>$1023,60<\/strong>.<\/p>\n\n\n\n<p>Este es el tipo de cambio que rige para las transacciones (compra de bienes o servicios v\u00eda tarjeta de cr\u00e9dito o d\u00e9bito) en el exterior<strong>; incluye plataformas como Netflix o Spotify.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00f3lar blue<\/h2>\n\n\n\n<p>El&nbsp;<strong>d\u00f3lar blue<\/strong>&nbsp;o informal baj\u00f3 $15 y opera a<strong>&nbsp;$1370&nbsp;<\/strong>para la venta. En julio, la divisa paralela escal\u00f3 $5 y cerr\u00f3 a&nbsp;<strong>$1370<\/strong>. El viernes 12 anot\u00f3 un m\u00e1ximo de $1500. En lo que va del a\u00f1o, acumul\u00f3 un alza de $345.<\/p>\n\n\n\n<p>En&nbsp;<strong>junio<\/strong>, el d\u00f3lar blue escal\u00f3 $140 y cerr\u00f3 el mes a<strong>&nbsp;$1365<\/strong>. El mi\u00e9rcoles 26, el blue toc\u00f3 los $1380 y cerr\u00f3 a $1370, un nuevo r\u00e9cord.<\/p>\n\n\n\n<p>En&nbsp;<strong>mayo<\/strong>, el d\u00f3lar blue aument\u00f3 $185 y finaliz\u00f3 el mes a&nbsp;<strong>$1225<\/strong>. El jueves 23, el blue lleg\u00f3 a tocar los $1300.<\/p>\n\n\n\n<p>En&nbsp;<strong>abril<\/strong>, el d\u00f3lar blue subi\u00f3 $30 y cerr\u00f3 el mes a<strong>&nbsp;$1040<\/strong>.<\/p>\n\n\n\n<p>En&nbsp;<strong>marzo<\/strong>, el d\u00f3lar blue retrocedi\u00f3 $20 y finaliz\u00f3 el mes a&nbsp;<strong>$1010<\/strong>.<\/p>\n\n\n\n<p>En&nbsp;<strong>febrero<\/strong>, el&nbsp;<strong>d\u00f3lar blue<\/strong>&nbsp;<strong>baj\u00f3 $165<\/strong>&nbsp;y cerr\u00f3 el mes a&nbsp;<strong>$1030<\/strong>.<\/p>\n\n\n\n<p>En<strong>&nbsp;enero<\/strong>, el d\u00f3lar blue&nbsp;<strong>subi\u00f3 $170&nbsp;<\/strong>y cerr\u00f3 el mes a&nbsp;<strong>$1195<\/strong>.<\/p>\n\n\n\n<p>En<strong>&nbsp;diciembre&nbsp;<\/strong>de 2023, el d\u00f3lar blue trep\u00f3 $100 y cerr\u00f3 el a\u00f1o a&nbsp;<strong>$1025<\/strong>.<\/p>\n\n\n\n<p>En 2023, el&nbsp;<strong>d\u00f3lar blue&nbsp;<\/strong>acumul\u00f3 una&nbsp;<strong>suba de $679<\/strong>. En tanto, en 2022, hab\u00eda cerrado en $346.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00f3lar mayorista o comercial<\/h2>\n\n\n\n<p>En el segmento&nbsp;<strong>mayorista<\/strong>, el d\u00f3lar comercial opera a&nbsp;<strong>$932<\/strong>. En la \u00faltima jornada de julio, el Banco Central vendi\u00f3 US$81 millones y el acumulado de&nbsp;<strong>julio&nbsp;<\/strong>cambi\u00f3 a signo negativo, por&nbsp;<strong>US$181 millones de ventas netas.<\/strong><\/p>\n\n\n\n<p>En junio, el BCRA termin\u00f3 con&nbsp;<strong>saldo negativo<\/strong>&nbsp;de<strong>&nbsp;US$84 millones<\/strong>. AcumulaUS$17.162 millones desde diciembre.<\/p>\n\n\n\n<p>En mayo, el Banco Central compr\u00f3 reservas por<strong>&nbsp;US$2522 millones<\/strong>.<\/p>\n\n\n\n<p>En abril, el BCRA acumul\u00f3 US$3348 millones y en marzo,&nbsp;<strong>US$2884 millones<\/strong>. En&nbsp;<strong>febrero<\/strong>, el Banco Central obtuvo US$2357 millones. El Banco Central cerr\u00f3<strong>&nbsp;enero<\/strong>&nbsp;con ventas por US$10 millones, aunque acumul\u00f3 durante el mes US$3273 millones.<\/p>\n\n\n\n<p>En diciembre, el BCRA sum\u00f3 compras por US$2862 millones. El d\u00f3lar mayorista cerr\u00f3 2023 a<strong>&nbsp;$808,45<\/strong>.<\/p>\n\n\n\n<p>En 2023,&nbsp;<strong>las reservas cayeron en nueve de los 12 meses<\/strong>. Las mayores p\u00e9rdidas se vieron en&nbsp;<strong>junio<\/strong>&nbsp;(US$5075 millones),&nbsp;<strong>octubre<\/strong>&nbsp;(US$4366 millones) y&nbsp;<strong>abril<\/strong>&nbsp;(US$4059 millones). De punta a punta,&nbsp;<strong>la ca\u00edda totaliz\u00f3 US$21.527 millones en 2023<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00f3lar contado con liquidaci\u00f3n (CCL)<\/h2>\n\n\n\n<p>El&nbsp;<strong>d\u00f3lar contado con liquidaci\u00f3n (CCL)<\/strong>&nbsp;cotiza a&nbsp;<strong>$1284,84<\/strong>. En lo que va del a\u00f1o, subi\u00f3 $311,69.En 2023, acumul\u00f3 un alza de&nbsp;<strong>$629,90<\/strong>&nbsp;o 183,51%.<\/p>\n\n\n\n<p>\u00bfQu\u00e9 es el d\u00f3lar contado con liqui? Es el tipo de cambio que surge de la operatoria que permite a los inversores&nbsp;<strong>comprar papeles argentinos en el mercado local y venderlos en el exterior para lograr as\u00ed girar divisas para \u201catesoramiento\u201d<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00f3lar MEP o Bolsa<\/h2>\n\n\n\n<p>Por su parte, el&nbsp;<strong>d\u00f3lar MEP<\/strong>&nbsp;opera a<strong>&nbsp;$1293,33&nbsp;<\/strong>en las pantallas oficiales y subi\u00f3 $298,33 en lo que va de 2024. En el 2023, acumul\u00f3 un alza de $667,06 o 203,41%.<\/p>\n\n\n\n<p>El d\u00f3lar MEP es un tipo de cambio que, como el CCL, se obtiene mediante la&nbsp;<strong>compraventa de acciones&nbsp;<\/strong>o bonos. La \u00fanica diferencia es que las divisas resultantes se depositan localmente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00f3lar Cripto<\/h2>\n\n\n\n<p>El tipo de cambio para acceder a d\u00f3lares mediante\u00a0<strong>criptomonedas<\/strong>\u00a0se negocia a\u00a0<strong>$1329,30<\/strong>.En el ecosistema cripto, no obstante, existen diferentes cotizaciones seg\u00fan la billetera virtual con la que se opere.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cu\u00e1l es la brecha hoy entre el d\u00f3lar blue y el mayorista<\/h2>\n\n\n\n<p>La brecha entre el&nbsp;<strong>d\u00f3lar blue<\/strong>&nbsp;y el mayorista se ubica en&nbsp;<strong>46,99%<\/strong>. El d\u00f3lar mayorista abre en&nbsp;<strong>$932<\/strong>.<\/p>\n\n\n\n<p>Esta cotizaci\u00f3n mayorista surge del segmento que comanda el BCRA. Adem\u00e1s de la autoridad monetaria, intervienen all\u00ed las empresas y bancos que demandan d\u00f3lares as\u00ed como los exportadores de granos y oleaginosas que liquidan divisas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eld\u00f3lar\u00a0oficial\u00a0(sin impuestos) cotiza este jueves 1 de agosto a\u00a0$911,50\u00a0para la compra y\u00a0$951,50 para la venta\u00a0en las pantallas del Banco de la Naci\u00f3n Argentina (BNA). El\u00a0d\u00f3lar blue\u00a0opera a a\u00a0$1350\u00a0para la compra&hellip; <\/p>\n","protected":false},"author":12,"featured_media":156410,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-156394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/156394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=156394"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/156394\/revisions"}],"predecessor-version":[{"id":156411,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/156394\/revisions\/156411"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/156410"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=156394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=156394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=156394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}