{"id":160640,"date":"2024-08-20T22:15:38","date_gmt":"2024-08-21T01:15:38","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=160640"},"modified":"2024-08-20T22:15:50","modified_gmt":"2024-08-21T01:15:50","slug":"san-lorenzo-visita-a-atletico-mineiro-en-busqueda-de-sellar-su-clasificacion-a-cuartos-de-la-copa-libertadores","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/deportes\/san-lorenzo-visita-a-atletico-mineiro-en-busqueda-de-sellar-su-clasificacion-a-cuartos-de-la-copa-libertadores\/","title":{"rendered":"San Lorenzo visita a Atl\u00e9tico Mineiro en b\u00fasqueda de sellar su clasificaci\u00f3n a cuartos de la Copa Libertadores"},"content":{"rendered":"\n<p>El \u201cCicl\u00f3n\u201d define como visitante a partir de las 21:30 horas.<\/p>\n\n\n\n<p><strong>San Lorenzo jugar\u00e1 ante Atl\u00e9tico Mineiro en un partido correspondiente a la vuelta de los octavos de final de la Copa Sudamericana, el cual se disputar\u00e1 en el Estadio Presidente El\u00edas Kalil.<\/strong><\/p>\n\n\n\n<p>Los dirigidos por Leandro Romagnoli vienen de empatar 1 a 1 ante el equipo brasile\u00f1o, en condici\u00f3n de local, con goles del delantero&nbsp;<strong>Alexis Cuello<\/strong>, para el \u201cCicl\u00f3n\u201d, a los 17 minutos del primer tiempo, y del enganche&nbsp;<strong>Paulinho<\/strong>, para el Mineiro, a los 13 minutos de la segunda mitad.<\/p>\n\n\n\n<p>El \u00e1rbitro ser\u00e1 el chileno Felipe Gonz\u00e1lez, mientras que en el VAR estar\u00e1 Jos\u00e9 Cabero, tambi\u00e9n oriundo de Chile.<\/p>\n\n\n\n<p>Las formaciones de ambos equipos:<\/p>\n\n\n\n<p><strong>Atl\u00e9tico Mineiro<\/strong>: \u00c9verson; Rodrigo Battaglia, Bruno Fuchs, Junior Alonso; Gustavo Scarpa, Ot\u00e1vio, Mat\u00edas Zaracho, Guilherme Arana; Alan Franco; Paulinho, Deyverson. DT: Gabriel Milito.<\/p>\n\n\n\n<p><strong>San Lorenzo<\/strong>: Gast\u00f3n G\u00f3mez; Oscar Arias, Jhohan Roma\u00f1a, Gast\u00f3n Campi, El\u00edas B\u00e1ez; Nicol\u00e1s Tripicchio, Santiago Sosa, Eli\u00e1n Irala; Iv\u00e1n Leguizam\u00f3n, Alexis Cuello, Mat\u00edas Reali. DT: Leandro Romagnoli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El \u201cCicl\u00f3n\u201d define como visitante a partir de las 21:30 horas. San Lorenzo jugar\u00e1 ante Atl\u00e9tico Mineiro en un partido correspondiente a la vuelta de los octavos de final de&hellip; <\/p>\n","protected":false},"author":4,"featured_media":160641,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-160640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/160640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=160640"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/160640\/revisions"}],"predecessor-version":[{"id":160642,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/160640\/revisions\/160642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/160641"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=160640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=160640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=160640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}