{"id":194214,"date":"2025-03-03T10:00:13","date_gmt":"2025-03-03T13:00:13","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=194214"},"modified":"2025-03-03T10:00:14","modified_gmt":"2025-03-03T13:00:14","slug":"gran-incendio-en-paraje-loma-alta-amenazo-viviendas-y-una-escuela","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/interior\/gran-incendio-en-paraje-loma-alta-amenazo-viviendas-y-una-escuela\/","title":{"rendered":"Gran incendio en Paraje Loma Alta amenaz\u00f3 viviendas y una escuela"},"content":{"rendered":"\n<p>D\u00eda complicado ayer en Paraje Loma Alta por incendios de pastizales. Debieron trabajar intensamente bomberos de Ca\u00e1 Cat\u00ed y de otras localidades, polic\u00edas, brigadistas de la provincia y pobladores.<\/p>\n\n\n\n<p>Un incendio de grandes proporciones se desat\u00f3 ayer domingo en en Loma Alta, entre Paso Florent\u00edn y Lomas de Vallejos.<\/p>\n\n\n\n<p>La situaci\u00f3n alert\u00f3 a los vecinos ya que el fuego estuvo cerca de viviendas y una escuela. Gracias al r\u00e1pido accionar de bomberos el fuego fue controlado tras varias horas.&nbsp;Previous<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.diarioepoca.com\/content\/bucket\/4\/1417394h720.jpg.webp\" alt=\"482029538_960864276026697_5146395045565867859_n.jpg\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.diarioepoca.com\/content\/bucket\/5\/1417395w790h720.jpg.webp\" alt=\"481259578_960864232693368_4415650766102075408_n.jpg\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.diarioepoca.com\/content\/bucket\/6\/1417396w790h720.jpg.webp\" alt=\"480941291_1255465016586728_6140120726775095200_n.jpg\"\/><\/figure>\n\n\n\n<p>Next<\/p>\n\n\n\n<p>Intervinieron bomberos de Ca\u00e1 Cat\u00ed, polic\u00edas, brigadistas de la provincia, dotaciones de bomberos de otras localidades, ambulancia de Lomas de Vallejos y operarios de la DPEC.<\/p>\n\n\n\n<p>Ante la gravedad de la situaci\u00f3n, vecinos y propietarios colaboraron en sofocar el fuego. Hasta esta ma\u00f1ana no hay servicio de energ\u00eda el\u00e9ctrica por la quema de postes.&nbsp;<\/p>\n\n\n\n<p>Con informaci\u00f3n de Redes Sociales Ca\u00e1 Cat\u00ed<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00eda complicado ayer en Paraje Loma Alta por incendios de pastizales. Debieron trabajar intensamente bomberos de Ca\u00e1 Cat\u00ed y de otras localidades, polic\u00edas, brigadistas de la provincia y pobladores. Un&hellip; <\/p>\n","protected":false},"author":3,"featured_media":194222,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1658],"tags":[],"class_list":["post-194214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interior"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/194214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=194214"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/194214\/revisions"}],"predecessor-version":[{"id":194253,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/194214\/revisions\/194253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/194222"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=194214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=194214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=194214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}