{"id":200903,"date":"2025-04-08T00:28:59","date_gmt":"2025-04-08T03:28:59","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=200903"},"modified":"2025-04-08T09:19:54","modified_gmt":"2025-04-08T12:19:54","slug":"fuerte-operativo-detienen-a-4-personas-y-decomisan-mas-de-24-millones-en-mercancias","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/actualidad\/fuerte-operativo-detienen-a-4-personas-y-decomisan-mas-de-24-millones-en-mercancias\/","title":{"rendered":"Fuerte operativo: detienen a 4 personas y decomisan m\u00e1s\u00a0de $24 millones en mercanc\u00edas"},"content":{"rendered":"\n<p>La Prefectura Naval Argentina llev\u00f3 adelante diversos allanamientos, en una causa por tr\u00e1fico de drogas.<\/p>\n\n\n\n<p>a Prefectura Naval Argentina inform\u00f3 este lunes que&nbsp;realiz\u00f3&nbsp;<strong>tres allanamientos<\/strong>&nbsp;simult\u00e1neos en domicilios de la ciudad correntina de Goya, donde detuvo&nbsp;a cuatro personas y secuestr\u00f3 una importante cantidad de bienes vinculados a la investigaci\u00f3n.<\/p>\n\n\n\n<p>Los operativos se dieron en el marco de una causa por tr\u00e1fico de estupefacientes, iniciada en junio de 2023, y se incautaron&nbsp;<strong>37,6 gramos de coca\u00edna, cuatro motocicletas, dos autom\u00f3viles, una pistola calibre 22, dinero en efectivo y dispositivos electr\u00f3nicos. El valor total supera los 24 millones de pesos.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/pxcdn.ellitoral.com.ar\/litoral\/042025\/1744061579947.jpeg?cw=807\" alt=\"Fuerte operativo: detienen a 4 personas y decomisan m\u00e1s\u00a0de $24 millones en mercanc\u00edas\" title=\"Fuerte operativo: detienen a 4 personas y decomisan m\u00e1s\u00a0de $24 millones en mercanc\u00edas-\"\/><\/figure>\n\n\n\n<p>Adem\u00e1s, se detuvo a dos hombres y dos mujeres que eran investigados por la causa.&nbsp;<\/p>\n\n\n\n<p>Intervinieron en la causa el Juzgado Federal de Primera Instancia, a cargo de Cristina Pozzer Penzo y la Fiscal\u00eda Federal de Primera Instancia encabezada,&nbsp;Mariano&nbsp;De Guzm\u00e1n, ambos de la ciudad de Goya.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/pxcdn.ellitoral.com.ar\/litoral\/042025\/1744061578183.jpeg?cw=807\" alt=\"Fuerte operativo: detienen a 4 personas y decomisan m\u00e1s\u00a0de $24 millones en mercanc\u00edas\" title=\"Fuerte operativo: detienen a 4 personas y decomisan m\u00e1s\u00a0de $24 millones en mercanc\u00edas-\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La Prefectura Naval Argentina llev\u00f3 adelante diversos allanamientos, en una causa por tr\u00e1fico de drogas. a Prefectura Naval Argentina inform\u00f3 este lunes que&nbsp;realiz\u00f3&nbsp;tres allanamientos&nbsp;simult\u00e1neos en domicilios de la ciudad correntina&hellip; <\/p>\n","protected":false},"author":4,"featured_media":200904,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,33],"tags":[],"class_list":["post-200903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-policiales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/200903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=200903"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/200903\/revisions"}],"predecessor-version":[{"id":200905,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/200903\/revisions\/200905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/200904"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=200903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=200903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=200903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}