{"id":206680,"date":"2025-05-09T10:20:27","date_gmt":"2025-05-09T13:20:27","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=206680"},"modified":"2025-05-09T10:20:29","modified_gmt":"2025-05-09T13:20:29","slug":"el-gobierno-fijo-por-decreto-el-salario-minimo-vital-y-movil-de-cuanto-es","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/informacion-general\/el-gobierno-fijo-por-decreto-el-salario-minimo-vital-y-movil-de-cuanto-es\/","title":{"rendered":"El Gobierno fij\u00f3 por decreto el Salario M\u00ednimo Vital y M\u00f3vil: de cu\u00e1nto es"},"content":{"rendered":"\n<p>Fue ante la falta de acuerdo entre empresarios y trabajadores.<\/p>\n\n\n\n<p>El Gobierno nacional fij\u00f3 por decreto el Salario M\u00ednimo, Vital y M\u00f3vil (SMVM) y los montos m\u00ednimos y m\u00e1ximos de la prestaci\u00f3n por desempleo debido a que el Consejo que trata el tema no alcanz\u00f3 un consenso durante su reciente sesi\u00f3n plenaria.<\/p>\n\n\n\n<p>La Resoluci\u00f3n 5\/2025 publicada hoy en el Bolet\u00edn Oficial establece los nuevos valores del SMVM para todos los trabajadores comprendidos en el R\u00e9gimen de Contrato de Trabajo, el R\u00e9gimen de Trabajo Agrario, la Administraci\u00f3n P\u00fablica Nacional y entidades del Estado empleadoras.<\/p>\n\n\n\n<p>El Consejo del Salario M\u00ednimo se hab\u00eda reunido el martes 29 de abril sin lograr acordar los nuevos montos.<\/p>\n\n\n\n<p>Ahora estos valores, excluidas las asignaciones familiares, son los siguientes:<\/p>\n\n\n\n<p>* A partir del 1\u00b0 de abril de 2025: $ 302.600 para trabajadores mensualizados a jornada completa y $ 1.513 por hora para trabajadores jornalizados.<\/p>\n\n\n\n<p>* A partir del 1\u00b0 de mayo de 2025: $ 308.200 para mensualizados y $1.541) por hora para jornalizados.<\/p>\n\n\n\n<p>* A partir del 1\u00b0 de junio de 2025: $ 313.400 para mensualizados y $ 1.567 por hora para jornalizados.<\/p>\n\n\n\n<p>* A partir del 1\u00b0 de julio de 2025: $ 317.800 para mensualizados y $ 1.589 por hora para jornalizados.<\/p>\n\n\n\n<p>* A partir del 1\u00b0 de agosto de 2025: $ 322.000 para mensualizados y $ 1.610 por hora para jornalizados.<\/p>\n\n\n\n<p>En relaci\u00f3n con la Prestaci\u00f3n por Desempleo, la resoluci\u00f3n establece que se mantendr\u00e1 la f\u00f3rmula fijada previamente. El monto ser\u00e1 equivalente a un 75% del importe neto de la mejor remuneraci\u00f3n mensual, normal y habitual de los seis (6) meses anteriores al cese del contrato de trabajo.<\/p>\n\n\n\n<p>Asimismo, se dispone que &#8220;en ning\u00fan caso la prestaci\u00f3n mensual podr\u00e1 ser inferior al 50% del Salario M\u00ednimo Vital y M\u00f3vil vigente, ni superior al CIEN POR CIENTO 100% del Salario M\u00ednimo Vital y M\u00f3vil vigente&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fue ante la falta de acuerdo entre empresarios y trabajadores. El Gobierno nacional fij\u00f3 por decreto el Salario M\u00ednimo, Vital y M\u00f3vil (SMVM) y los montos m\u00ednimos y m\u00e1ximos de&hellip; <\/p>\n","protected":false},"author":3,"featured_media":206694,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-206680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/206680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=206680"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/206680\/revisions"}],"predecessor-version":[{"id":206702,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/206680\/revisions\/206702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/206694"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=206680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=206680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=206680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}