{"id":232184,"date":"2025-10-20T16:17:20","date_gmt":"2025-10-20T19:17:20","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=232184"},"modified":"2025-10-20T16:17:28","modified_gmt":"2025-10-20T19:17:28","slug":"el-taragui-rock-2025-tendra-una-fuerte-impronta-correntina-y-regional","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/eventos\/el-taragui-rock-2025-tendra-una-fuerte-impronta-correntina-y-regional\/","title":{"rendered":"El Tarag\u00fc\u00ed Rock 2025 tendr\u00e1 una fuerte impronta correntina y regional"},"content":{"rendered":"\n<p>En el marco de la edici\u00f3n 15 del&nbsp;festival de rock m\u00e1s importante de la regi\u00f3n, en la Sala Va\u00f1ek del Instituto de Corrientes se realiz\u00f3 este lunes una conferencia de prensa para brindar detalles del esperado evento, organizado por el Gobierno de Corrientes, a trav\u00e9s del Instituto de Cultura. Cabe mencionar que el evento se llevar\u00e1 adelante el&nbsp;1 y 2 de noviembre en el Anfiteatro Cocomarola.<\/p>\n\n\n\n<p>La presidenta del Instituto de Cultura de Corrientes, Beatriz Kunin, invit\u00f3 a \u201capoyar a nuestras bandas\u201d. Adem\u00e1s, la&nbsp;titular del organismo provincial, acompa\u00f1ada por Francisco Ben\u00edtez y el productor Renzo Repetto, asegur\u00f3 que \u201cel Tarag\u00fc\u00ed Rock 2025 vuelve a encender la pasi\u00f3n por la m\u00fasica en el litoral argentino con una edici\u00f3n que celebra, m\u00e1s que nunca, el talento de Corrientes y del interior. Este a\u00f1o, el festival reafirma su compromiso con las bandas locales y regionales, d\u00e1ndoles el lugar que merecen en uno de los escenarios m\u00e1s importantes del pa\u00eds\u201d.<\/p>\n\n\n\n<p>La funcionaria se\u00f1al\u00f3 que como organizaci\u00f3n del festival \u201ctuvimos que ajustar el presupuesto debido a la situaci\u00f3n econ\u00f3mica, pero no quer\u00edan dejar de hacerlo porque es un evento importante para la ciudad, la regi\u00f3n y las provincias vecinas. Es un espacio para que las bandas emergentes se hagan conocer y puedan salir a trabajar en otras provincias, y adem\u00e1s tiene un efecto multiplicador en la econom\u00eda de la provincia, movilizando alojamiento, gastronom\u00eda, comercio, remises, pasajes y agencias de viaje\u201d.<\/p>\n\n\n\n<p>Tambi\u00e9n se refiri\u00f3 al cambio de lugar remarcando que&nbsp;\u201cla decisi\u00f3n del cambio de lugar se tom\u00f3 por practicidad y seguridad. El anfiteatro Cocomarola ya cuenta con escenario, ba\u00f1os y un espacio cercado. El a\u00f1o pasado hubo problemas con el transporte de regreso debido al estado de la Ruta Nacional 12. Por eso, se busc\u00f3 que el acceso al evento sea m\u00e1s f\u00e1cil y seguro para todos\u201d, explic\u00f3 Kunin.<\/p>\n\n\n\n<p><strong>Armado de la programaci\u00f3n<\/strong><\/p>\n\n\n\n<p>Destac\u00f3 que se recibieron m\u00e1s de mil propuestas desde distintos puntos de Argentina y pa\u00edses lim\u00edtrofes, demostrando la magnitud y el prestigio que el Tarag\u00fc\u00ed Rock alcanz\u00f3. \u201cLa selecci\u00f3n fue un verdadero desaf\u00edo: solo dos jornadas para condensar la diversidad, la energ\u00eda y la creatividad de una escena musical en constante crecimiento\u201d, asegur\u00f3.<\/p>\n\n\n\n<p>Al respecto, indic\u00f3 que el criterio fue claro: dar prioridad a los artistas de Corrientes y del interior, a las bandas emergentes y a los proyectos con trayectoria que representan la riqueza cultural de la provincia y su entorno. \u201cLa grilla refleja esa diversidad, con propuestas que van desde la capital hasta las ciudades del interior, mostrando una identidad musical amplia y en expansi\u00f3n\u201d, afirm\u00f3.<\/p>\n\n\n\n<p><strong>Diversidad de g\u00e9neros y estilos<\/strong><\/p>\n\n\n\n<p>El Tarag\u00fc\u00ed Rock 2025 propone un recorrido sonoro que abarca desde el metal, reggae y hip hop, hasta el trap, blues, ska, indie y rock and roll, mostrando la amplitud de la escena contempor\u00e1nea. Cada banda aporta su identidad, su historia y su energ\u00eda a un encuentro donde conviven lo nuevo y lo consagrado.&nbsp;<\/p>\n\n\n\n<p>&#8220;Este a\u00f1o, el escenario vuelve a ser testigo de la fuerza de la m\u00fasica de Corrientes y del interior, de su diversidad y de su proyecci\u00f3n hacia el pa\u00eds y la regi\u00f3n \u201cporque el Tarag\u00fc\u00ed Rock no solo suena: late con el coraz\u00f3n de Corrientes\u201d, sostuvieron desde la organizaci\u00f3n.<\/p>\n\n\n\n<p><strong>Entradas<\/strong><\/p>\n\n\n\n<p>Las entradas tienen un costo \u00fanico por noche de 15 mil pesos, y se pueden adquirir de lunes a viernes, de 8 a 20, en el Instituto de Cultura (San Juan 546). En tanto, el s\u00e1bado y domingo, de 17 a 22, en Centenario Shopping (Av. Ra\u00fal Alfons\u00edn 3525) y UniPlaza, el nuevo shopping de La Unidad (Moreno y Don Bosco).<\/p>\n\n\n\n<p>Est\u00e1n disponibles todas las formas de pago: efectivo, tarjetas de cr\u00e9dito y d\u00e9bito, y billeteras virtuales. Adem\u00e1s, desde el mi\u00e9rcoles se podr\u00e1n comprar tambi\u00e9n a trav\u00e9s de&nbsp;<a href=\"https:\/\/4ue34.r.sp1-brevo.net\/mk\/cl\/f\/sh\/6rqJfgq8dINmNvd2HB7mP7OK8Ju\/mXkOgoLmWWrX\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/weepas.ar\/<\/a><\/p>\n\n\n\n<p><strong>Grilla<\/strong><\/p>\n\n\n\n<p><strong>S\u00c1BADO 1\/11<\/strong><\/p>\n\n\n\n<p>Dj, Alkitran,&nbsp;(Corrientes), Monos Kabrones&nbsp;(Formosa),&nbsp;Ceci&nbsp;Mutio&nbsp;(Corrientes), Lobo del Hombres&nbsp;(Posadas),&nbsp;Francisco&nbsp;Gortari y Las \u00c1ves&nbsp;Noct\u00e1mbulas&nbsp;(Esquina),&nbsp;Manuel&nbsp;Farizano y&nbsp;Los&nbsp;Suinda&nbsp;(Goya),&nbsp;Flu Os&nbsp;(Buenos Aires),&nbsp;Kalacawas&nbsp;(Bella Vista),&nbsp;Baltasar&nbsp;Comotto y&nbsp;Emmanuel Horvilleur.&nbsp;<\/p>\n\n\n\n<p><strong>DOMINGO 2\/11<\/strong><\/p>\n\n\n\n<p>Dj,&nbsp;Deadgone&nbsp;(Ober\u00e1),&nbsp;Lenoise&nbsp;(Resistencia), Rodrigo Atroz&nbsp;\u2013 Gale&nbsp;(Corrientes),&nbsp;Filippo&nbsp;(Buenos Aires),&nbsp;La&nbsp;Chiflada&nbsp;(Corrientes),&nbsp;Hdp&nbsp;(Corrientes),&nbsp;Pelo Blues&nbsp;(Corrientes),&nbsp;Negroovs&nbsp;(Resistencia),&nbsp;Rocio&nbsp;Lens&nbsp;(Corrientes),&nbsp;Mango&nbsp;Dub&nbsp;(Corrientes),&nbsp;Kchiporros.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2025\/10\/image-683-1024x768.png\" alt=\"\" class=\"wp-image-232185\" srcset=\"https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2025\/10\/image-683-1024x768.png 1024w, https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2025\/10\/image-683-300x225.png 300w, https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2025\/10\/image-683-768x576.png 768w, https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2025\/10\/image-683-1536x1152.png 1536w, https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2025\/10\/image-683.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2025\/10\/image-684-1024x768.png\" alt=\"\" class=\"wp-image-232186\" srcset=\"https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2025\/10\/image-684-1024x768.png 1024w, https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2025\/10\/image-684-300x225.png 300w, https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2025\/10\/image-684-768x576.png 768w, https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2025\/10\/image-684-1536x1152.png 1536w, https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2025\/10\/image-684.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de la edici\u00f3n 15 del&nbsp;festival de rock m\u00e1s importante de la regi\u00f3n, en la Sala Va\u00f1ek del Instituto de Corrientes se realiz\u00f3 este lunes una conferencia de&hellip; <\/p>\n","protected":false},"author":8,"featured_media":232187,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-232184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/232184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=232184"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/232184\/revisions"}],"predecessor-version":[{"id":232188,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/232184\/revisions\/232188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/232187"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=232184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=232184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=232184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}