{"id":233364,"date":"2025-10-28T12:48:47","date_gmt":"2025-10-28T15:48:47","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=233364"},"modified":"2025-10-28T13:46:19","modified_gmt":"2025-10-28T16:46:19","slug":"leandro-garcia-el-exnovio-de-lourdes-fernandez-seguira-preso-los-detalles-de-la-decision-judicial","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/espectaculos\/leandro-garcia-el-exnovio-de-lourdes-fernandez-seguira-preso-los-detalles-de-la-decision-judicial\/","title":{"rendered":"Leandro Garc\u00eda, el exnovio de Lourdes Fern\u00e1ndez, seguir\u00e1 preso: los detalles de la decisi\u00f3n judicial"},"content":{"rendered":"\n<p>El hombre est\u00e1 detenido desde el jueves a la noche, cuando la polic\u00eda irrumpi\u00f3 en su casa de Palermo.<\/p>\n\n\n\n<p>El exnovio de la cantante <strong>Lourdes Fern\u00e1ndez<\/strong>,\u00a0<strong>Leandro Garc\u00eda G\u00f3mez<\/strong>, seguir\u00e1 preso por decisi\u00f3n del juez\u00a0<strong>Diego Javier Slupski<\/strong>.<\/p>\n\n\n\n<p><strong>El hombre est\u00e1 preso desde el jueves a la noche<\/strong>, cuando la Polic\u00eda irrumpi\u00f3 en su casa de Palermo para buscar a la artista musical que no tuvo contacto con su familia durante 19 d\u00edas.&nbsp;<strong>Lo acusan de privaci\u00f3n ileg\u00edtima de la libertad.<\/strong><\/p>\n\n\n\n<p>El escrito del magistrado al que accedi\u00f3\u00a0<strong> Show<\/strong>\u00a0indica que Slupski no hizo lugar al pedido de excarcelaci\u00f3n que hab\u00eda promovido la defensa de la expareja de la integrante del grupo Bandana \u201c<strong>bajo ning\u00fan tipo de condici\u00f3n ni cauci\u00f3n\u201d<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/tn.com.ar\/resizer\/v2\/el-exnovio-de-lourdes-de-bandana-fue-detenido-el-jueves-a-la-noche-foto-policia-de-la-ciudad-5HSGU7PBE5AXJO5DQJHSI2DO5Y.jpg?auth=432978ab3a2fa48fabaa48cbee649639a4854e34b6e5bc2d06e5f805bede5c65&amp;width=767\" alt=\"El exnovio de Lourdes de Bandana fue detenido el jueves a la noche. (Foto: Polic\u00eda de la Ciudad)\"\/><\/figure>\n\n\n\n<p>As\u00ed, el juez sigui\u00f3 el pedido de Silvana Russi, la responsable de la&nbsp;<strong>Fiscal\u00eda Nacional en lo Criminal y Correccional N\u00b043<\/strong>. La fiscal hab\u00eda solicitado que Garc\u00eda continuara preso.<\/p>\n\n\n\n<p>\u201cLas graves caracter\u00edsticas de los hechos investigados, la naturaleza del delito que se le atribuye a Garc\u00eda G\u00f3mez y la actitud asumida por \u00e9ste constituyen<strong>&nbsp;indicios suficientes para considerar que no se someter\u00e1 a la persecuci\u00f3n penal\u201d<\/strong>, fue uno de los fundamentos del dictamen que, finalmente, resolvi\u00f3 el juez.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qu\u00e9 dice el informe de los especialistas que evaluaron a Lourdes de Bandana<\/h2>\n\n\n\n<p>Este lunes se supo que la&nbsp;<strong>Oficina de Violencia Dom\u00e9stica (OVD)<\/strong>&nbsp;elabor\u00f3 un informe sobre la situaci\u00f3n de Lourdes Fern\u00e1ndez en el que estableci\u00f3 que la artista se encuentra en una&nbsp;<strong>situaci\u00f3n de \u201calto riesgo\u201d<\/strong>.<\/p>\n\n\n\n<p>El documento, realizado por un equipo interdisciplinario de profesionales de la psicolog\u00eda, el trabajo social y el derecho, describe&nbsp;<strong>un contexto de vulnerabilidad extrema<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/tn.com.ar\/resizer\/v2\/leandro-garcia-gomez-esta-imputado-de-los-delitos-de-privacion-ilegal-de-la-libertad-y-lesiones-en-contexto-de-violencia-de-genero-foto-instagramlowrdez-PIOO3PZRRFGXLKDM5AXKY3JMNI.jpg?auth=46465e8a3730a04cbf48390c851ae3bc72fffb9600a8964263620c3233e9e36d&amp;width=767\" alt=\"Leandro Garc\u00eda G\u00f3mez est\u00e1 imputado de los delitos de privaci\u00f3n ilegal de la libertad y lesiones en contexto de violencia de g\u00e9nero. (Foto: instagram\/lowrdez)\"\/><\/figure>\n\n\n\n<p>De acuerdo a los especialistas, en el testimonio de la cantante se observan&nbsp;<strong>patrones de control, aislamiento y sometimiento psicol\u00f3gico<\/strong>&nbsp;que suelen estar presentes en los v\u00ednculos abusivos.<\/p>\n\n\n\n<p>Aunque&nbsp;<strong>Lourdes Fern\u00e1ndez<\/strong>&nbsp;neg\u00f3 haber sido agredida f\u00edsicamente por su expareja,&nbsp;<strong>Leandro Garc\u00eda G\u00f3mez<\/strong>, los peritos interpretaron su declaraci\u00f3n como la de&nbsp;<strong>\u201cuna mujer manipulada por el violento\u201d<\/strong>, una figura que enmarca el impacto emocional y la dependencia que pueden generar las relaciones de dominaci\u00f3n.<\/p>\n\n\n\n<p>Ante los resultados del informe,&nbsp;<strong>Yamil Castro Bianchi<\/strong>, abogado de la madre de la artista, pedir\u00e1 que Lourdes&nbsp;<strong>vuelva a declarar<\/strong>, esta vez como&nbsp;<strong>posible v\u00edctima de delitos relacionados con la trata de personas<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El hombre est\u00e1 detenido desde el jueves a la noche, cuando la polic\u00eda irrumpi\u00f3 en su casa de Palermo. El exnovio de la cantante Lourdes Fern\u00e1ndez,\u00a0Leandro Garc\u00eda G\u00f3mez, seguir\u00e1 preso&hellip; <\/p>\n","protected":false},"author":8,"featured_media":233365,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-233364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/233364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=233364"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/233364\/revisions"}],"predecessor-version":[{"id":233366,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/233364\/revisions\/233366"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/233365"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=233364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=233364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=233364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}