{"id":233659,"date":"2025-10-29T23:19:47","date_gmt":"2025-10-30T02:19:47","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=233659"},"modified":"2025-10-29T23:19:54","modified_gmt":"2025-10-30T02:19:54","slug":"quien-fue-el-segundo-eliminado-de-la-cuarta-temporada-de-masterchef-celebrity","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/espectaculos\/quien-fue-el-segundo-eliminado-de-la-cuarta-temporada-de-masterchef-celebrity\/","title":{"rendered":"\u00bfQui\u00e9n fue el segundo eliminado de la cuarta temporada de MasterChef Celebrity?"},"content":{"rendered":"\n<p>Un participante dej\u00f3 el certamen por decisi\u00f3n del jurado. Ahora 22 concursantes contin\u00faan en carrera.<\/p>\n\n\n\n<p>La competencia en MasterChef Celebrity Argentina 2025 se pone cada vez m\u00e1s exigente y este martes se conoci\u00f3 el nombre del segundo eliminado de la temporada. En una gala cargada de tensi\u00f3n, Esteban Mirol qued\u00f3 fuera del reality culinario de Telefe tras no convencer al jurado con su plato agridulce.<\/p>\n\n\n\n<p><br>El periodista de extensa trayectoria que forma parte de Telefe Noticias no hizo pie en la gala decisiva con un plato de cerdo con pur\u00e9.<br>&nbsp;<br><br>El desaf\u00edo de la segunda gala de eliminaci\u00f3n fue de cocina agridulce. El jurado les pidi\u00f3 a los participantes un plato que otorgue esas sensaciones a modo de eufemismo por lo que ellos pod\u00edan sentir teniendo que luchar por mantener su lugar en la competencia al mismo tiempo en el que otros compa\u00f1eros est\u00e1n c\u00f3modos en el balc\u00f3n.<br>&nbsp;&nbsp;<br>&nbsp;<br>&#8220;Ya sea fresca, deshidratada o en cualquiera de sus formas&#8221;, resalt\u00f3 Martitegui antes de que los concursantes comenzaran con el reto de la jornada.<\/p>\n\n\n\n<p>Los platos m\u00e1s destacados de la noche fueron los de La Joaqui, quien se inclin\u00f3 por un gazpacho de camarones, y el Turco Husain, que present\u00f3 solomillo de cerdo con batatas asadas, salsa de maracuy\u00e1 y ensalada fresca.<\/p>\n\n\n\n<p>Por su parte, Momi Giardina se luci\u00f3 al cocinar matambrito de cerdo con guarnici\u00f3n de esp\u00e1rragos y pickles de frambuesa mientras que Sof\u00eda &#8220;La Reini&#8221; Gonet no se qued\u00f3 atr\u00e1s con su ribs de cerdo con chutney de manzana y papas pay.<\/p>\n\n\n\n<p>Maxi L\u00f3pez, Sof\u00eda Mart\u00ednez, Ian Lucas y Agust\u00edn &#8220;Cachete&#8221; Sierra integraron el segundo grupo de concursantes salvados.<\/p>\n\n\n\n<p>Por otro lado, los platos menos logrados de la jornada fueron los de Julia Calvo, Esteban Mirol y Miguel \u00c1ngel Rodr\u00edguez.<\/p>\n\n\n\n<p>Sin embargo, el jurado decidi\u00f3 darle una segunda oportunidad a la actriz, dejando a su colega y al periodista al borde de la eliminaci\u00f3n del reality culinario.<\/p>\n\n\n\n<p>De esta manera, por decisi\u00f3n de Dami\u00e1n Betular, Germ\u00e1n Martitegui y Donato De Santis , Esteban Mirol abandon\u00f3 MasterChef Celebrity.<\/p>\n\n\n\n<p>El propio Germ\u00e1n fue quien comenz\u00f3 la despedida para el periodista. &#8220;Es dif\u00edcil despedirse en esta instancia, s\u00e9 que uno piensa que &#8220;falt\u00f3 un poco m\u00e1s\u2019. Sos una persona muy querida en esta casa, en Telefe. Fue una alegr\u00eda conocerte&#8221;, coment\u00f3 el chef.<\/p>\n\n\n\n<p>&#8220;Gracias por haberme invitado a MasterChef. Y bueno, las cosas salieron mal pero acepto la decisi\u00f3n. Yo recib\u00ed siempre todos los mensajes de ustedes, y eso es algo que me interesa dejarlo en claro porque si no pareciera que no lo tom\u00e9 en serio y yo me tom\u00e9 esta competencia muy e nserio&#8221;, le comunic\u00f3 Mirol a los tres jurados del reality culinario al momento de despedirse del programa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un participante dej\u00f3 el certamen por decisi\u00f3n del jurado. Ahora 22 concursantes contin\u00faan en carrera. La competencia en MasterChef Celebrity Argentina 2025 se pone cada vez m\u00e1s exigente y este&hellip; <\/p>\n","protected":false},"author":4,"featured_media":233660,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-233659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/233659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=233659"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/233659\/revisions"}],"predecessor-version":[{"id":233661,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/233659\/revisions\/233661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/233660"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=233659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=233659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=233659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}