{"id":234546,"date":"2025-11-04T21:55:50","date_gmt":"2025-11-05T00:55:50","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=234546"},"modified":"2025-11-04T21:55:52","modified_gmt":"2025-11-05T00:55:52","slug":"por-que-se-derrumba-el-bitcoin-y-hasta-cuando-puede-durar-el-fenomeno","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/economia\/por-que-se-derrumba-el-bitcoin-y-hasta-cuando-puede-durar-el-fenomeno\/","title":{"rendered":"Por qu\u00e9 se derrumba el bitcoin y hasta cu\u00e1ndo puede durar el fen\u00f3meno"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Las principales criptomonedas afrontan escenarios negativos.<\/h2>\n\n\n\n<p>El&nbsp;<strong>bitcoin<\/strong>&nbsp;cay\u00f3 6% este martes en la bolsa de Wall Street y cotizaba por debajo de los&nbsp;<strong>US$ 100.000<\/strong>&nbsp;por primera vez desde junio.<\/p>\n\n\n\n<p>LLeg\u00f3 a bajar a&nbsp;<strong>99.966 d\u00f3lares<\/strong>, aunque luego limit\u00f3 su descenso y pas\u00f3 a cotizar apenas por encima de los 101.344 d\u00f3lares.<\/p>\n\n\n\n<p>La ca\u00edda lleva el descenso de los \u00faltimos siete d\u00edas a un rojo del&nbsp;<mark>11,38%<\/mark>.&nbsp;<\/p>\n\n\n\n<p>En el mercado lo adjudican a la&nbsp;<mark>preocupaci\u00f3n de los inversores sobre la sostenibilidad de las valoraciones burs\u00e1tiles, impulsadas por el sector de la inteligencia artificial (IA).<\/mark><\/p>\n\n\n\n<p>Seg\u00fan Forbes, el movimiento a la baja comenz\u00f3 a mediados de octubre, luego de que la Reserva Federal redujo las tasas de inter\u00e9s.&nbsp;<\/p>\n\n\n\n<p>A esa situaci\u00f3n se suma la incertidumbre sobre lo que har\u00e1 el banco central de Estados Unidos con las tasas en diciembre.<\/p>\n\n\n\n<p>Para Katie Stockton, fundadora y socia directora de la firma Fairlead Strategies, el impulso a largo plazo del bitcoin sigue siendo positivo.<\/p>\n\n\n\n<p>As\u00ed, fij\u00f3 como posible precio de la criptomoneda a largo plazo los 134.500 d\u00f3lares.<\/p>\n\n\n\n<p>La din\u00e1mica negativa de bitcoin es similar a la que experimentan en los \u00faltimos d\u00edas las otras criptomonedas.&nbsp;<\/p>\n\n\n\n<p><mark>Ehereum ca\u00eda 10,96%, por lo que acumulaba un rojo de 21% en la \u00faltima semana.<\/mark><\/p>\n\n\n\n<p><strong>Solana, en tanto, se precipitaba un 6,7% en las \u00faltimas 24 horas, extendiendo el rojo semanal a 20,5%.<\/strong><\/p>\n\n\n\n<p>El movimiento de las otras cripto era similar: Dogecoin ca\u00eda un 4,2% (20,25% semanal), Cardano lo hac\u00eda un 6,5% (21,2% en la semana) y Tron se derrumbaba ca\u00edda un 0,2%, llevando su movimiento a la baja hasta un 6m7% en la semana.<\/p>\n\n\n\n<p>Entre las stablecoins, Tether USDt cotizaba apenas en rojo (un 0,04% a las 18 de Argentina) y USDC mostraba un leve verde de 0,04%.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las principales criptomonedas afrontan escenarios negativos. El&nbsp;bitcoin&nbsp;cay\u00f3 6% este martes en la bolsa de Wall Street y cotizaba por debajo de los&nbsp;US$ 100.000&nbsp;por primera vez desde junio. LLeg\u00f3 a bajar&hellip; <\/p>\n","protected":false},"author":4,"featured_media":234547,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-234546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/234546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=234546"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/234546\/revisions"}],"predecessor-version":[{"id":234548,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/234546\/revisions\/234548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/234547"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=234546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=234546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=234546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}