{"id":234823,"date":"2025-11-06T14:03:20","date_gmt":"2025-11-06T17:03:20","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=234823"},"modified":"2025-11-06T14:03:47","modified_gmt":"2025-11-06T17:03:47","slug":"desmienten-version-viral-sobre-la-partida-de-lali-esposito-del-pais","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/nacionales\/desmienten-version-viral-sobre-la-partida-de-lali-esposito-del-pais\/","title":{"rendered":"DESMIENTEN VERSI\u00d3N VIRAL SOBRE LA PARTIDA DE LALI ESP\u00d3SITO DEL PA\u00cdS"},"content":{"rendered":"\n<p>(Corresponsal\u00eda Buenos Aires) &#8211; En las \u00faltimas horas se viraliz\u00f3 en redes sociales una publicaci\u00f3n que aseguraba que la cantante y actriz Lali Esp\u00f3sito habr\u00eda abandonado la Argentina rumbo a Europa, acompa\u00f1ada de una supuesta declaraci\u00f3n pol\u00edtica: \u201cMe voy a vivir a Europa chicos, pero les prometo que en 2027 vuelvo cuando le saquemos a Milei\u201d.<\/p>\n\n\n\n<p>Sin embargo, la informaci\u00f3n es falsa. No existen declaraciones oficiales de Lali Esp\u00f3sito ni comunicados de prensa que confirmen su salida del pa\u00eds ni la frase adjudicada. La imagen utilizada en la publicaci\u00f3n corresponde a una foto antigua de la artista en un aeropuerto y fue reutilizada fuera de contexto.<\/p>\n\n\n\n<p>Fuentes cercanas a la artista desmintieron cualquier tipo de mudanza definitiva o mensaje pol\u00edtico reciente.<\/p>\n\n\n\n<p>Una vez m\u00e1s, este episodio refleja c\u00f3mo las noticias falsas se propagan r\u00e1pidamente en redes sociales, generando confusi\u00f3n entre los usuarios. Se recomienda siempre verificar la informaci\u00f3n antes de compartirla.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Corresponsal\u00eda Buenos Aires) &#8211; En las \u00faltimas horas se viraliz\u00f3 en redes sociales una publicaci\u00f3n que aseguraba que la cantante y actriz Lali Esp\u00f3sito habr\u00eda abandonado la Argentina rumbo a&hellip; <\/p>\n","protected":false},"author":11,"featured_media":234824,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,10],"tags":[],"class_list":["post-234823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-nacionales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/234823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=234823"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/234823\/revisions"}],"predecessor-version":[{"id":234825,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/234823\/revisions\/234825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/234824"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=234823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=234823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=234823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}