{"id":235227,"date":"2025-11-09T22:33:04","date_gmt":"2025-11-10T01:33:04","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=235227"},"modified":"2025-11-09T22:33:19","modified_gmt":"2025-11-10T01:33:19","slug":"red-de-trata-sexual-vinculada-al-turismo-en-paso-de-la-patria-hay-tres-nuevos-detenidos","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/policiales\/red-de-trata-sexual-vinculada-al-turismo-en-paso-de-la-patria-hay-tres-nuevos-detenidos\/","title":{"rendered":"Red de trata sexual vinculada al turismo en Paso de la Patria: hay tres nuevos detenidos"},"content":{"rendered":"\n<p>Entre los apresados hay una mujer del Servicio Penitenciario de Corrientes, su pareja y un gu\u00eda de pesca. La organizaci\u00f3n captaba j\u00f3venes vulnerables y las trasladaba a fiestas privadas con turistas extranjeros.<\/p>\n\n\n\n<p>La Polic\u00eda Federal Argentina (PFA) detuvo este viernes a tres personas en el marco de la investigaci\u00f3n por una red de trata de personas con fines de explotaci\u00f3n sexual que operaba entre la ciudad de Corrientes y Paso de la Patria.<\/p>\n\n\n\n<p>Con estas detenciones, ya son cinco los involucrados puestos a disposici\u00f3n de la Justicia Federal, que investiga un esquema delictivo vinculado a fiestas privadas con turistas, principalmente brasile\u00f1os.<\/p>\n\n\n\n<p>Seg\u00fan trascendi\u00f3, entre los nuevos detenidos se encuentran una agente del Servicio Penitenciario Provincial (SPP), su esposo y un gu\u00eda de pesca que colaboraba con el traslado de las v\u00edctimas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Una investigaci\u00f3n que lleva meses<\/h2>\n\n\n\n<p>De acuerdo con fuentes judiciales, la causa se inici\u00f3 hace al menos cinco meses, a partir de datos obtenidos por la Divisi\u00f3n Unidad Operativa de Investigaciones Especiales de la PFA. Los investigadores lograron identificar puntos de captaci\u00f3n de mujeres j\u00f3venes en situaci\u00f3n econ\u00f3mica vulnerable, que luego eran trasladadas hacia Paso de la Patria para participar de eventos con fines sexuales.<\/p>\n\n\n\n<p>Las pesquisas se\u00f1alaron dos lugares claves: una est\u00e9tica ubicada en inmediaciones de avenida Chacabuco y Cazadores Correntinos, y una casa de tatuajes regenteada por una pareja joven. Tambi\u00e9n se detect\u00f3 movimiento en un boliche de una quinta sobre avenida Ra\u00fal Alfons\u00edn, donde se reclutaba y seleccionaba a las v\u00edctimas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El rol del Servicio Penitenciario<\/h2>\n\n\n\n<p>Uno de los aspectos m\u00e1s delicados del caso involucra al Servicio Penitenciario Provincial, donde una funcionaria \u2014hermanastra de una de las principales captadoras\u2014 habr\u00eda reclutado a mujeres dentro de la misma instituci\u00f3n.<\/p>\n\n\n\n<p>Las investigaciones indican que la red manejaba un grupo de al menos 80 mujeres, que eran rotadas seg\u00fan la demanda de los &#8220;clientes&#8221;. No se descarta la participaci\u00f3n de menores de edad, un dato que podr\u00eda confirmarse con la apertura de los tel\u00e9fonos secuestrados durante los allanamientos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">V\u00edctimas enga\u00f1adas y explotaci\u00f3n sistem\u00e1tica<\/h2>\n\n\n\n<p>En los operativos, la PFA rescat\u00f3 a una joven correntina, quien relat\u00f3 haber sido enga\u00f1ada con la promesa de asistir a una fiesta privada. Una vez en el lugar, cont\u00f3 que comenzaron a embriagarla y luego a ofrecerla a los turistas extranjeros.<\/p>\n\n\n\n<p>Otra testigo explic\u00f3 que las mujeres deb\u00edan entregar la totalidad del dinero del primer &#8220;pase&#8221; a las captadoras y, en los siguientes, aportar un porcentaje fijo. Las que intentaban salirse de la red eran presionadas o amenazadas para continuar.<\/p>\n\n\n\n<p>Los fines de semana, las v\u00edctimas eran llevadas al boliche donde se realizaban los contactos con los clientes, y desde all\u00ed eran trasladadas en combis hasta Paso de la Patria, donde se concretaban los encuentros.<\/p>\n\n\n\n<p>Las autoridades federales contin\u00faan con la investigaci\u00f3n para determinar la magnitud total de la red, la identificaci\u00f3n de todos los implicados y la asistencia integral a las v\u00edctimas rescatadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre los apresados hay una mujer del Servicio Penitenciario de Corrientes, su pareja y un gu\u00eda de pesca. La organizaci\u00f3n captaba j\u00f3venes vulnerables y las trasladaba a fiestas privadas con&hellip; <\/p>\n","protected":false},"author":4,"featured_media":235228,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-235227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/235227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=235227"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/235227\/revisions"}],"predecessor-version":[{"id":235229,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/235227\/revisions\/235229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/235228"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=235227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=235227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=235227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}