{"id":235304,"date":"2025-11-10T15:30:42","date_gmt":"2025-11-10T18:30:42","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=235304"},"modified":"2025-11-10T15:31:13","modified_gmt":"2025-11-10T18:31:13","slug":"la-justicia-espera-una-pericia-clave-sobre-posibles-inconsistencias-en-las-declaraciones-juradas-de-cfk","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/crimen-y-justicia\/la-justicia-espera-una-pericia-clave-sobre-posibles-inconsistencias-en-las-declaraciones-juradas-de-cfk\/","title":{"rendered":"La Justicia espera una pericia clave sobre posibles inconsistencias en las declaraciones juradas de CFK"},"content":{"rendered":"\n<p>Mientras avanza el juicio por la causa Cuadernos, a la exmandataria se le abre otro frente judicial. La causa se centra en el per\u00edodo de sus presidencias, desde 2009 a 2015.<a href=\"https:\/\/tn.com.ar\/autor\/Brunoyacono\/\"><\/a><\/p>\n\n\n\n<p>Mientras avanza el\u00a0<strong>juicio por la<\/strong>\u00a0<strong>causa Cuadernos<\/strong>, la\u00a0<strong>Justicia\u00a0<\/strong>espera un\u00a0<strong>informe pericial<\/strong>\u00a0que podr\u00eda sumar nuevos elementos al frente judicial de la expresidenta\u00a0<strong>Cristina Kirchner<\/strong>.<\/p>\n\n\n\n<p>Fuentes judiciales informaron \u00a0que esta semana podr\u00eda llegar a la fiscal\u00eda de\u00a0<strong>Gerardo Pollicita<\/strong>\u00a0un\u00a0<strong>peritaje contable<\/strong>\u00a0destinado a determinar si existieron o no\u00a0<strong>inconsistencias en las declaraciones juradas<\/strong>\u00a0que la exjefa de Estado present\u00f3 ante la\u00a0<strong>Oficina Anticorrupci\u00f3n<\/strong>\u00a0(OA) durante el per\u00edodo bajo estudio.<\/p>\n\n\n\n<p>De acuerdo con los primeros resultados del an\u00e1lisis,&nbsp;<strong>los peritos detectaron irregularidades formales<\/strong>&nbsp;en algunos de los documentos. Seg\u00fan trascendi\u00f3, el informe mencionar\u00eda&nbsp;<strong>\u201ccasillas en blanco que no permiten identificar correctamente los bienes inmuebles\u201d<\/strong>, adem\u00e1s de&nbsp;<strong>ausencia de documentaci\u00f3n respaldatoria<\/strong>, como declaraciones juradas de ganancias o tr\u00e1mites sucesorios vinculados al patrimonio familiar.<\/p>\n\n\n\n<p>El estudio, que se encuentra en etapa de revisi\u00f3n final,&nbsp;<strong>no investiga un posible enriquecimiento il\u00edcito<\/strong>, sino que apunta a&nbsp;<strong>verificar la consistencia y completitud de la informaci\u00f3n patrimonial<\/strong>&nbsp;presentada por Cristina Kirchner ante los organismos de control.<\/p>\n\n\n\n<p>Entre los puntos se\u00f1alados, el peritaje habr\u00eda advertido que&nbsp;<strong>no se incorporaron las declaraciones juradas ante la AFIP correspondientes a la sucesi\u00f3n de N\u00e9stor Kirchner<\/strong>, fallecido en 2010, lo que impedir\u00eda reconstruir con precisi\u00f3n el traspaso y evoluci\u00f3n de determinados bienes. En ese sentido, el informe alude a&nbsp;<strong>\u201cespacios en blanco\u201d&nbsp;<\/strong>en los formularios de la expresidenta, en los que deb\u00eda consignarse informaci\u00f3n sobre inmuebles.<\/p>\n\n\n\n<p>Una vez remitido el documento a la fiscal\u00eda,&nbsp;<strong>Pollicita evaluar\u00e1 si los hallazgos ameritan nuevas medidas<\/strong>&nbsp;dentro del expediente o si las observaciones pueden considerarse meramente administrativas. La causa se origin\u00f3 tras una denuncia por presuntas inconsistencias patrimoniales, y su avance qued\u00f3&nbsp;<strong>en suspenso<\/strong>&nbsp;mientras se resolv\u00edan peritajes y pedidos de documentaci\u00f3n complementaria.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/tn.com.ar\/resizer\/v2\/cristina-kirchner-debio-aparecer-en-camara-en-el-comienzo-del-juicio-por-la-causa-cuadernos-foto-captura-tn-5WAFDZ4KD5HIHPYPJOTJVTYYSI.png?auth=4c675a96b79cb606ef0451fb7b23627398ddda5dc12bf97fbcf9cf0c27fd32e3&amp;width=767\" alt=\"Cristina Kirchner debi\u00f3 aparecer en c\u00e1mara en el comienzo del juicio por la Causa Cuadernos (Foto: captura TN).\"\/><\/figure>\n\n\n\n<p>El nuevo informe llega en un momento judicial especialmente sensible para Cristina Kirchner. El jueves pasado comenz\u00f3 el<strong>&nbsp;juicio oral por la causa Cuadernos<\/strong>, que investiga un presunto&nbsp;<strong>sistema de pago de sobornos vinculados a la obra p\u00fablica&nbsp;<\/strong>durante los gobiernos kirchneristas.<\/p>\n\n\n\n<p>El proceso est\u00e1 a cargo del&nbsp;<strong>Tribunal Oral Federal N\u00b07<\/strong>, integrado por Enrique M\u00e9ndez Signori, Fernando Canero y Germ\u00e1n Castelli, y tiene&nbsp;<strong>174 procesados<\/strong>, entre exfuncionarios y empresarios, de los cuales&nbsp;<strong>26 se presentaron como arrepentidos<\/strong>. En total, se analizan&nbsp;<strong>540 hechos<\/strong>&nbsp;y&nbsp;<strong>26 calificaciones legales distintas<\/strong>&nbsp;seg\u00fan la participaci\u00f3n de cada acusado.<\/p>\n\n\n\n<p>Uno de los testigos clave ser\u00e1&nbsp;<strong>Ernesto Clarens<\/strong>, hist\u00f3rico financista del kirchnerismo, quien se acogi\u00f3 al r\u00e9gimen del arrepentido y deber\u00e1 ratificar sus dichos para mantener su acuerdo con la fiscal\u00eda. Clarens declar\u00f3 que&nbsp;<strong>recib\u00eda dinero de empresarios de la construcci\u00f3n<\/strong>&nbsp;\u2014unos&nbsp;<strong>300.000 d\u00f3lares por semana<\/strong>, seg\u00fan su relato\u2014, lo convert\u00eda en divisas y luego lo entregaba a&nbsp;<strong>Daniel Mu\u00f1oz<\/strong>, secretario privado de N\u00e9stor Kirchner.<\/p>\n\n\n\n<p>En su testimonio, el financista describi\u00f3 que las entregas se realizaban en el&nbsp;<strong>Hotel Panamericano o en el domicilio de Juncal y Uruguay<\/strong>, donde viv\u00eda el matrimonio Kirchner. Tambi\u00e9n sostuvo que parte del dinero era trasladado a&nbsp;<strong>El Calafate en aviones oficiales<\/strong>, y que se guardaba en una b\u00f3veda ubicada en la vivienda del expresidente.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras avanza el juicio por la causa Cuadernos, a la exmandataria se le abre otro frente judicial. La causa se centra en el per\u00edodo de sus presidencias, desde 2009 a&hellip; <\/p>\n","protected":false},"author":8,"featured_media":235308,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,5],"tags":[],"class_list":["post-235304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-crimen-y-justicia"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/235304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=235304"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/235304\/revisions"}],"predecessor-version":[{"id":235309,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/235304\/revisions\/235309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/235308"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=235304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=235304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=235304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}