{"id":23730,"date":"2022-11-29T12:39:18","date_gmt":"2022-11-29T15:39:18","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=23730"},"modified":"2022-11-29T12:40:37","modified_gmt":"2022-11-29T15:40:37","slug":"este-domingo-se-correra-una-nueva-edicion-del-san-antonio-trail-en-loreto","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/informacion-general\/este-domingo-se-correra-una-nueva-edicion-del-san-antonio-trail-en-loreto\/","title":{"rendered":"Este domingo se correr\u00e1 una nueva edici\u00f3n del San Antonio Trail en Loreto"},"content":{"rendered":"\n<p>Una nueva edici\u00f3n del San Antonio Trail se correr\u00e1 este domingo 4 de diciembre en el portal hom\u00f3nimo en Loreto, Corrientes. Las distancias competitivas son de 15k y 21k, mientras que tambi\u00e9n habr\u00e1 otra participativa de 5k. Este martes se present\u00f3 el evento en Casa de Gobierno con la presencia de la ministra de Turismo, Alejandra Eliciri y el intendente de Loreto, Orlando Maidana.<\/p>\n\n\n\n<p>La competencia se da en el marco del cierre del circuito correntino de running y tendr\u00e1 uno de los escenarios ideales para los atletas, viviendo una experiencia \u00fanica en los Esteros del Iber\u00e1. A su vez, esta actividad dar\u00e1 visibilidad a uno de los atractivos caracter\u00edsticos de nuestra provincia, ya que se aguarda la participaci\u00f3n de m\u00e1s de 300 runners de todo el pa\u00eds.<\/p>\n\n\n\n<p>El intendente Maidana coment\u00f3 que las plazas hoteleras est\u00e1n completas por este evento, que forma parte de las actividades por las Fiestas Patronales.<\/p>\n\n\n\n<p>El turismo de naturaleza en Corrientes tuvo gran posicionamiento en los \u00faltimos a\u00f1os, donde este tipo de encuentros deportivos, adem\u00e1s de generar un \u00e1mbito de camarader\u00eda entre los atletas, tiene un mensaje conservacionista sobre los ambientes naturales. Y, al mismo tiempo, despierta el inter\u00e9s de los participantes para descubrir este potencial correntino para disfrutarlo en cualquier momento del a\u00f1o.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>La ministra de Turismo declar\u00f3 en la presentaci\u00f3n que esta competencia fomenta la pr\u00e1ctica deportiva amateur, promoviendo el turismo en Loreto y mostrando todo lo que tiene para ofrecer.<\/p>\n\n\n\n<p>Se trata de la segunda vez que se corre en este sitio, siendo la primera bajo la denominaci\u00f3n de San Antonio Trail. Todo lo recaudado ser\u00e1 donado a los Bomberos Voluntarios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una nueva edici\u00f3n del San Antonio Trail se correr\u00e1 este domingo 4 de diciembre en el portal hom\u00f3nimo en Loreto, Corrientes. Las distancias competitivas son de 15k y 21k, mientras&hellip; <\/p>\n","protected":false},"author":4,"featured_media":23734,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-23730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/23730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=23730"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/23730\/revisions"}],"predecessor-version":[{"id":23733,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/23730\/revisions\/23733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/23734"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=23730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=23730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=23730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}