{"id":23960,"date":"2022-11-30T09:51:38","date_gmt":"2022-11-30T12:51:38","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=23960"},"modified":"2022-11-30T09:51:43","modified_gmt":"2022-11-30T12:51:43","slug":"dia-nacional-del-mate-por-que-se-celebra-este-30-de-noviembre","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/informacion-general\/dia-nacional-del-mate-por-que-se-celebra-este-30-de-noviembre\/","title":{"rendered":"D\u00eda Nacional del Mate: por qu\u00e9 se celebra este 30 de noviembre"},"content":{"rendered":"\n<p>Se trata de la infusi\u00f3n m\u00e1s arraigadas en la psiquis nacional. Anualmente, los argentinos consumen 280 millones de kilos de yerba por a\u00f1o.<\/p>\n\n\n\n<p>Cada 30 de noviembre se celebra el D\u00eda Nacional del Mate, la bebida consumida en el 90% de los hogares argentinos. Se cree que en el pa\u00eds se consumen, por persona, m\u00e1s litros de esta infusi\u00f3n que de agua por persona por d\u00eda.&nbsp;<\/p>\n\n\n\n<p>La fecha conmemora &nbsp;al caudillo Andr\u00e9s &#8220;Andresito&#8221; Guacurar\u00ed y Artigas, impulsor de la producci\u00f3n y distribuci\u00f3n de la yerba mate, y \u00fanico gobernador ind\u00edgena que hubo en el pa\u00eds.&nbsp;<\/p>\n\n\n\n<p>Seg\u00fan el Instituto Nacional de la Yerba Mate (INYM), &#8220;Andresito&#8221; consideraba a la yerba mate un elemento central del aparato productivo por lo que busc\u00f3 centralizar su cultivo y comercializaci\u00f3n en mano de los guaran\u00edes.<\/p>\n\n\n\n<p>La festividad se conmemora desde el a\u00f1o 2015, cuando el Congreso sancion\u00f3 la Ley 27.117 que estableci\u00f3 al 30 de noviembre como el D\u00eda Nacional del Mate.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.lt7noticias.com\/content\/bucket\/3\/13973w770h433c.jpg.webp\" alt=\"\"\/><\/figure>\n\n\n\n<p><strong>MITOS Y DATOS CURIOSOS SOBRE EL MATE<\/strong><br>1 &#8211; &#8220;El mate baja el colesterol y es bueno para el coraz\u00f3n&#8221;: si bien el mate aporta polifenoles, vitaminas y minerales, no existe evidencia cientifica de que pueda reducir los niveles de colesterol.<\/p>\n\n\n\n<p>2 &#8211; &#8220;Tomar mate ayuda a bajar de peso&#8221;: el mate no funciona como m\u00e9todo de descenso de peso porque no hay alimentos que adelgacen o engorden. Si no es consumido con az\u00facar, puede ingerirse en planes nutricionales bajos en carbohidratos.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.lt7noticias.com\/content\/bucket\/6\/11026w770h433c.jpg.webp\" alt=\"\"\/><\/figure>\n\n\n\n<p><br>&nbsp;3 &#8211; &#8220;Desayunar s\u00f3lo mate est\u00e1 bien&#8221;: para que el desayune genere saciedad y aporte energ\u00eda debe estar compuesto por una infusi\u00f3n, una fruta\/verdura, cereales integrales, y alguna fuente de grasas saludables y prote\u00ednas.<\/p>\n\n\n\n<p>4 &#8211; &#8220;El mate reemplaza el agua&#8221;: el mate tiene diur\u00e9ticos que favorecen la eliminaci\u00f3n de l\u00edquidos, por lo que deber\u00eda ser acompa\u00f1ado de agua natural.<\/p>\n\n\n\n<p><br>5 &#8211; &#8220;Se puede tomar todo el mate que uno quiera&#8221;: el mate posee compuestos que pueden irritar en caso de acidez gastico o alg\u00fan malestar digestivo, por lo que no es ideal tomar m\u00e1s de 2 litros por d\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata de la infusi\u00f3n m\u00e1s arraigadas en la psiquis nacional. Anualmente, los argentinos consumen 280 millones de kilos de yerba por a\u00f1o. Cada 30 de noviembre se celebra el&hellip; <\/p>\n","protected":false},"author":4,"featured_media":23961,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-23960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informacion-general"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/23960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=23960"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/23960\/revisions"}],"predecessor-version":[{"id":23962,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/23960\/revisions\/23962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/23961"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=23960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=23960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=23960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}