{"id":249774,"date":"2026-03-18T13:32:09","date_gmt":"2026-03-18T16:32:09","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=249774"},"modified":"2026-03-18T13:32:16","modified_gmt":"2026-03-18T16:32:16","slug":"violencia-en-rio-de-janeiro-un-operativo-policial-dejo-ocho-muertos-y-los-narcos-quemaron-colectivos","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/internacionales\/violencia-en-rio-de-janeiro-un-operativo-policial-dejo-ocho-muertos-y-los-narcos-quemaron-colectivos\/","title":{"rendered":"Violencia en R\u00edo de Janeiro: un operativo policial dej\u00f3 ocho muertos y los narcos quemaron colectivos"},"content":{"rendered":"\n<p>Abatieron al jefe narco del Morro dos Prazeres y un vecino muri\u00f3 como reh\u00e9n; hubo ataques, barricadas y suspensi\u00f3n de clases en plena ciudad.<\/p>\n\n\n\n<p>Una ma\u00f1ana de terror sacudi\u00f3 este mi\u00e9rcoles al centro de\u00a0<strong>R\u00edo de Janeiro<\/strong>. Un operativo policial termin\u00f3 con\u00a0<strong>ocho muertos<\/strong>, entre ellos\u00a0<strong>Claudio Augusto dos Santos<\/strong>, alias\u00a0<strong>Jil\u00f3<\/strong>, se\u00f1alado como jefe del narcotr\u00e1fico en el\u00a0<strong>Morro dos Prazeres<\/strong>, y\u00a0<strong>Leandro Silva Souza<\/strong>, un vecino que fue tomado como reh\u00e9n por los delincuentes.<\/p>\n\n\n\n<p>Adem\u00e1s, dos personas resultaron heridas y la violencia se desat\u00f3 en las calles: colectivos incendiados, barricadas y servicios interrumpidos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El operativo y la reacci\u00f3n narco: caos en las calles de R\u00edo<\/h2>\n\n\n\n<p>El operativo del&nbsp;<strong>Batalh\u00e3o de Opera\u00e7\u00f5es Especiais (Bope)<\/strong>&nbsp;arranc\u00f3 cerca de las 5 de la ma\u00f1ana en las comunidades de&nbsp;<strong>Prazeres, Fallet, Fogueteiro, Coroa, Escondidinho y Paula Ramos<\/strong>. M\u00e1s de&nbsp;<strong>150 agentes<\/strong>, apoyados por 14 patrulleros y dos blindados, avanzaron contra los narcos, seg\u00fan inform\u00f3 la Polic\u00eda Militar.<\/p>\n\n\n\n<p>En medio del despliegue, un grupo de delincuentes irrumpi\u00f3 en una vivienda y tom\u00f3 como rehenes a&nbsp;<strong>Leandro Silva Souza<\/strong>&nbsp;y su esposa&nbsp;<strong>Roberta<\/strong>. El comandante del Bope,&nbsp;<strong>Marcelo Corbage<\/strong>, explic\u00f3 que \u201cen una acci\u00f3n cobarde, tomaron a una pareja como reh\u00e9n. Busc\u00e1bamos una soluci\u00f3n pac\u00edfica, pero hubo disparos en la casa. El se\u00f1or Leandro fue alcanzado en la cabeza. Roberta fue rescatada en estado de shock y declarar\u00e1 ante la Justicia\u201d.<\/p>\n\n\n\n<p>La violencia escal\u00f3 r\u00e1pidamente. En la&nbsp;<strong>Avenida Paulo de Frontin<\/strong>, en el barrio&nbsp;<strong>Rio Comprido<\/strong>, un colectivo fue incendiado y otros veh\u00edculos fueron secuestrados para bloquear el tr\u00e1nsito. El humo y las llamas paralizaron el acceso al t\u00fanel Rebou\u00e7as y generaron un caos total en la zona.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Colectivos incendiados y servicios afectados: el impacto en la ciudad<\/h2>\n\n\n\n<p>El ataque a los colectivos fue una respuesta directa a la operaci\u00f3n policial en las favelas controladas por el&nbsp;<strong>Comando Vermelho<\/strong>.<\/p>\n\n\n\n<p>Seg\u00fan la empresa&nbsp;<strong>Rio \u00d4nibus<\/strong>, cinco colectivos fueron usados como barricadas y uno de ellos termin\u00f3 completamente incendiado. Siete l\u00edneas de colectivos debieron desviar su recorrido y al menos diez servicios resultaron afectados, complicando a\u00fan m\u00e1s la movilidad en la ciudad.<\/p>\n\n\n\n<p>Las escuelas tampoco escaparon al drama:&nbsp;<strong>siete establecimientos municipales suspendieron sus actividades<\/strong>&nbsp;y una unidad de atenci\u00f3n primaria de salud cerr\u00f3 sus puertas. Otras tres funcionaron con restricciones.<\/p>\n\n\n\n<p>El&nbsp;<strong>Hospital Souza Aguiar<\/strong>&nbsp;recibi\u00f3 a diez personas baleadas durante la ma\u00f1ana. Ocho hombres llegaron sin vida, una mujer permanece internada en estado estable y un polic\u00eda fue atendido por heridas leves y dado de alta.<\/p>\n\n\n\n<p>La Polic\u00eda Militar inform\u00f3 que secuestr\u00f3&nbsp;<strong>dos fusiles, cuatro pistolas y dos rev\u00f3lveres<\/strong>&nbsp;durante el operativo. Adem\u00e1s, detuvo a cuatro personas acusadas de provocar disturbios en las calles.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qui\u00e9n era Jil\u00f3, el jefe narco abatido por el Bope<\/h2>\n\n\n\n<p><strong>Claudio Augusto dos Santos<\/strong>, conocido como&nbsp;<strong>Jil\u00f3<\/strong>, ten\u00eda un largo historial delictivo desde los a\u00f1os 90: tr\u00e1fico de drogas, homicidio, secuestro y robo, con&nbsp;<strong>diez \u00f3rdenes de captura vigentes<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/tn.com.ar\/resizer\/v2\/claudio-augusto-dos-santos-apodado-jilo-dos-prazeres-tenia-55-anos-foto-gentileza-g1-ENVUGGSIHFFYLHDXHY4VFGXA5A.png?auth=c39fa21b999c8683e6bb287356e9c135e338daadddf63f37f0553e4188dcf76b&amp;width=767\" alt=\"Cl\u00e1udio Augusto dos Santos, apodado Jil\u00f3 dos Prazeres, ten\u00eda 55 a\u00f1os. (Foto: gentileza g1).\"\/><\/figure>\n\n\n\n<p>La polic\u00eda lo vinculaba con el asesinato del turista italiano&nbsp;<strong>Roberto Bardella<\/strong>&nbsp;en 2016, un caso que conmocion\u00f3 a Brasil. Bardella y su primo ingresaron por error al Morro dos Prazeres en moto; el turista fue ejecutado y su cuerpo fue encontrado oculto en el ba\u00fal de un auto. Jil\u00f3 hab\u00eda salido de prisi\u00f3n apenas un mes antes de ese crimen.<\/p>\n\n\n\n<p>El&nbsp;<strong>Centro de Operaciones y Resiliencia (COR)<\/strong>&nbsp;de la ciudad alert\u00f3 sobre cortes en varias calles clave, como Itapiru, Bar\u00e3o de Petr\u00f3polis, Estrela y la propia Avenida Paulo de Frontin. Cuatro patrulleros del&nbsp;<strong>Batalh\u00e3o de Rondas Especiais e Controle de Multid\u00e3o (Recom)<\/strong>&nbsp;bloquearon los accesos a los morros de Fallet y Prazeres.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"574\" src=\"https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2026\/03\/image-464-1024x574.png\" alt=\"\" class=\"wp-image-249775\" srcset=\"https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2026\/03\/image-464-1024x574.png 1024w, https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2026\/03\/image-464-300x168.png 300w, https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2026\/03\/image-464-768x430.png 768w, https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2026\/03\/image-464.png 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Abatieron al jefe narco del Morro dos Prazeres y un vecino muri\u00f3 como reh\u00e9n; hubo ataques, barricadas y suspensi\u00f3n de clases en plena ciudad. Una ma\u00f1ana de terror sacudi\u00f3 este&hellip; <\/p>\n","protected":false},"author":8,"featured_media":249775,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-249774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/249774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=249774"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/249774\/revisions"}],"predecessor-version":[{"id":249776,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/249774\/revisions\/249776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/249775"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=249774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=249774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=249774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}