{"id":250760,"date":"2026-03-27T10:00:16","date_gmt":"2026-03-27T13:00:16","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=250760"},"modified":"2026-03-27T10:00:18","modified_gmt":"2026-03-27T13:00:18","slug":"maduro-comparece-en-la-corte-de-nueva-york-para-reclamar-la-anulacion-de-su-juicio-por-narcoterrorista","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/internacionales\/maduro-comparece-en-la-corte-de-nueva-york-para-reclamar-la-anulacion-de-su-juicio-por-narcoterrorista\/","title":{"rendered":"Maduro comparece en la Corte de Nueva York para reclamar la anulaci\u00f3n de su juicio por narcoterrorista"},"content":{"rendered":"\n<p>La defensa del exdictador venezolano sostiene que el proceso penal en su contra viola las enmiendas Quinta y Sexta de la Constituci\u00f3n de los EEUU, un argumento jur\u00eddico que ser\u00eda rechazado por improcedente en los tribunales de Manhattan.<\/p>\n\n\n\n<p>Nicol\u00e1s Maduro comparece hoy en la Corte de New York para reclamar al juez Alvin Hellerstein que su juicio penal por narcoterrorista sea anulado por presunta violaci\u00f3n a la Quinta y Sexta Enmienda de la Constituci\u00f3n de los Estados Unidos.<\/p>\n\n\n\n<p>Se trata de una defensa dise\u00f1ada por el abogado Barry J. Pollack, que hace una peculiar interpretaci\u00f3n de las enmiendas de la constituci\u00f3n para sostener un argumento jur\u00eddico que ser\u00eda rechazado por el tribunal de Manhattan.<\/p>\n\n\n\n<p>La interpretaci\u00f3n constitucional de Pollack deriva en dos falacias. Afirma que Maduro no tiene dinero para pagar a su abogados, y que esa presunta situaci\u00f3n de insolvencia econ\u00f3mica afectar\u00eda su principio de defensa en juicio.<\/p>\n\n\n\n<p>En un escrito de 17 fojas, el abogado defensor de Maduro sostuvo:<\/p>\n\n\n\n<p>-&#8220;La ley venezolana otorga al Sr. Maduro y a la Sra. Flores de Maduro un derecho de propiedad sobre el pago de sus honorarios legales. La revocaci\u00f3n de las Licencias Originales por parte de la OFAC y la negativa a restablecerlas interfiere con su derecho a contratar al abogado de su elecci\u00f3n ya que, sin la capacidad de ejercer este derecho de propiedad, ninguno de los dos tiene la capacidad de financiar la defensa por s\u00ed mismos. Ver Declaraci\u00f3n. de Nicol\u00e1s Maduro Moros (ECF No. 290-2) y Declaraci\u00f3n. de Cilia Flores de Maduro (ECF No. 293-2) (declaraciones juradas de incapacidad de pago y disposici\u00f3n a presentar declaraciones financieras a petici\u00f3n de la Corte)&#8221;, afirma Pollack en la foja 4 de su presentaci\u00f3n, a la que accedi\u00f3 Infobae.<\/p>\n\n\n\n<p>Y completa as\u00ed sus argumentaciones legales en la foja 11:<\/p>\n\n\n\n<p>&#8220;El gobierno no puede afirmar la &#8220;seguridad nacional&#8221; o la &#8220;pol\u00edtica exterior&#8221; y luego pasar por encima de los derechos procesales internos de un individuo. Por ejemplo, en procesos que involucran informaci\u00f3n clasificada, el gobierno no puede impedir que los acusados obtengan evidencia exculpatoria material, descubrible bajo Brady v. Maryland, 373 U.S. 83 (1963), y usen esa evidencia en su defensa en un juicio p\u00fablico, simplemente porque el gobierno tiene una raz\u00f3n pol\u00edtica leg\u00edtima para mantener el documento clasificado. Bajo la Ley de Procedimientos de Informaci\u00f3n Clasificada (18 U.S.C. App. III), si el gobierno no ofrece un sustituto adecuado, el tribunal debe desestimar la acusaci\u00f3n. Ver United States v. Giffen, 473 F.3d 30, 33 (2d Cir. 2006) (Bajo CIPA, &#8220;si el tribunal se niega a permitir tal sustituci\u00f3n, y el gobierno se opone a la divulgaci\u00f3n de la informaci\u00f3n clasificada, el remedio presuntivo es la desestimaci\u00f3n de la acusaci\u00f3n&#8221;).<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.diarioepoca.com\/content\/bucket\/1\/1480361w790h549c.webp.webp\" alt=\"\"\/><\/figure>\n\n\n\n<p>La refutaci\u00f3n de los argumentos presentados por Pollack es lineal y simple.<\/p>\n\n\n\n<p>Los fondos de Venezuela para financiar una defensa legal a un mandatario o exmandatario no aplica en el caso de Maduro y su esposa.<\/p>\n\n\n\n<p>No son autoridades legales, y est\u00e1 probado que ocupaban el Palacio Miraflores por el fraude cometido en los \u00faltimos comicios presidenciales.<\/p>\n\n\n\n<p>A su vez, Maduro y Flores de Maduro tienen que probar que no disponen de fondos propios -su fortuna presunta es incalculable-, y la VI enmienda garantiza un abogado que no necesariamente debe financiarse con fondos que est\u00e1n inmovilizados por decisi\u00f3n de la Secretar\u00eda del Tesoro (OFAC).<\/p>\n\n\n\n<p>El tribunal de New York puede asignar un abogado de oficio que conoce las normas y puede cumplir con la defensa que garantiza la Constituci\u00f3n de los Estados Unidos.<\/p>\n\n\n\n<p>Este es un derecho que Maduro tiene a disposici\u00f3n cuando lo desee.<\/p>\n\n\n\n<p>Y respecto a la V enmienda, la defensa de Maduro no hace referencia a la Ley de Poderes Econ\u00f3micos de Emergencia Internacional (IEEPA), que asigna a la Casa Blanca una amplia autoridad normativa para regular transacciones con gobiernos extranjeros por razones de seguridad nacional.<\/p>\n\n\n\n<p>Desde esta perspectiva, pese a que la dictadura caribe\u00f1a estaba dispuesta a pagar la defensa de Maduro, Donald Trump ratific\u00f3 que no habr\u00e1 fondos de Venezuela para solventar a los letrados del presunto narcotraficante.<\/p>\n\n\n\n<p>Nicol\u00e1s Maduro est\u00e1 acusado por cometer narcoterrorismo, y en este contexto la DEA redact\u00f3 un informe que prueba las vinculaciones del exdictador caribe\u00f1o con el r\u00e9gimen iran\u00ed.<\/p>\n\n\n\n<p>Infobae accedi\u00f3 a ese dossier de 28 fojas, que sostiene lo siguiente:<\/p>\n\n\n\n<p>-&#8221; La alianza Ir\u00e1n-Venezuela permite a Teher\u00e1n evadir las sanciones internacionales a trav\u00e9s de una arquitectura financiera opaca que involucra al Fondo Conjunto China-Venezuela, el FONDEN, fondos bilaterales, cuentas de fideicomiso y bancos corresponsales en Uruguay, Panam\u00e1, Dub\u00e1i y Hong Kong&#8221;.<\/p>\n\n\n\n<p>-&#8220;Esta red canaliza recursos significativos a empresas estatales iran\u00edes clave en los sectores de energ\u00eda, construcci\u00f3n naval y de doble uso, manteniendo as\u00ed la resiliencia econ\u00f3mica del r\u00e9gimen y financiando actividades hostiles en todo el Medio Oriente y las Am\u00e9ricas&#8221;.<\/p>\n\n\n\n<p>-&#8220;Simult\u00e1neamente, la asociaci\u00f3n se extiende a los dominios militar y nuclear: Ir\u00e1n transfiere tecnolog\u00eda de drones, misiles antibuque y capacidades industriales a Venezuela, mientras explota y contrabandea encubiertamente uranio de la Cuenca de Roraima y adquiere tecnolog\u00eda relacionada con lo nuclear (equipos CNC, aleaciones especiales, experiencia en agua pesada) a trav\u00e9s de la triangulaci\u00f3n con Argentina (2006-2014), apoyando directamente el programa nuclear sancionado de Ir\u00e1n y alterando el equilibrio estrat\u00e9gico global&#8221;.<\/p>\n\n\n\n<p>-&#8220;Venezuela tambi\u00e9n funciona como un centro cr\u00edtico para organizaciones terroristas designadas por los EE. UU., como Hezbollah y Hamas, facilitando el lavado de dinero, el tr\u00e1fico de drogas y armas, la emisi\u00f3n fraudulenta de pasaportes y la movilidad operativa en toda la regi\u00f3n&#8221;.<\/p>\n\n\n\n<p>-&#8220;Estas redes se conectan con la Triple Frontera, estructuras criminales colombianas y ecuatorianas, remanentes de las FARC y carteles mexicanos, formando un ecosistema h\u00edbrido de crimen transnacional y terrorismo alineado con los intereses iran\u00edes&#8221;.<\/p>\n\n\n\n<p>-&#8220;La alianza, por lo tanto, no es mera cooperaci\u00f3n diplom\u00e1tica o econ\u00f3mica, sino una plataforma multifac\u00e9tica para la proyecci\u00f3n del poder iran\u00ed que socava las sanciones, fortalece a un estado hostil y amplifica a los actores violentos no estatales&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.diarioepoca.com\/content\/bucket\/2\/1480362w790h526c.jpg.webp\" alt=\"\"\/><figcaption class=\"wp-element-caption\">DONALD TRUMP, FLANQUEADO POR SU GABINETE, ANUNCIA LA CAPTURA DE NICOL\u00c1S MADURO EN CARACAS.<\/figcaption><\/figure>\n\n\n\n<p>Si no hay sorpresas legales, el juez Hellerstein resolver\u00e1 hoy el planteo del abogado de Maduro, y una presentaci\u00f3n hecha por los fiscales federales que intentan evitar que la prueba recogida contra el exdictador sea compartida con los otros acusados del caso.<\/p>\n\n\n\n<p>Junto a Maduro y su esposa Cilia Flores tambi\u00e9n est\u00e1n imputados Diosdado Cabello -ministro del Interior de Venezuela-, Ram\u00f3n Rodr\u00edguez Chac\u00edn -exministro del interior de Venezuela-; Nicol\u00e1s Maduro Guerra -hijo del exdictador-,y Hector Rusthenford Guerrero Flores, alias &#8220;Ni\u00f1o Guerrero&#8221;, l\u00edder de la organizaci\u00f3n criminal Tren de Aragua.<\/p>\n\n\n\n<p>Si prosperar\u00e1 el pedido de Pollack, todos los socios ilegales de Maduro podr\u00edan acceder a las evidencias del caso. La defensa del exdictador fuerza la interpretaci\u00f3n del derecho para lograr una coartada que beneficie a su cliente ante las evidencias en contra.<\/p>\n\n\n\n<p>Hellerstein resolver\u00eda en contra del planteo de Pollack respecto a anular el juicio contra Maduro y a favor de los fiscales para trabar que los socios del exdictador accedan a la prueba aportada por la DEA.<\/p>\n\n\n\n<p>La audiencia est\u00e1 prevista para el mediod\u00eda de New York.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La defensa del exdictador venezolano sostiene que el proceso penal en su contra viola las enmiendas Quinta y Sexta de la Constituci\u00f3n de los EEUU, un argumento jur\u00eddico que ser\u00eda&hellip; <\/p>\n","protected":false},"author":3,"featured_media":250766,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-250760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/250760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=250760"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/250760\/revisions"}],"predecessor-version":[{"id":250794,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/250760\/revisions\/250794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/250766"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=250760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=250760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=250760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}