{"id":256514,"date":"2026-05-13T12:07:08","date_gmt":"2026-05-13T15:07:08","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=256514"},"modified":"2026-05-13T12:07:14","modified_gmt":"2026-05-13T15:07:14","slug":"copa-argentina-platense-va-por-los-octavos-de-final","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/deportes\/copa-argentina-platense-va-por-los-octavos-de-final\/","title":{"rendered":"COPA ARGENTINA: PLATENSE VA POR LOS OCTAVOS DE FINAL"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">El calamar se enfrenta esta tarde a San Mart\u00edn de San Juan en busca de una nueva instancia de la copa nacional.<\/h2>\n\n\n\n<p><strong>Por Nicol\u00e1s Reif<\/strong><\/p>\n\n\n\n<p>Los 16avos de final de la Copa Argentina 2026 continuar\u00e1n este mi\u00e9rcoles cuando Platense y San Mart\u00edn de San Juan se midan en el Estadio Alfredo Beranger de Temperley desde las 16.15 horas.<\/p>\n\n\n\n<p>El calamar, de flojo andar en el torneo Apertura pero de buena Copa Libertadores, intentar\u00e1 dejar en el camino a un santo sanjuanino de irregular presente en la Primera Nacional.<\/p>\n\n\n\n<p>El encuentro ser\u00e1 televisado por TyC Sports y quien avance esperar\u00e1 en la siguiente instancia al vencedor del partido entre Instituto y Lan\u00fas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El calamar se enfrenta esta tarde a San Mart\u00edn de San Juan en busca de una nueva instancia de la copa nacional. Por Nicol\u00e1s Reif Los 16avos de final de&hellip; <\/p>\n","protected":false},"author":11,"featured_media":256517,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[1551,2225,1103,2754],"class_list":["post-256514","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-copa-argentina","tag-horarios-de-tv","tag-platense","tag-san-martin-de-san-juan"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/256514","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=256514"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/256514\/revisions"}],"predecessor-version":[{"id":256518,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/256514\/revisions\/256518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/256517"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=256514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=256514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=256514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}