{"id":264100,"date":"2026-07-15T09:48:09","date_gmt":"2026-07-15T12:48:09","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=264100"},"modified":"2026-07-15T09:48:21","modified_gmt":"2026-07-15T12:48:21","slug":"peregrinos-de-san-luis-llegaron-a-la-basilica","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/actualidad\/peregrinos-de-san-luis-llegaron-a-la-basilica\/","title":{"rendered":"peregrinos de San Luis llegaron a la Bas\u00edlica"},"content":{"rendered":"\n<p>En una masiva demostraci\u00f3n de fe, la comunidad religiosa de San Luis Rey de Francia arrib\u00f3 este martes por la tarde a la localidad de Itat\u00ed, completando de manera exitosa y sin inconvenientes la primera etapa de su tradicional peregrinaci\u00f3n, que este a\u00f1o alcanza su 126\u00b0 edici\u00f3n.<a href=\"https:\/\/api.whatsapp.com\/send?text=Devoci%C3%B3n%20centenaria%20rumbo%20a%20la%20UNESCO:%20peregrinos%20de%20San%20Luis%20llegaron%20a%20la%20Bas%C3%ADlica%20-%20https:\/\/www.diarioepoca.com\/1384829-devocion-centenaria-rumbo-a-la-unesco-peregrinos-de-san-luis-llegaron-a-la-basilica?utm_source=WhatsApp%26utm_medium=WhatsApp%26utm_campaign=WhatsApp%26utm_term=WhatsApp\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/www.diarioepoca.com\/1384829-devocion-centenaria-rumbo-a-la-unesco-los-fieles-de-san-luis-llegaron-sin-contratiempos-a-la-basilica#\"><\/a><a href=\"https:\/\/www.diarioepoca.com\/1384829-devocion-centenaria-rumbo-a-la-unesco-los-fieles-de-san-luis-llegaron-sin-contratiempos-a-la-basilica#\"><\/a><\/p>\n\n\n\n<p>El arribo se concret\u00f3 gracias al amplio dispositivo de seguridad diagramado desde el Ministerio de Seguridad y la Jefatura de Polic\u00eda de Corrientes, que acompa\u00f1\u00f3 a los miles de fieles durante todo el trayecto desde el punto de partida hasta la Bas\u00edlica de Itat\u00ed.<\/p>\n\n\n\n<p>La peregrinaci\u00f3n \u2014una de las m\u00e1s emblem\u00e1ticas de la provincia\u2014 tuvo como objetivo la participaci\u00f3n en las celebraciones lit\u00fargicas por el aniversario de la Coronaci\u00f3n Pontificia de Nuestra Se\u00f1ora de Itat\u00ed.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Despliegue de seguridad<\/h3>\n\n\n\n<p>El operativo combin\u00f3 recursos humanos y tecnol\u00f3gicos de \u00faltima generaci\u00f3n. El monitoreo de la columna de caminantes y jinetes incluy\u00f3 patrullajes terrestres de la Divisi\u00f3n Motorizada, Caballer\u00eda y Polic\u00eda Rural, junto al uso de drones con visi\u00f3n nocturna que vigilaron los campamentos y las rutas las 24 horas del d\u00eda.<\/p>\n\n\n\n<p>La supervisi\u00f3n en terreno estuvo a cargo del jefe de la Polic\u00eda de Corrientes, comisario general Miguel \u00c1ngel Leguizam\u00f3n, acompa\u00f1ado por el subjefe comisario general Walter Dar\u00edo Aceval y las m\u00e1ximas autoridades de la Unidad Regional I de San Luis del Palmar, entre ellas el director comisario mayor Alberto Cano.<\/p>\n\n\n\n<p>Por la complejidad del operativo, se articul\u00f3 el trabajo de m\u00faltiples ministerios provinciales, fuerzas federales como Gendarmer\u00eda Nacional, Prefectura Naval y Polic\u00eda Federal Argentina, y organismos civiles de asistencia sanitaria y rescate.<\/p>\n\n\n\n<p>Defensa Civil, Cruz Roja Argentina, Bomberos Voluntarios y las carteras de Salud P\u00fablica coordinaron puestos de hidrataci\u00f3n y asistencia a lo largo de los caminos, con el apoyo log\u00edstico de los municipios de San Cosme, Ramada Paso y Paso de la Patria.<\/p>\n\n\n\n<p>Los fieles permanecer\u00e1n en la localidad santuario durante las festividades lit\u00fargicas, en tanto que el esquema de seguridad policial mantendr\u00e1 sus puestos fijos y m\u00f3viles para garantizar el posterior regreso ordenado de la feligres\u00eda hacia sus hogares.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2026\/07\/image-442.png\" alt=\"\" class=\"wp-image-264103\" srcset=\"https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2026\/07\/image-442.png 960w, https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2026\/07\/image-442-300x225.png 300w, https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2026\/07\/image-442-768x576.png 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"638\" src=\"https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2026\/07\/image-443.png\" alt=\"\" class=\"wp-image-264104\" srcset=\"https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2026\/07\/image-443.png 850w, https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2026\/07\/image-443-300x225.png 300w, https:\/\/corrientesdetarde.com\/wp-content\/uploads\/2026\/07\/image-443-768x576.png 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En una masiva demostraci\u00f3n de fe, la comunidad religiosa de San Luis Rey de Francia arrib\u00f3 este martes por la tarde a la localidad de Itat\u00ed, completando de manera exitosa&hellip; <\/p>\n","protected":false},"author":8,"featured_media":264102,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-264100","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/264100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=264100"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/264100\/revisions"}],"predecessor-version":[{"id":264105,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/264100\/revisions\/264105"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/264102"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=264100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=264100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=264100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}