{"id":264125,"date":"2026-07-15T14:22:59","date_gmt":"2026-07-15T17:22:59","guid":{"rendered":"https:\/\/corrientesdetarde.com\/?p=264125"},"modified":"2026-07-15T14:23:07","modified_gmt":"2026-07-15T17:23:07","slug":"la-municipalidad-explico-como-funcionan-las-aplicaciones-para-un-transporte-seguro","status":"publish","type":"post","link":"https:\/\/corrientesdetarde.com\/index.php\/destacados\/la-municipalidad-explico-como-funcionan-las-aplicaciones-para-un-transporte-seguro\/","title":{"rendered":"La Municipalidad explic\u00f3 c\u00f3mo funcionan las aplicaciones para un transporte seguro"},"content":{"rendered":"\n<p>La gesti\u00f3n del intendente Claudio Polich expuso en el espacio de disertaciones de la Feria Provincial del Libro las herramientas digitales \u201cTransporte Seguro\u201d y \u201cMi Transporte Seguro\u201d. Buscan transparentar el servicio privado de pasajeros, evitar estafas y reducir la siniestralidad vial mediante el control ciudadano en tiempo real.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"La Municipalidad explic\u00f3 c\u00f3mo funcionan las aplicaciones para un transporte seguro\" width=\"1110\" height=\"624\" src=\"https:\/\/www.youtube.com\/embed\/HjiJ4uiq908?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>La Municipalidad de Corrientes brind\u00f3 una conferencia en la Feria Provincial del Libro orientada a difundir las herramientas tecnol\u00f3gicas de desarrollo local dise\u00f1adas para que los usuarios puedan viajar sin riesgos en la v\u00eda p\u00fablica.<br>La exposici\u00f3n estuvo encabezada por el secretario de Movilidad Urbana y Seguridad Ciudadana, Yamand\u00fa Barrios, y el director general de Transporte Integral, Armando Maidana.<br>Durante el encuentro se analiz\u00f3 el impacto del desembarco de las aplicaciones m\u00f3viles en la regi\u00f3n y se ponder\u00f3 la unificaci\u00f3n legislativa que rige en la ciudad, la cual regula bajo un mismo marco normativo a taxis, remises y veh\u00edculos de plataformas electr\u00f3nicas.<br>Barrios destac\u00f3 la importancia de que la ciudadan\u00eda se apropie de estas innovaciones para su propia protecci\u00f3n. \u201cEs importante que los vecinos est\u00e9n al tanto de las aplicaciones, el instrumento que tiene para, de cierta forma, controlar y no ser estafado al subir a un remis, a un taxi o a un m\u00f3vil de aplicaci\u00f3n\u201d, se\u00f1al\u00f3 el funcionario.<br>Asimismo, vincul\u00f3 esta iniciativa con el plan de seguridad de la comuna, asegurando que el principal objetivo de la gesti\u00f3n del intendente Claudio Polich es bajar la siniestralidad vial y reducir la cantidad de v\u00edctimas en accidentes de tr\u00e1nsito mediante una fuerte presencia educativa en escuelas, iglesias y clubes de la ciudad.<br><br>CONTROL DIGITAL<br>El director general de Transporte Integral, Armando Maidana, fue el encargado de detallar el funcionamiento de los soportes inform\u00e1ticos creados de manera interna por equipos t\u00e9cnicos de la comuna, un desarrollo que le vali\u00f3 al Municipio un reconocimiento de la Red de Innovaci\u00f3n Local (RIL) por su aporte a la gesti\u00f3n inteligente del transporte.<br>El sistema se compone de dos herramientas complementarias que act\u00faan en paralelo. La primera de ellas, denominada \u201cTransporte Seguro\u201d, fue dise\u00f1ada exclusivamente para el personal de fiscalizaci\u00f3n.<br>Mediante esta aplicaci\u00f3n m\u00f3vil, los inspectores municipales pueden consultar de manera instant\u00e1nea el dominio de cualquier veh\u00edculo en la v\u00eda p\u00fablica para acceder al historial de habilitaci\u00f3n, los datos t\u00e9cnicos del rodado y la n\u00f3mina de choferes registrados, lo que permite agilizar los operativos urbanos.<br>La segunda alternativa, de car\u00e1cter netamente ciudadano, se denomina \u201cMi Transporte Seguro\u201d y funciona de manera integrada dentro de la app oficial de la Municipalidad de Corrientes.<br>Esta herramienta permite que cualquier usuario, al momento de solicitar un viaje, introduzca la patente de la unidad para constatar en tiempo real si el auto est\u00e1 autorizado.<br>De esta forma, el municipio fomenta el cruce de datos para transparentar las prestaciones y brindar soporte t\u00e9cnico y legal seguro ante eventuales reclamos o incidentes entre prestadores y pasajeros.<br><br>REGULACI\u00d3N EFICIENTE<br>Durante su intervenci\u00f3n, Maidana contrast\u00f3 la pol\u00edtica de integraci\u00f3n de la capital correntina con los escenarios de conflicto que atraviesan otras capitales del Nordeste.<br>\u201cNosotros tenemos municipios vecinos, como Resistencia (Chaco) o Posadas (Misiones), que no han podido regularizar este tipo de transporte, porque el desembarco de una plataforma electr\u00f3nica en s\u00ed es conflictivo\u201d, analiz\u00f3 el director.<br>El funcionario explic\u00f3 que debieron \u201caprender sobre la marcha\u201d el m\u00e9todo para gestionar la intermediaci\u00f3n de viajes y la transparencia en las tarifas.<br>Al respecto, concluy\u00f3 que mientras las plataformas operan bajo el libre juego de la oferta y la demanda, para taxis y remises se estableci\u00f3 un sistema de bandas tarifarias con \u201cun piso y un techo\u201d, logrando un mercado m\u00e1s equitativo y seguro para los usuarios y los prestadores del servicio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La gesti\u00f3n del intendente Claudio Polich expuso en el espacio de disertaciones de la Feria Provincial del Libro las herramientas digitales \u201cTransporte Seguro\u201d y \u201cMi Transporte Seguro\u201d. Buscan transparentar el&hellip; <\/p>\n","protected":false},"author":4,"featured_media":264126,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-264125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados"],"_links":{"self":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/264125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/comments?post=264125"}],"version-history":[{"count":1,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/264125\/revisions"}],"predecessor-version":[{"id":264128,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/posts\/264125\/revisions\/264128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media\/264126"}],"wp:attachment":[{"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/media?parent=264125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/categories?post=264125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corrientesdetarde.com\/index.php\/wp-json\/wp\/v2\/tags?post=264125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}